{"id":798,"date":"2024-09-08T17:03:50","date_gmt":"2024-09-08T17:03:50","guid":{"rendered":"https:\/\/loveforasia.org\/?p=798"},"modified":"2025-06-18T18:22:46","modified_gmt":"2025-06-18T18:22:46","slug":"","status":"publish","type":"post","link":"https:\/\/loveforasia.org\/de\/john-131-17\/","title":{"rendered":"Johannes 13,1-17","raw":"Johannes 13,1-17"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jesus w\u00e4scht seinen J\u00fcngern die F\u00fc\u00dfe<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>1 Es war kurz vor dem Passahfest. Jesus wusste, dass die Stunde gekommen war, um diese Welt zu verlassen und zum Vater zu gehen. Er hatte die Seinen, die in der Welt waren, geliebt und liebte sie bis zum Ende.<br>2 Das Abendessen war im Gange, und der Teufel hatte Judas, den Sohn von Simon Iskariot, bereits dazu verleitet, Jesus zu verraten.<br>3 Jesus wusste, dass der Vater ihm alles in die Hand gegeben hatte und dass er von Gott gekommen war und zu Gott zur\u00fcckkehren w\u00fcrde.<br>4 Da stand er vom Mahl auf, legte sein Obergewand ab, nahm ein Tuch und band es sich um die H\u00fcfte.<br>5 Dann goss er Wasser in ein Becken und begann, die F\u00fc\u00dfe seiner J\u00fcnger zu waschen und sie mit dem Tuch abzutrocknen, das er umgebunden hatte.<br>6 Als er zu Simon Petrus kam, sagte dieser zu ihm: \u201eHerr, willst du mir die F\u00fc\u00dfe waschen?\u201c<br>7 Jesus antwortete: \u201eWas ich tue, verstehst du jetzt noch nicht, aber sp\u00e4ter wirst du es begreifen.\u201c<br>8 \u201eNein,\u201c sagte Petrus, \u201eniemals sollst du mir die F\u00fc\u00dfe waschen.\u201c Jesus entgegnete: \u201eWenn ich dich nicht wasche, hast du keinen Anteil an mir.\u201c<br>9 \u201eHerr,\u201c sagte Simon Petrus, \u201edann wasche nicht nur meine F\u00fc\u00dfe, sondern auch meine H\u00e4nde und meinen Kopf!\u201c<br>10 Jesus antwortete: \u201eWer gebadet hat, braucht sich nur die F\u00fc\u00dfe zu waschen; er ist ganz rein. Und ihr seid rein, aber nicht alle.\u201c<br>11 Er wusste n\u00e4mlich, wer ihn verraten w\u00fcrde; deshalb sagte er: \u201eNicht alle seid ihr rein.\u201c<br>12 Als er ihnen die F\u00fc\u00dfe gewaschen hatte, zog er seine Kleider wieder an und kehrte zu seinem Platz zur\u00fcck. Er fragte sie: \u201eVersteht ihr, was ich f\u00fcr euch getan habe?<br>13 Ihr nennt mich \u201aLehrer\u2018 und \u201aHerr\u2018, und das zu Recht, denn das bin ich.<br>14 Wenn nun ich, euer Herr und Lehrer, euch die F\u00fc\u00dfe gewaschen habe, so sollt auch ihr einander die F\u00fc\u00dfe waschen.<br>15 Ich habe euch ein Beispiel gegeben, damit auch ihr so handelt, wie ich an euch gehandelt habe.<br>16 Wahrlich, ich sage euch: Ein Diener ist nicht gr\u00f6\u00dfer als sein Herr, und ein Gesandter nicht gr\u00f6\u00dfer als der, der ihn gesandt hat.<br>17 Wenn ihr dies wisst, seid ihr selig, wenn ihr es auch tut.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hallo zusammen, ich bin Kiki. Der chinesische Name unserer zweiten Programmphase lautet \u201e\u8bfb\u7ecf\u5927\u8bb2\u5802\u201c, auf Englisch \u201eBible study\u201c (Bibelstudium).<br>Wir werden einen entspannten und angenehmen Lernmodus einf\u00fchren, um euch in eine neue Lernwelt zu f\u00fchren. Jedes Mal werde ich aus der Perspektive eines Lernenden eine pers\u00f6nliche Zusammenfassung und Analyse machen, und dann wird Schwester Ingrid mir helfen, mit allen ein vertieftes Lernen und Problemdiskussionen zu f\u00fchren.<br>Ich hoffe, dass ein solch interessanter und interaktiver Prozess euch allen neue Lernerfahrungen bringen kann. Im Folgenden ist mein Interview mit meiner Schwester zu verwandten Themen. Heute ist der zweiundzwanzigste Vortrag \u00fcber das Johannesevangelium.<br>Alle sind herzlich eingeladen, eine Nachricht im Kommentarbereich f\u00fcr Diskussionen zu hinterlassen!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Meine Zusammenfassung des zweiundzwanzigsten Studiums \u00fcber Johannes:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun, alle zusammen! Zun\u00e4chst kommt wieder meine pers\u00f6nliche Studienzusammenfassung f\u00fcr heute.<br>Also, kurz vor dem Passahfest wusste Jesus, dass es fast an der Zeit war, diese Welt zu verlassen und zu seinem Vater im Himmel zur\u00fcckzukehren. Er liebte seine J\u00fcnger so sehr und wollte ihnen zeigen, wie tief seine Liebe zu ihnen ging. W\u00e4hrend des Abendessens, obwohl Jesus wusste, dass Judas ihn verraten w\u00fcrde, tat er etwas wirklich \u00dcberraschendes. Er stand auf, zog seine \u00e4u\u00dferen Kleider aus und band sich ein Handtuch um die H\u00fcften. Dann goss er Wasser in ein Becken und begann, die F\u00fc\u00dfe seiner J\u00fcnger zu waschen.<br>Das mag seltsam erscheinen, aber damals war das Waschen der F\u00fc\u00dfe normalerweise die Aufgabe von Dienern, da die F\u00fc\u00dfe der Menschen durch das Gehen in Sandalen sehr schmutzig wurden.<br>Als Jesus zu Petrus kam, sagte dieser: \u201eAuf keinen Fall wirst du mir die F\u00fc\u00dfe waschen!\u201c Aber Jesus sagte ihm, dass, wenn er seine F\u00fc\u00dfe nicht w\u00e4scht, Petrus keinen Anteil an ihm haben w\u00fcrde.<br>Daraufhin bat Petrus Jesus, nicht nur seine F\u00fc\u00dfe, sondern auch seine H\u00e4nde und seinen Kopf zu waschen! Jesus erkl\u00e4rte, dass jemand, der gebadet hat, nur seine F\u00fc\u00dfe waschen muss, um rein zu sein.<br>Nachdem er allen die F\u00fc\u00dfe gewaschen hatte, fragte Jesus sie, ob sie verstanden h\u00e4tten, was er getan hatte. Er erinnerte sie daran, dass sie ihn Lehrer und Herr nannten, was auch richtig war. Und da er, ihr Lehrer und Herr, ihnen die F\u00fc\u00dfe gewaschen hatte, sollten sie das Gleiche f\u00fcreinander tun.<br>Jesus gab ihnen ein Beispiel f\u00fcr Demut und Dienst, indem er zeigte, dass niemand zu wichtig ist, um anderen zu dienen. Er schloss, indem er sagte, dass sie gesegnet sein w\u00fcrden, wenn sie seinem Beispiel folgten und dies f\u00fcreinander taten.<br>Nun wird Schwester Ingrid eine weitergehende Zusammenfassung machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Kommentar der Schwester zu meiner Studienzusammenfassung:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jesus wollte zeigen, dass Liebe nicht aus guten Gef\u00fchlen und Romantik besteht, sondern darin, zu dienen und zu geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb steht in Johannes 3,16: \u201eDenn so sehr hat Gott die Welt geliebt, dass er seinen einzigen Sohn gab.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jesus ist Teil dieser Liebe und Teil seines Vaters, und deshalb w\u00e4scht er hier die F\u00fc\u00dfe der J\u00fcnger: Er m\u00f6chte die Liebe, die er f\u00fcr sie hat, in Taten zeigen. Wenn wir dem zustimmen, hat er die gleiche Liebe auch f\u00fcr uns und reinigt uns heute mit dem Wasser der Bibel und dem Heiligen Geist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heute sind wir herausgefordert, auch die F\u00fc\u00dfe anderer Christen zu waschen, indem wir ihnen mit Liebe und dem Wort des Evangeliums dienen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Christen geh\u00f6ren wir nicht zu dieser Welt, aber wir leben in dieser Welt. Deshalb werden wir oft mit Dingen kontaminiert, die nicht zum Evangelium geh\u00f6ren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch wenn wir einander auf diesem Weg in den Himmel dienen, k\u00f6nnen wir standhaft bleiben, bis wir das Ziel erreicht haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fragen zur Diskussion basierend auf Johannes 13:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Okay. Auf der Grundlage des obigen Bibelstudiums m\u00f6chte ich meiner Schwester einige verwandte Fragen stellen. Wir hoffen, dass die folgenden Fragen unseren Br\u00fcdern und Schwestern, die gerade Christen geworden sind, hilfreich sein k\u00f6nnen.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Warum hat Jesus sich entschieden, seinen J\u00fcngern die F\u00fc\u00dfe zu waschen, und was symbolisierte diese Handlung?<br>\u2013 Seine Handlung symbolisierte die Liebe, die er f\u00fcr diejenigen hat, die zu ihm geh\u00f6ren.<\/li>\n\n\n\n<li>Wie reagierte Petrus, als Jesus ihm die F\u00fc\u00dfe waschen wollte, und warum \u00e4nderte er seine Meinung?<br>\u2013 Petrus wollte nicht, dass Jesus ihm die F\u00fc\u00dfe w\u00e4scht, weil er in Jesus den K\u00f6nig sah und nicht den Diener. Jesus erkl\u00e4rte, dass es notwendig sei, was Petrus zum Umdenken brachte.<\/li>\n\n\n\n<li>Was meinte Jesus, als er sagte: \u201eWenn ich dich nicht wasche, hast du keinen Anteil an mir\u201c?<br>\u2013 Es ist wichtig, die Liebe Christi anzunehmen und sie nicht abzulehnen. Wir m\u00fcssen von den t\u00e4glichen Verunreinigungen durch das Leben auf der Erde gereinigt werden.<\/li>\n\n\n\n<li>Warum sagte Jesus, dass nicht alle am Tisch rein waren?<br>\u2013 Er bezog sich auf Judas Iskariot, der ihn sp\u00e4ter am Abend verraten w\u00fcrde.<\/li>\n\n\n\n<li>Welches Beispiel wollte Jesus seinen J\u00fcngern geben, indem er ihnen die F\u00fc\u00dfe wusch?<br>\u2013 Er zeigte ihnen, wie sie einander lieben sollten. Sp\u00e4ter wird er sagen, dass die Welt sie daran erkennen wird, dass sie seine J\u00fcnger sind, weil sie einander lieben.<\/li>\n\n\n\n<li>Was lehrt uns die Fu\u00dfwaschung durch Jesus \u00fcber F\u00fchrung und Demut?<br>\u2013 Jesus erniedrigte sich selbst bis zum Kreuz. Er strebte keine irdische F\u00fchrung an. Er hatte nur diese kleine Herde, die er drei Jahre lang lehrte, um sie auf den Dienst vorzubereiten, nachdem er zu seinem Vater im Himmel zur\u00fcckgekehrt war.<\/li>\n\n\n\n<li>Warum ist es bedeutsam, dass Jesus die F\u00fc\u00dfe aller J\u00fcnger, auch die von Judas, wusch?<br>\u2013 Judas hatte alle M\u00f6glichkeiten, umzukehren und Jesus nicht zu verraten. Er entschied sich jedoch selbst, dies zu tun, aber Jesus versuchte, ihn auf diese Weise nicht zu verlieren.<\/li>\n\n\n\n<li>Wie k\u00f6nnen wir Jesu Beispiel des Dienens in unserem t\u00e4glichen Leben folgen?<br>\u2013 Wir m\u00fcssen sensibel sein, wer in einem bestimmten Moment ein ermutigendes oder korrigierendes Wort braucht, und nicht z\u00f6gern, jemanden anzurufen, von dem wir wissen, dass er einsam ist und jemanden braucht, der sich um ihn k\u00fcmmert.<\/li>\n\n\n\n<li>Was meint Jesus, wenn er sagt: \u201eEin Diener ist nicht gr\u00f6\u00dfer als sein Herr\u201c?<br>\u2013 Wir sollten nicht nach irdischer F\u00fchrung streben, sondern dem\u00fctig gegen\u00fcber den Menschen um uns herum handeln.<\/li>\n<\/ol>\n\n\n\n<ol start=\"10\" class=\"wp-block-list\">\n<li>Wie sagt Jesus, dass wir gesegnet werden, wenn wir die Dinge tun, die Er uns gelehrt hat?<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">In der Bibel steht mehrfach geschrieben: Wenn ihr diese Dinge h\u00f6rt und sie tut, dann wird es gute Folgen f\u00fcr euer Leben haben.<\/p>\n","protected":false,"raw":"<!-- wp:paragraph -->\n<p>Jesus w\u00e4scht seinen J\u00fcngern die F\u00fc\u00dfe<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>1 Es war kurz vor dem Passahfest. Jesus wusste, dass die Stunde gekommen war, um diese Welt zu verlassen und zum Vater zu gehen. Er hatte die Seinen, die in der Welt waren, geliebt und liebte sie bis zum Ende.<br>2 Das Abendessen war im Gange, und der Teufel hatte Judas, den Sohn von Simon Iskariot, bereits dazu verleitet, Jesus zu verraten.<br>3 Jesus wusste, dass der Vater ihm alles in die Hand gegeben hatte und dass er von Gott gekommen war und zu Gott zur\u00fcckkehren w\u00fcrde.<br>4 Da stand er vom Mahl auf, legte sein Obergewand ab, nahm ein Tuch und band es sich um die H\u00fcfte.<br>5 Dann goss er Wasser in ein Becken und begann, die F\u00fc\u00dfe seiner J\u00fcnger zu waschen und sie mit dem Tuch abzutrocknen, das er umgebunden hatte.<br>6 Als er zu Simon Petrus kam, sagte dieser zu ihm: \u201eHerr, willst du mir die F\u00fc\u00dfe waschen?\u201c<br>7 Jesus antwortete: \u201eWas ich tue, verstehst du jetzt noch nicht, aber sp\u00e4ter wirst du es begreifen.\u201c<br>8 \u201eNein,\u201c sagte Petrus, \u201eniemals sollst du mir die F\u00fc\u00dfe waschen.\u201c Jesus entgegnete: \u201eWenn ich dich nicht wasche, hast du keinen Anteil an mir.\u201c<br>9 \u201eHerr,\u201c sagte Simon Petrus, \u201edann wasche nicht nur meine F\u00fc\u00dfe, sondern auch meine H\u00e4nde und meinen Kopf!\u201c<br>10 Jesus antwortete: \u201eWer gebadet hat, braucht sich nur die F\u00fc\u00dfe zu waschen; er ist ganz rein. Und ihr seid rein, aber nicht alle.\u201c<br>11 Er wusste n\u00e4mlich, wer ihn verraten w\u00fcrde; deshalb sagte er: \u201eNicht alle seid ihr rein.\u201c<br>12 Als er ihnen die F\u00fc\u00dfe gewaschen hatte, zog er seine Kleider wieder an und kehrte zu seinem Platz zur\u00fcck. Er fragte sie: \u201eVersteht ihr, was ich f\u00fcr euch getan habe?<br>13 Ihr nennt mich \u201aLehrer\u2018 und \u201aHerr\u2018, und das zu Recht, denn das bin ich.<br>14 Wenn nun ich, euer Herr und Lehrer, euch die F\u00fc\u00dfe gewaschen habe, so sollt auch ihr einander die F\u00fc\u00dfe waschen.<br>15 Ich habe euch ein Beispiel gegeben, damit auch ihr so handelt, wie ich an euch gehandelt habe.<br>16 Wahrlich, ich sage euch: Ein Diener ist nicht gr\u00f6\u00dfer als sein Herr, und ein Gesandter nicht gr\u00f6\u00dfer als der, der ihn gesandt hat.<br>17 Wenn ihr dies wisst, seid ihr selig, wenn ihr es auch tut.\u201c<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hallo zusammen, ich bin Kiki. Der chinesische Name unserer zweiten Programmphase lautet \u201e\u8bfb\u7ecf\u5927\u8bb2\u5802\u201c, auf Englisch \u201eBible study\u201c (Bibelstudium).<br>Wir werden einen entspannten und angenehmen Lernmodus einf\u00fchren, um euch in eine neue Lernwelt zu f\u00fchren. Jedes Mal werde ich aus der Perspektive eines Lernenden eine pers\u00f6nliche Zusammenfassung und Analyse machen, und dann wird Schwester Ingrid mir helfen, mit allen ein vertieftes Lernen und Problemdiskussionen zu f\u00fchren.<br>Ich hoffe, dass ein solch interessanter und interaktiver Prozess euch allen neue Lernerfahrungen bringen kann. Im Folgenden ist mein Interview mit meiner Schwester zu verwandten Themen. Heute ist der zweiundzwanzigste Vortrag \u00fcber das Johannesevangelium.<br>Alle sind herzlich eingeladen, eine Nachricht im Kommentarbereich f\u00fcr Diskussionen zu hinterlassen!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>2. Meine Zusammenfassung des zweiundzwanzigsten Studiums \u00fcber Johannes:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nun, alle zusammen! Zun\u00e4chst kommt wieder meine pers\u00f6nliche Studienzusammenfassung f\u00fcr heute.<br>Also, kurz vor dem Passahfest wusste Jesus, dass es fast an der Zeit war, diese Welt zu verlassen und zu seinem Vater im Himmel zur\u00fcckzukehren. Er liebte seine J\u00fcnger so sehr und wollte ihnen zeigen, wie tief seine Liebe zu ihnen ging. W\u00e4hrend des Abendessens, obwohl Jesus wusste, dass Judas ihn verraten w\u00fcrde, tat er etwas wirklich \u00dcberraschendes. Er stand auf, zog seine \u00e4u\u00dferen Kleider aus und band sich ein Handtuch um die H\u00fcften. Dann goss er Wasser in ein Becken und begann, die F\u00fc\u00dfe seiner J\u00fcnger zu waschen.<br>Das mag seltsam erscheinen, aber damals war das Waschen der F\u00fc\u00dfe normalerweise die Aufgabe von Dienern, da die F\u00fc\u00dfe der Menschen durch das Gehen in Sandalen sehr schmutzig wurden.<br>Als Jesus zu Petrus kam, sagte dieser: \u201eAuf keinen Fall wirst du mir die F\u00fc\u00dfe waschen!\u201c Aber Jesus sagte ihm, dass, wenn er seine F\u00fc\u00dfe nicht w\u00e4scht, Petrus keinen Anteil an ihm haben w\u00fcrde.<br>Daraufhin bat Petrus Jesus, nicht nur seine F\u00fc\u00dfe, sondern auch seine H\u00e4nde und seinen Kopf zu waschen! Jesus erkl\u00e4rte, dass jemand, der gebadet hat, nur seine F\u00fc\u00dfe waschen muss, um rein zu sein.<br>Nachdem er allen die F\u00fc\u00dfe gewaschen hatte, fragte Jesus sie, ob sie verstanden h\u00e4tten, was er getan hatte. Er erinnerte sie daran, dass sie ihn Lehrer und Herr nannten, was auch richtig war. Und da er, ihr Lehrer und Herr, ihnen die F\u00fc\u00dfe gewaschen hatte, sollten sie das Gleiche f\u00fcreinander tun.<br>Jesus gab ihnen ein Beispiel f\u00fcr Demut und Dienst, indem er zeigte, dass niemand zu wichtig ist, um anderen zu dienen. Er schloss, indem er sagte, dass sie gesegnet sein w\u00fcrden, wenn sie seinem Beispiel folgten und dies f\u00fcreinander taten.<br>Nun wird Schwester Ingrid eine weitergehende Zusammenfassung machen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>3. Kommentar der Schwester zu meiner Studienzusammenfassung:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus wollte zeigen, dass Liebe nicht aus guten Gef\u00fchlen und Romantik besteht, sondern darin, zu dienen und zu geben.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Deshalb steht in Johannes 3,16: \u201eDenn so sehr hat Gott die Welt geliebt, dass er seinen einzigen Sohn gab.\u201c<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus ist Teil dieser Liebe und Teil seines Vaters, und deshalb w\u00e4scht er hier die F\u00fc\u00dfe der J\u00fcnger: Er m\u00f6chte die Liebe, die er f\u00fcr sie hat, in Taten zeigen. Wenn wir dem zustimmen, hat er die gleiche Liebe auch f\u00fcr uns und reinigt uns heute mit dem Wasser der Bibel und dem Heiligen Geist.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Heute sind wir herausgefordert, auch die F\u00fc\u00dfe anderer Christen zu waschen, indem wir ihnen mit Liebe und dem Wort des Evangeliums dienen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Als Christen geh\u00f6ren wir nicht zu dieser Welt, aber wir leben in dieser Welt. Deshalb werden wir oft mit Dingen kontaminiert, die nicht zum Evangelium geh\u00f6ren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Doch wenn wir einander auf diesem Weg in den Himmel dienen, k\u00f6nnen wir standhaft bleiben, bis wir das Ziel erreicht haben.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Fragen zur Diskussion basierend auf Johannes 13:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Okay. Auf der Grundlage des obigen Bibelstudiums m\u00f6chte ich meiner Schwester einige verwandte Fragen stellen. Wir hoffen, dass die folgenden Fragen unseren Br\u00fcdern und Schwestern, die gerade Christen geworden sind, hilfreich sein k\u00f6nnen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Warum hat Jesus sich entschieden, seinen J\u00fcngern die F\u00fc\u00dfe zu waschen, und was symbolisierte diese Handlung?<br>\u2013 Seine Handlung symbolisierte die Liebe, die er f\u00fcr diejenigen hat, die zu ihm geh\u00f6ren.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Wie reagierte Petrus, als Jesus ihm die F\u00fc\u00dfe waschen wollte, und warum \u00e4nderte er seine Meinung?<br>\u2013 Petrus wollte nicht, dass Jesus ihm die F\u00fc\u00dfe w\u00e4scht, weil er in Jesus den K\u00f6nig sah und nicht den Diener. Jesus erkl\u00e4rte, dass es notwendig sei, was Petrus zum Umdenken brachte.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Was meinte Jesus, als er sagte: \u201eWenn ich dich nicht wasche, hast du keinen Anteil an mir\u201c?<br>\u2013 Es ist wichtig, die Liebe Christi anzunehmen und sie nicht abzulehnen. Wir m\u00fcssen von den t\u00e4glichen Verunreinigungen durch das Leben auf der Erde gereinigt werden.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Warum sagte Jesus, dass nicht alle am Tisch rein waren?<br>\u2013 Er bezog sich auf Judas Iskariot, der ihn sp\u00e4ter am Abend verraten w\u00fcrde.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Welches Beispiel wollte Jesus seinen J\u00fcngern geben, indem er ihnen die F\u00fc\u00dfe wusch?<br>\u2013 Er zeigte ihnen, wie sie einander lieben sollten. Sp\u00e4ter wird er sagen, dass die Welt sie daran erkennen wird, dass sie seine J\u00fcnger sind, weil sie einander lieben.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Was lehrt uns die Fu\u00dfwaschung durch Jesus \u00fcber F\u00fchrung und Demut?<br>\u2013 Jesus erniedrigte sich selbst bis zum Kreuz. Er strebte keine irdische F\u00fchrung an. Er hatte nur diese kleine Herde, die er drei Jahre lang lehrte, um sie auf den Dienst vorzubereiten, nachdem er zu seinem Vater im Himmel zur\u00fcckgekehrt war.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Warum ist es bedeutsam, dass Jesus die F\u00fc\u00dfe aller J\u00fcnger, auch die von Judas, wusch?<br>\u2013 Judas hatte alle M\u00f6glichkeiten, umzukehren und Jesus nicht zu verraten. Er entschied sich jedoch selbst, dies zu tun, aber Jesus versuchte, ihn auf diese Weise nicht zu verlieren.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Wie k\u00f6nnen wir Jesu Beispiel des Dienens in unserem t\u00e4glichen Leben folgen?<br>\u2013 Wir m\u00fcssen sensibel sein, wer in einem bestimmten Moment ein ermutigendes oder korrigierendes Wort braucht, und nicht z\u00f6gern, jemanden anzurufen, von dem wir wissen, dass er einsam ist und jemanden braucht, der sich um ihn k\u00fcmmert.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Was meint Jesus, wenn er sagt: \u201eEin Diener ist nicht gr\u00f6\u00dfer als sein Herr\u201c?<br>\u2013 Wir sollten nicht nach irdischer F\u00fchrung streben, sondern dem\u00fctig gegen\u00fcber den Menschen um uns herum handeln.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:list {\"ordered\":true,\"start\":10} -->\n<ol start=\"10\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Wie sagt Jesus, dass wir gesegnet werden, wenn wir die Dinge tun, die Er uns gelehrt hat?<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>In der Bibel steht mehrfach geschrieben: Wenn ihr diese Dinge h\u00f6rt und sie tut, dann wird es gute Folgen f\u00fcr euer Leben haben.<\/p>\n<!-- \/wp:paragraph -->"},"excerpt":{"rendered":"","protected":false,"raw":""},"author":1,"featured_media":797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_en_post_content":"<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"795\"} \/-->\n\n<!-- wp:paragraph -->\n<p>Jesus washes his disciples\u2019 feet<br>1 It was just before the Passover Festival. Jesus knew that the hour had come for him to leave this world and go to the Father. Having loved his own who were in the world, he loved them to the end.<br>2 The evening meal was in progress, and the devil had already prompted Judas, the son of Simon Iscariot, to betray Jesus.<br>3 Jesus knew that the Father had put all things under his power, and that he had come from God and was returning to God;<br>4 so he got up from the meal, took off his outer clothing, and wrapped a towel round his waist.<br>5 After that, he poured water into a basin and began to wash his disciples\u2019 feet, drying them with the towel that was wrapped round him.<br>6 He came to Simon Peter, who said to him, \u2018Lord, are you going to wash my feet?\u2019<br>7 Jesus replied, \u2018You do not realise now what I am doing, but later you will understand.\u2019<br>8 \u2018No,\u2019 said Peter, \u2018you shall never wash my feet.\u2019 Jesus answered, \u2018Unless I wash you, you have no part with me.\u2019<br>9 \u2018Then, Lord,\u2019 Simon Peter replied, \u2018not just my feet but my hands and my head as well!\u2019<br>10 Jesus answered, \u2018Those who have had a bath need only to wash their feet; their whole body is clean. And you are clean, though not every one of you.\u2019<br>11 For he knew who was going to betray him, and that was why he said not every one was clean.<br>12 When he had finished washing their feet, he put on his clothes and returned to his place. \u2018Do you understand what I have done for you?\u2019 he asked them.<br>13 \u2018You call me \u201cTeacher\u201d and \u201cLord\u201d, and rightly so, for that is what I am.<br>14 Now that I, your Lord and Teacher, have washed your feet, zou also should wash one another\u2019s feet.<br>15 I have set you an example that you should do as I have done for you.<br>16 Very truly I tell you, no servant is greater than his master, nor is a messenger greater than the one who sent him.<br>17 Now that you know these things, you will be blessed if you do them.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hello everyone, I am kiki. Chinese name of our second phase of the program is \"\u8bfb\u7ecf\u5927\u8bb2\u5802\". The English name is \"Bible study\".<br>We will adopt a relaxed also enjoyable learning mode to take you into a new learning world. Each time I will make a personal summary and analysis from the perspective of a learner, and then Sister Ingrid will help me conduct in-depth learning and problem discussions with everybody.<br>I hope that such an interesting and interactive process can bring new knowledge experience to you all. The following is my interview with my sister on related issues. Today is the twenty-two lecture on the Gospel of John.<br>Everyone is welcome to leave a message in the comment area for discussion!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>2.My summary of John twenty-two-time study:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Well, everybody! Firstly, is still my today\u2019s personal study summary.<br>So, right before the Passover Festival, Jesus knew it was almost time for Him to leave the world and go back to His Father in heaven. He loved His disciples so much and was determined to show them just how deep that love went. During dinner, even though Jesus knew Judas was about to betray Him, He did something really surprising. He got up, took off His outer clothes, and wrapped a towel around His waist. Then, He poured water into a basin and began washing His disciples' feet.<br>This might seem strange, but back in those days, washing someone's feet was usually a job for servants because people's feet got really dirty from walking around in sandals.<br>When Jesus got to Peter, Peter was like, \"No way, you're not washing my feet!\" But Jesus told him that if He didn\u2019t wash his feet, Peter wouldn't have any part with Him.<br>Peter then asked Jesus to wash not just his feet, but his hands and head too! Jesus explained that someone who's had a bath only needs to wash their feet to be clean.<br>After washing everyone's feet, Jesus asked them if they understood what He had done. He reminded them that they called Him Teacher and Lord, which was true. And since He, their Teacher and Lord, had washed their feet, they should do the same for one another.<br>Jesus was setting an example of humility and service, showing them that no one is too important to serve others. He ended by saying that they would be blessed if they followed His example and did these things for each other.<br>Now let Ingrid sister make a go further summary.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>3.Sister\u2019s comment from my studying summary:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus wanted to demonstrate, that love not consists in good feelings and romance, love means to serve and to give.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Therefore, it is written in John 3,16 For so much God father had loved the world that he gave his own son.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus is part of this love and part of his father, and that is why he is washing the feet of the disciples here: He wants to show the love he has for them in action and if we agree, he has the same love for us too and cleanses us today with the water of the Bible and the Holy Spirit.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Today we are challenged to wash the feet of other Christians, too by serving them with love and the word of the Gospel.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>As Christians we are not from this world, but we live in this world, this is why we often get contaminated with things that not belong to the gospel.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>But when we serve each other on this trial to heaven, we can walk firm until we have reached this goal.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":4} -->\n<ol start=\"4\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Q list part: base on John 13th items:<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Okay. Base on above bible study content, now let me ask sister some related questions.<br>We hope the following questions can be helpful to our brothers and sisters who have just become Christians.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 1. Why did Jesus choose to wash His disciples' feet, and what did this act symbolize?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>His act symbolized the love he has for those who belong to him.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 2.How did Peter react when Jesus wanted to wash his feet, and why did he change his mind?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Peter did not want Jesus to wash his feet, because in his eyes, Jesus is the king and not the servant. Jesus explained, that it is necessary, that made him change his mind.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 3. What did Jesus mean when He said, \"Unless I wash you, you have no part with me\"?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>It is important to receive the love of Christ and not to refuse it. And we have to be cleaned from the daily walking on earth.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 4. Why did Jesus say that not everyone at the table was clean?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>He referred to Judas Iscariot, who will betray him later in the evening.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 5. What example was Jesus trying to set for His disciples by washing their feet?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>He showed them how to love one another. Later he will say, that the world will see, that they are his disciples, because they love one another.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 6. What does Jesus\u2019 act of washing the disciples\u2019 feet teach us about leadership and humility?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus humbled himself until he accepted to go to the cross. He did not seek earthly leadership.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>He only had this little flock who he was teaching three years long for to prepare them for ministry after he has gone to the father in heaven.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 7. Why is it significant that Jesus washed the feet of all His disciples, including Judas?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Judas has got all opportunities to repent and not betray Jesus. He himself chose to do this, but Jesus tried not to loose him by this way.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 8. How can we follow Jesus\u2019 example of serving others in our daily lives?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>We have to be sensible who needs a word of encouragement or a word of correction in this moment.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>And not hesitate to call someone we know and we feel, that she or he is lonely and need somebody who cares about.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 9. What does Jesus mean when He says, \"No servant is greater than his master\"?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>We shall not look out for earthly leadership. We shall act with humility towards the people around us, too.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\uf0b7 10. How does Jesus say we will be blessed if we do the things He taught us?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>It is several times written down in the bible, if you hear these things and do them, then it will have a good consequence for your life.<\/p>\n<!-- \/wp:paragraph -->","_en_post_name":"john-131-17","_en_post_excerpt":"","_en_post_title":"John 13,1-17","_zh_post_content":"<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"795\"} \/-->\n\n<!-- wp:paragraph -->\n<p>1 \u903e \u8d8a \u8282 \u4ee5 \u524d \uff0c \u8036 \u7a23 \u77e5 \u9053 \u81ea \u5df1 \u79bb \u4e16 \u5f52 \u7236 \u7684 \u65f6 \u5019 \u5230 \u4e86 \u3002 \u4ed6 \u65e2 \u7136 \u7231 \u4e16 \u95f4 \u5c5e \u81ea \u5df1 \u7684 \u4eba \uff0c \u5c31 \u7231 \u4ed6 \u4eec \u5230 \u5e95 \u3002<br>2 \u5403 \u665a \u996d \u7684 \u65f6 \u5019 \uff0c \u9b54 \u9b3c \u5df2 \u5c06 \u5356 \u8036 \u7a23 \u7684 \u610f \u601d \u653e \u5728 \u897f \u95e8 \u7684 \u513f \u5b50 \u52a0 \u7565 \u4eba \u72b9 \u5927 \u5fc3 \u91cc \u3002<br>3 \u8036 \u7a23 \u77e5 \u9053 \u7236 \u5df2 \u5c06 \u4e07 \u6709 \u4ea4 \u5728 \u4ed6 \u624b \u91cc \uff0c \u4e14 \u77e5 \u9053 \u81ea \u5df1 \u662f \u4ece \u795e \u51fa \u6765 \u7684 \uff0c \u53c8 \u8981 \u5f52 \u5230 \u795e \u90a3 \u91cc \u53bb \uff0c<br>4 \u5c31 \u79bb \u5e2d \u7ad9 \u8d77 \u6765 \uff0c \u8131 \u4e86 \u8863 \u670d \uff0c \u62ff \u4e00 \u6761 \u624b \u5dfe \u675f \u8170 \uff0c<br>5 \u968f \u5f8c \u628a \u6c34 \u5012 \u5728 \u76c6 \u91cc \uff0c \u5c31 \u6d17 \u95e8 \u5f92 \u7684 \u811a \uff0c \u5e76 \u7528 \u81ea \u5df1 \u6240 \u675f \u7684 \u624b \u5dfe \u64e6 \u4e7e \u3002<br>6 \u6328 \u5230 \u897f \u95e8 \u5f7c \u5f97 \uff0c \u5f7c \u5f97 \u5bf9 \u4ed6 \u8bf4 \uff1a \u4e3b \u963f \uff0c \u4f60 \u6d17 \u6211 \u7684 \u811a \u9ebd \uff1f<br>7 \u8036 \u7a23 \u56de \u7b54 \u8bf4 \uff1a \u6211 \u6240 \u505a \u7684 \uff0c \u4f60 \u5982 \u4eca \u4e0d \u77e5 \u9053 \uff0c \u5f8c \u6765 \u5fc5 \u660e \u767d \u3002<br>8 \u5f7c \u5f97 \u8bf4 \uff1a \u4f60 \u6c38 \u4e0d \u53ef \u6d17 \u6211 \u7684 \u811a \uff01 \u8036 \u7a23 \u8bf4 \uff1a \u6211 \u82e5 \u4e0d \u6d17 \u4f60 \uff0c \u4f60 \u5c31 \u4e0e \u6211 \u65e0 \u5206 \u4e86 \u3002<br>9 \u897f \u95e8 \u5f7c \u5f97 \u8bf4 \uff1a \u4e3b \u963f \uff0c \u4e0d \u4f46 \u6211 \u7684 \u811a \uff0c \u8fde \u624b \u548c \u5934 \u4e5f \u8981 \u6d17 \u3002<br>10 \u8036 \u7a23 \u8bf4 \uff1a \u51e1 \u6d17 \u8fc7 \u6fa1 \u7684 \u4eba \uff0c \u53ea \u8981 \u628a \u811a \u4e00 \u6d17 \uff0c \u5168 \u8eab \u5c31 \u4e7e \u51c0 \u4e86 \u3002 \u4f60 \u4eec \u662f \u4e7e \u51c0 \u7684 \uff0c \u7136 \u800c \u4e0d \u90fd \u662f \u4e7e \u51c0 \u7684 \u3002<br>11 \u8036 \u7a23 \u539f \u77e5 \u9053 \u8981 \u5356 \u4ed6 \u7684 \u662f \u8c01 \uff0c \u6240 \u4ee5 \u8bf4 \uff1a \u4f60 \u4eec \u4e0d \u90fd \u662f \u4e7e \u51c0 \u7684 \u3002<br>12 \u8036 \u7a23 \u6d17 \u5b8c \u4e86 \u4ed6 \u4eec \u7684 \u811a \uff0c \u5c31 \u7a7f \u4e0a \u8863 \u670d \uff0c \u53c8 \u5750 \u4e0b \uff0c \u5bf9 \u4ed6 \u4eec \u8bf4 \uff1a \u6211 \u5411 \u4f60 \u4eec \u6240 \u505a \u7684 \uff0c \u4f60 \u4eec \u660e \u767d \u9ebd \uff1f<br>13 \u4f60 \u4eec \u79f0 \u547c \u6211 \u592b \u5b50 \uff0c \u79f0 \u547c \u6211 \u4e3b \uff0c \u4f60 \u4eec \u8bf4 \u7684 \u4e0d \u9519 \uff0c \u6211 \u672c \u6765 \u662f \u3002<br>14 \u6211 \u662f \u4f60 \u4eec \u7684 \u4e3b \uff0c \u4f60 \u4eec \u7684 \u592b \u5b50 \uff0c \u5c1a \u4e14 \u6d17 \u4f60 \u4eec \u7684 \u811a \uff0c \u4f60 \u4eec \u4e5f \u5f53 \u5f7c \u6b64 \u6d17 \u811a \u3002<br>15 \u6211 \u7ed9 \u4f60 \u4eec \u505a \u4e86 \u699c \u6837 \uff0c \u53eb \u4f60 \u4eec \u7167 \u7740 \u6211 \u5411 \u4f60 \u4eec \u6240 \u505a \u7684 \u53bb \u505a \u3002<br>16 \u6211 \u5b9e \u5b9e \u5728 \u5728 \u7684 \u544a \u8bc9 \u4f60 \u4eec \uff0c \u4ec6 \u4eba \u4e0d \u80fd \u5927 \u65bc \u4e3b \u4eba \uff0c \u5dee \u4eba \u4e5f \u4e0d \u80fd \u5927 \u65bc \u5dee \u4ed6 \u7684 \u4eba \u3002<br>17 \u4f60 \u4eec \u65e2 \u77e5 \u9053 \u8fd9 \u4e8b \uff0c \u82e5 \u662f \u53bb \u884c \u5c31 \u6709 \u798f \u4e86<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1.\u5927\u5bb6\u597d\u6211\u662f\u4e3b\u64adkiki,\u6211\u4eec\u7b2c\u4e8c\u9636\u6bb5\u7684\u8282\u76ee\u4e2d\u6587\u540d\u79f0\u662f\u300a\u8bfb\u7ecf\u5927\u8bb2\u5802\u300b\u3002\u82f1\u6587\u540d\u5b57\u662f\u300aBible study\u300b\u3002\u6211\u4eec\u4f1a\u91c7\u53d6\u8f7b\u677e\u6109\u5feb\u7684\u5b66\u4e60\u6a21\u5f0f\uff0c\u5e26\u4f60\u8fdb\u5165\u65b0\u7684\u5b66\u4e60\u4e16\u754c\u3002\u6211\u6bcf\u6b21\u4f1a\u4ee5\u5b66\u4e60\u8005\u7684\u89d2\u5ea6\u505a\u4e00\u4e2a\u4e2a\u4eba\u603b\u7ed3\u5206\u6790\uff0c\u7136\u540eIngrid \u59d0\u59d0\u4f1a\u5e2e\u52a9\u6211\u548c\u5927\u5bb6\u8fdb\u884c\u6df1\u5ea6\u7684\u5b66\u4e60\u548c\u95ee\u9898\u8ba8\u8bba\uff0c\u5e0c\u671b\u8fd9\u6837\u7684\u8da3\u5473\u4e92\u52a8\u6027\u8fc7\u7a0b\u80fd\u7ed9\u5927\u5bb6\u5e26\u6765\u65b0\u7684\u77e5\u8bc6\u4f53\u9a8c\u3002\u4ee5\u4e0b\u8fd8\u662f\u6211\u5bf9\u59d0\u59d0\u7684\u76f8\u5173\u95ee\u9898\u91c7\u8bbf\uff0c\u4eca\u5929\u662f\u7ea6\u7ff0\u798f\u97f3\u7b2c22\u8bb2\uff0c\u6b22\u8fce\u5927\u5bb6\u5728\u8bc4\u8bba\u533a\u7559\u8a00\u8ba8\u8bba\uff01<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u60f3\u8981\u8bc1\u660e\u7684\u662f\uff0c\u7231\u4e0d\u4ec5\u4ec5\u5728\u4e8e\u7f8e\u597d\u7684\u611f\u89c9\u548c\u6d6a\u6f2b\uff0c\u7231\u8fd8\u610f\u5473\u7740\u670d\u52a1\u548c\u4ed8\u51fa\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u56e0\u6b64\uff0c\u7ea6\u7ff0\u798f\u97f3 3:16 \u5199\u9053\uff0c\u7236\u7231\u4e16\u4eba\uff0c\u751a\u81f3\u5c06\u81ea\u5df1\u7684\u513f\u5b50\u8d50\u7ed9\u4ed6\u4eec\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u662f\u8fd9\u79cd\u7231\u7684\u4e00\u90e8\u5206\uff0c\u4e5f\u662f\u4ed6\u7236\u4eb2\u7684\u4e00\u90e8\u5206\uff0c\u8fd9\u5c31\u662f\u4e3a\u4ec0\u4e48\u4ed6\u5728\u8fd9\u91cc\u4e3a\u95e8\u5f92\u6d17\u811a\uff1a\u4ed6\u60f3\u7528\u884c\u52a8\u6765\u8868\u8fbe\u4ed6\u5bf9\u4ed6\u4eec\u7684\u7231\uff0c\u5982\u679c\u6211\u4eec\u540c\u610f\uff0c\u4ed6\u5bf9\u6211\u4eec\u4e5f\u6709\u7740\u540c\u6837\u7684\u7231\uff0c\u4eca\u5929\u4ed6\u5c31\u7528\u5723\u7ecf\u548c\u5723\u7075\u7684\u6c34\u6765\u51c0\u5316\u6211\u4eec\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4eca\u5929\uff0c\u6211\u4eec\u9762\u4e34\u7684\u6311\u6218\u662f\uff0c\u4e5f\u8981\u7528\u7231\u548c\u798f\u97f3\u4e3a\u5176\u4ed6\u57fa\u7763\u5f92\u6d17\u811a\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f5c\u4e3a\u57fa\u7763\u5f92\uff0c\u6211\u4eec\u4e0d\u662f\u5c5e\u4e8e\u8fd9\u4e2a\u4e16\u754c\uff0c\u4f46\u6211\u4eec\u751f\u6d3b\u5728\u8fd9\u4e2a\u4e16\u754c\uff0c\u8fd9\u5c31\u662f\u4e3a\u4ec0\u4e48\u6211\u4eec\u5e38\u5e38\u88ab\u4e0d\u5c5e\u4e8e\u798f\u97f3\u7684\u4e8b\u7269\u6240\u6c61\u67d3\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u5f53\u6211\u4eec\u5728\u901a\u5f80\u5929\u5802\u7684\u8003\u9a8c\u4e2d\u4e92\u76f8\u670d\u52a1\u65f6\uff0c\u6211\u4eec\u5c31\u80fd\u575a\u5b9a\u5730\u8d70\u4e0b\u53bb\uff0c\u76f4\u5230\u8fbe\u5230\u8fd9\u4e2a\u76ee\u6807\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u4e3a\u4ec0\u4e48\u9009\u62e9\u7ed9\u95e8\u5f92\u6d17\u811a\uff1f\u8fd9\u4e2a\u884c\u4e3a\u8c61\u5f81\u7740\u4ec0\u4e48\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4ed6\u7684\u884c\u4e3a\u8c61\u5f81\u7740\u4ed6\u5bf9\u90a3\u4e9b\u5c5e\u4e8e\u4ed6\u7684\u4eba\u7684\u7231\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u8036\u7a23\u8981\u7ed9\u5f7c\u5f97\u6d17\u811a\u65f6\uff0c\u5f7c\u5f97\u7684\u53cd\u5e94\u662f\u4ec0\u4e48\uff1f\u4e3a\u4ec0\u4e48\u4ed6\u6539\u53d8\u4e86\u4e3b\u610f\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f7c\u5f97\u4e0d\u60f3\u8ba9\u8036\u7a23\u6d17\u4ed6\u7684\u811a\uff0c\u56e0\u4e3a\u5728\u4ed6\u773c\u91cc\uff0c\u8036\u7a23\u662f\u738b\uff0c\u4e0d\u662f\u4ec6\u4eba\u3002\u8036\u7a23\u89e3\u91ca\u8bf4\uff0c\u8fd9\u662f\u5fc5\u8981\u7684\uff0c\u8fd9\u8ba9\u4ed6\u6539\u53d8\u4e86\u4e3b\u610f\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u8bf4\u201c\u5982\u679c\u6211\u4e0d\u6d17\u4f60\uff0c\u4f60\u5c31\u4e0e\u6211\u65e0\u5206\u201d\u662f\u4ec0\u4e48\u610f\u601d\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u63a5\u53d7\u57fa\u7763\u7684\u7231\u5e76\u4e14\u4e0d\u62d2\u7edd\u5b83\u5f88\u91cd\u8981\u3002\u6211\u4eec\u5fc5\u987b\u4ece\u65e5\u5e38\u7684\u5c18\u4e16\u751f\u6d3b\u4e2d\u5f97\u5230\u51c0\u5316\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>\u8036\u7a23\u4e3a\u4ec0\u4e48\u8bf4\u5728\u5ea7\u7684\u5e76\u4e0d\u662f\u6bcf\u4e2a\u4eba\u90fd\u5e72\u51c0\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4ed6\u6307\u7684\u662f\u52a0\u7565\u4eba\u72b9\u5927\uff0c\u4ed6\u5c06\u4e8e\u5f53\u665a\u665a\u4e9b\u65f6\u5019\u80cc\u53db\u4ed6\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u901a\u8fc7\u7ed9\u95e8\u5f92\u6d17\u811a\u60f3\u8981\u6811\u7acb\u4ec0\u4e48\u6837\u7684\u699c\u6837\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4ed6\u5411\u4ed6\u4eec\u5c55\u793a\u4e86\u5982\u4f55\u5f7c\u6b64\u76f8\u7231\u3002\u540e\u6765\u4ed6\u8bf4\uff0c\u4e16\u4eba\u5c06\u4f1a\u770b\u5230\uff0c\u4ed6\u4eec\u662f\u4ed6\u7684\u95e8\u5f92\uff0c\u56e0\u4e3a\u4ed6\u4eec\u5f7c\u6b64\u76f8\u7231\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u7ed9\u95e8\u5f92\u6d17\u811a\u7684\u884c\u4e3a\u6559\u4f1a\u6211\u4eec\u5173\u4e8e\u9886\u5bfc\u548c\u8c26\u5351\u7684\u4ec0\u4e48\u9053\u7406\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u8c26\u5351\u81ea\u5df1\uff0c\u76f4\u5230\u4ed6\u540c\u610f\u4e0a\u5341\u5b57\u67b6\u3002\u4ed6\u4e0d\u5bfb\u6c42\u4e16\u4fd7\u7684\u9886\u5bfc\u5730\u4f4d\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4ed6\u53ea\u6709\u8fd9\u4e00\u5c0f\u7fa4\u7f8a\uff0c\u4ed6\u6559\u5bfc\u4ed6\u4eec\u4e09\u5e74\uff0c\u4e3a\u4ed6\u4eec\u505a\u597d\u51c6\u5907\uff0c\u8ba9\u4ed6\u4eec\u80fd\u591f\u5728\u4ed6\u53bb\u5929\u5802\u4e4b\u7236\u90a3\u91cc\u4e4b\u540e\u4ece\u4e8b\u4f20\u9053\u5de5\u4f5c\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u7ed9\u6240\u6709\u95e8\u5f92\u6d17\u811a\uff0c\u5305\u62ec\u72b9\u5927\uff0c\u8fd9\u6709\u4ec0\u4e48\u91cd\u8981\u610f\u4e49\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u72b9\u5927\u6709\u6094\u6539\u7684\u673a\u4f1a\uff0c\u53ef\u4ee5\u4e0d\u80cc\u53db\u8036\u7a23\u3002\u4ed6\u81ea\u5df1\u9009\u62e9\u8fd9\u6837\u505a\uff0c\u4f46\u8036\u7a23\u5374\u4e0d\u60f3\u7528\u8fd9\u79cd\u65b9\u5f0f\u5931\u53bb\u4ed6\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u5982\u4f55\u5728\u65e5\u5e38\u751f\u6d3b\u4e2d\u6548\u6cd5\u8036\u7a23\u670d\u4f8d\u4ed6\u4eba\u7684\u699c\u6837\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u5fc5\u987b\u660e\u667a\u5730\u77e5\u9053\u6b64\u523b\u8c01\u9700\u8981\u4e00\u53e5\u9f13\u52b1\u7684\u8bdd\u6216\u4e00\u53e5\u7ea0\u6b63\u7684\u8bdd\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6beb\u4e0d\u72b9\u8c6b\u5730\u7ed9\u6211\u4eec\u8ba4\u8bc6\u7684\u4eba\u6253\u7535\u8bdd\uff0c\u6211\u4eec\u611f\u89c9\u4ed6\u6216\u5979\u5f88\u5b64\u72ec\uff0c\u9700\u8981\u6709\u4eba\u5173\u5fc3\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u8bf4\u201c\u4ec6\u4eba\u4e0d\u5927\u4e8e\u4e3b\u4eba\u201d\u662f\u4ec0\u4e48\u610f\u601d\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u4e0d\u5e94\u5bfb\u6c42\u4e16\u4fd7\u7684\u9886\u5bfc\u3002\u6211\u4eec\u4e5f\u5e94\u4ee5\u8c26\u5351\u7684\u6001\u5ea6\u5bf9\u5f85\u6211\u4eec\u5468\u56f4\u7684\u4eba\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u8bf4\u5982\u679c\u6211\u4eec\u9075\u884c\u4ed6\u6559\u5bfc\u7684\u4e8b\uff0c\u6211\u4eec\u5c06\u5982\u4f55\u8499\u798f\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5723\u7ecf\u4e2d\u591a\u6b21\u5199\u9053\uff0c\u5982\u679c\u4f60\u542c\u5230\u8fd9\u4e9b\u4e8b\u60c5\u5e76\u53bb\u505a\uff0c\u90a3\u4e48\u5b83\u4f1a\u5bf9\u4f60\u7684\u751f\u6d3b\u4ea7\u751f\u597d\u7684\u5f71\u54cd\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4eca\u5929\u7684\u8282\u76ee\u5c31\u5230\u8fd9\u91cc\uff0c\u611f\u8c22\u5927\u5bb6\u7684\u6536\u542c\uff01 \u795d\u5927\u5bb62024\u590f\u5929\u5feb\u4e50\uff01\u6211\u4eec\u4e0b\u671f\u518d\u4f1a\uff01<\/p>\n<!-- \/wp:paragraph -->","_zh_post_name":"","_zh_post_excerpt":"","_zh_post_title":"John 13,1-17 cn ","_es_post_content":"<!-- wp:paragraph -->\n<p>Era el d\u00eda antes de la fiesta de la Pascua, y Jes\u00fas sab\u00eda que hab\u00eda llegado la hora de abandonar este mundo y volver a su Padre. Hab\u00eda amado a quienes estaban en el mundo y que eran suyos, y ahora les hab\u00eda demostrado por completo su amor hacia ellos. 2 Era el momento de la cena, y el Diablo ya hab\u00eda inculcado la idea de traicionar a Jes\u00fas en la mente de Judas, el hijo de Sim\u00f3n Iscariote. 3 Jes\u00fas sab\u00eda que el Padre hab\u00eda puesto todas las cosas bajo su autoridad,* y \u00e9l hab\u00eda venido de Dios y ahora iba a regresar a Dios. 4 Entonces Jes\u00fas se levant\u00f3 en medio de la cena, quit\u00f3 su bata y se ci\u00f1\u00f3 con una toalla. 5 Ech\u00f3 agua en un taz\u00f3n y comenz\u00f3 a lavar los pies de sus disc\u00edpulos, sec\u00e1ndolos con la toalla con la que se hab\u00eda ce\u00f1ido. 6 Se acerc\u00f3 a Sim\u00f3n Pedro, quien le pregunt\u00f3: \u201cSe\u00f1or, \u00bfvas a lavar mis pies?\u201d<br>7 Jes\u00fas respondi\u00f3: \u201cAhora no entender\u00e1s lo que estoy haciendo por ti. Pero un d\u00eda entender\u00e1s\u201d.<br>8 \u201c\u00a1No!\u201d protest\u00f3 Pedro. \u201c\u00a1Nunca lavar\u00e1s mis pies!\u201d<br>Jes\u00fas respondi\u00f3, \u201cSi no te lavo, no tendr\u00e1s parte conmigo\u201d,<br>9 \u201c\u00a1Entonces, Se\u00f1or, no laves solamente mis pies, sino tambi\u00e9n mis manos y mi cabeza!\u201d exclam\u00f3 Sim\u00f3n Pedro.<br>10 Jes\u00fas respondi\u00f3, \u201cCualquiera que ya se ha ba\u00f1ado, solo necesita lavar sus pies y entonces estar\u00e1 completamente limpio. Ustedes est\u00e1n limpios\u2014pero no todos\u201d. 11 Pues \u00e9l sab\u00eda qui\u00e9n era el que iba a traicionarlo. Por eso dijo \u201cNo todos est\u00e1n limpios\u201d.<br>12 Despu\u00e9s que Jes\u00fas hubo lavado los pies de los disc\u00edpulos, volvi\u00f3 a ponerse su bata y se sent\u00f3. \u201c\u00bfEntienden ustedes lo que les he hecho?\u201d les pregunt\u00f3. 13 \u201cUstedes me llaman \u2018Maestro\u2019 y \u2018Se\u00f1or,\u2019 y est\u00e1 bien que lo hagan, pues eso es lo que soy. 14 As\u00ed que si yo, que soy su Maestro y su Se\u00f1or, he lavado sus pies, ustedes deben lavarse los pies unos a otros. 15 Yo les he dejado un ejemplo, para que ustedes hagan como yo hice. 16 Les digo la verdad, los siervos no son m\u00e1s importantes que su amo, y el que es enviado no es mayor que quien lo env\u00eda. 1<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>1. Introducci\u00f3n<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hola a todos, soy Kiki. El nombre chino de nuestra segunda fase del programa es <strong>\u201e\u8bfb\u7ecf\u5927\u8bb2\u5802\u201c<\/strong>, en ingl\u00e9s <strong>\u201eBible study\u201c (estudio b\u00edblico)<\/strong>.<br>Vamos a introducir un modo de aprendizaje relajado y ameno para guiarlos a un nuevo mundo de conocimiento. Cada vez, har\u00e9 un resumen y an\u00e1lisis personal desde la perspectiva de un aprendiz, y luego la hermana Ingrid me ayudar\u00e1 a llevar a cabo un aprendizaje m\u00e1s profundo y discusiones sobre los problemas con todos ustedes.<br>Espero que un proceso tan interesante e interactivo pueda brindarles nuevas experiencias de aprendizaje. A continuaci\u00f3n, les presento mi entrevista con mi hermana sobre los temas relevantes. Hoy es la <strong>vig\u00e9simo segunda lecci\u00f3n sobre el Evangelio de Juan<\/strong>.<br>\u00a1Todos est\u00e1n cordialmente invitados a dejar un mensaje en la secci\u00f3n de comentarios para unirse a la discusi\u00f3n!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>2. Mi resumen del vig\u00e9simo segundo estudio sobre el Evangelio de Juan:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00a1Muy bien, todos! Ahora les comparto mi resumen personal del estudio de hoy.<br>Poco antes de la Pascua, Jes\u00fas sab\u00eda que hab\u00eda llegado casi el momento de dejar este mundo y regresar a su Padre en el cielo. Amaba tanto a sus disc\u00edpulos que quer\u00eda mostrarles hasta qu\u00e9 punto llegaba su amor por ellos. Durante la cena, aunque Jes\u00fas sab\u00eda que Judas lo traicionar\u00eda, hizo algo realmente sorprendente. Se levant\u00f3, se quit\u00f3 el manto exterior y se at\u00f3 una toalla a la cintura. Luego verti\u00f3 agua en una palangana y comenz\u00f3 a lavar los pies de sus disc\u00edpulos.<br>Esto puede parecer extra\u00f1o, pero en ese tiempo lavar los pies era una tarea t\u00edpica de los sirvientes, ya que los pies de las personas sol\u00edan ensuciarse mucho al caminar en sandalias.<br>Cuando Jes\u00fas lleg\u00f3 a Pedro, este le dijo: \u00ab\u00a1De ninguna manera me lavar\u00e1s los pies!\u00bb. Pero Jes\u00fas le respondi\u00f3 que si no le lavaba los pies, Pedro no podr\u00eda tener parte con \u00e9l.<br>Entonces Pedro pidi\u00f3 que no solo le lavara los pies, sino tambi\u00e9n las manos y la cabeza. Jes\u00fas explic\u00f3 que quien ya se ha ba\u00f1ado solo necesita lavarse los pies para estar completamente limpio.<br>Despu\u00e9s de lavar los pies de todos, Jes\u00fas les pregunt\u00f3 si entend\u00edan lo que hab\u00eda hecho. Les record\u00f3 que lo llamaban Maestro y Se\u00f1or, lo cual era correcto. Y, dado que \u00e9l, su Maestro y Se\u00f1or, les hab\u00eda lavado los pies, tambi\u00e9n ellos deb\u00edan lavarse los pies unos a otros.<br>Con este gesto, Jes\u00fas les dio un ejemplo de humildad y servicio, demostrando que nadie es demasiado importante como para no servir a los dem\u00e1s. Concluy\u00f3 diciendo que ser\u00edan bendecidos si segu\u00edan su ejemplo y se serv\u00edan entre ellos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ahora, la hermana Ingrid presentar\u00e1 un comentario m\u00e1s profundo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>3. Comentario de la hermana sobre mi resumen del estudio:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jes\u00fas quer\u00eda demostrar que el amor no consiste solo en sentimientos agradables o en romanticismo, sino en servir y dar.<br>Por eso, en Juan 3:16 est\u00e1 escrito: \u00abPorque tanto am\u00f3 Dios al mundo, que dio a su Hijo unig\u00e9nito\u00bb.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jes\u00fas es parte de este amor, as\u00ed como lo es de su Padre. Por eso, lav\u00f3 los pies de sus disc\u00edpulos: quer\u00eda expresar con acciones el amor que sent\u00eda por ellos. Si aceptamos esto, debemos recordar que tiene el mismo amor por nosotros hoy y que nos purifica con el agua de la Biblia y el Esp\u00edritu Santo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hoy se nos desaf\u00eda a lavar los pies de otros cristianos sirvi\u00e9ndoles con amor y la palabra del Evangelio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Como cristianos, no pertenecemos a este mundo, pero vivimos en \u00e9l. Por eso, a veces nos contaminamos con cosas que no provienen del Evangelio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sin embargo, si nos servimos mutuamente en este camino hacia el cielo, podremos mantenernos firmes hasta alcanzar la meta final.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Preguntas para la discusi\u00f3n basadas en Juan 13:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ahora, sobre la base del estudio b\u00edblico anterior, quiero plantear algunas preguntas relacionadas a mi hermana. Esperamos que estas preguntas sean \u00fatiles para nuestros hermanos y hermanas que acaban de convertirse en cristianos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>\u00bfPor qu\u00e9 decidi\u00f3 Jes\u00fas lavar los pies de sus disc\u00edpulos, y qu\u00e9 simboliz\u00f3 esta acci\u00f3n?<\/strong><br>\u2013 Su acci\u00f3n simboliz\u00f3 el amor que tiene por aquellos que le pertenecen.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfC\u00f3mo reaccion\u00f3 Pedro cuando Jes\u00fas quiso lavarle los pies y por qu\u00e9 cambi\u00f3 de opini\u00f3n?<\/strong><br>\u2013 Pedro no quer\u00eda que Jes\u00fas le lavara los pies porque lo ve\u00eda como un rey, no como un siervo. Jes\u00fas le explic\u00f3 que era necesario, lo que hizo que Pedro cambiara de opini\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 quiso decir Jes\u00fas con: \u201eSi no te lavo, no tendr\u00e1s parte conmigo\u201c?<\/strong><br>\u2013 Es importante aceptar el amor de Cristo y no rechazarlo. Necesitamos ser limpiados de las impurezas diarias que enfrentamos en esta vida terrenal.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfPor qu\u00e9 dijo Jes\u00fas que no todos los presentes estaban limpios?<\/strong><br>\u2013 Se refer\u00eda a Judas Iscariote, quien m\u00e1s tarde esa misma noche lo traicionar\u00eda.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 ejemplo quiso dar Jes\u00fas a sus disc\u00edpulos al lavarles los pies?<\/strong><br>\u2013 Les mostr\u00f3 c\u00f3mo deb\u00edan amarse entre ellos. M\u00e1s adelante, dir\u00e1 que el mundo los reconocer\u00e1 como sus disc\u00edpulos por el amor que se tengan unos a otros.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 nos ense\u00f1a el lavado de pies de Jes\u00fas sobre liderazgo y humildad?<\/strong><br>\u2013 Jes\u00fas se humill\u00f3 hasta el punto de morir en la cruz. No busc\u00f3 liderazgo terrenal; su objetivo era preparar a esta peque\u00f1a comunidad para el servicio tras su regreso al Padre.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfPor qu\u00e9 fue significativo que Jes\u00fas tambi\u00e9n lavara los pies de Judas?<\/strong><br>\u2013 Judas tuvo todas las oportunidades para arrepentirse y no traicionar a Jes\u00fas. Sin embargo, eligi\u00f3 no hacerlo, pero Jes\u00fas intent\u00f3 salvarlo con este acto.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfC\u00f3mo podemos seguir el ejemplo de servicio de Jes\u00fas en nuestra vida diaria?<\/strong><br>\u2013 Debemos estar atentos a qui\u00e9n necesita una palabra de \u00e1nimo o correcci\u00f3n en cada momento, y no dudar en contactar a alguien que est\u00e9 solo o necesite apoyo.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 quiso decir Jes\u00fas con \u201eUn siervo no es mayor que su se\u00f1or\u201c?<\/strong><br>\u2013 No debemos buscar liderazgo terrenal, sino actuar con humildad hacia quienes nos rodean.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfC\u00f3mo dice Jes\u00fas que seremos bendecidos si hacemos lo que nos ha ense\u00f1ado?<\/strong><br>\u2013 La Biblia ense\u00f1a que escuchar y practicar estas ense\u00f1anzas traer\u00e1 buenas consecuencias a nuestras vidas.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->","_es_post_name":"","_es_post_excerpt":"","_es_post_title":"Juan 13,1-17","_de_post_content":"<!-- wp:paragraph -->\n<p>Jesus w\u00e4scht seinen J\u00fcngern die F\u00fc\u00dfe<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>1 Es war kurz vor dem Passahfest. Jesus wusste, dass die Stunde gekommen war, um diese Welt zu verlassen und zum Vater zu gehen. Er hatte die Seinen, die in der Welt waren, geliebt und liebte sie bis zum Ende.<br>2 Das Abendessen war im Gange, und der Teufel hatte Judas, den Sohn von Simon Iskariot, bereits dazu verleitet, Jesus zu verraten.<br>3 Jesus wusste, dass der Vater ihm alles in die Hand gegeben hatte und dass er von Gott gekommen war und zu Gott zur\u00fcckkehren w\u00fcrde.<br>4 Da stand er vom Mahl auf, legte sein Obergewand ab, nahm ein Tuch und band es sich um die H\u00fcfte.<br>5 Dann goss er Wasser in ein Becken und begann, die F\u00fc\u00dfe seiner J\u00fcnger zu waschen und sie mit dem Tuch abzutrocknen, das er umgebunden hatte.<br>6 Als er zu Simon Petrus kam, sagte dieser zu ihm: \u201eHerr, willst du mir die F\u00fc\u00dfe waschen?\u201c<br>7 Jesus antwortete: \u201eWas ich tue, verstehst du jetzt noch nicht, aber sp\u00e4ter wirst du es begreifen.\u201c<br>8 \u201eNein,\u201c sagte Petrus, \u201eniemals sollst du mir die F\u00fc\u00dfe waschen.\u201c Jesus entgegnete: \u201eWenn ich dich nicht wasche, hast du keinen Anteil an mir.\u201c<br>9 \u201eHerr,\u201c sagte Simon Petrus, \u201edann wasche nicht nur meine F\u00fc\u00dfe, sondern auch meine H\u00e4nde und meinen Kopf!\u201c<br>10 Jesus antwortete: \u201eWer gebadet hat, braucht sich nur die F\u00fc\u00dfe zu waschen; er ist ganz rein. Und ihr seid rein, aber nicht alle.\u201c<br>11 Er wusste n\u00e4mlich, wer ihn verraten w\u00fcrde; deshalb sagte er: \u201eNicht alle seid ihr rein.\u201c<br>12 Als er ihnen die F\u00fc\u00dfe gewaschen hatte, zog er seine Kleider wieder an und kehrte zu seinem Platz zur\u00fcck. Er fragte sie: \u201eVersteht ihr, was ich f\u00fcr euch getan habe?<br>13 Ihr nennt mich \u201aLehrer\u2018 und \u201aHerr\u2018, und das zu Recht, denn das bin ich.<br>14 Wenn nun ich, euer Herr und Lehrer, euch die F\u00fc\u00dfe gewaschen habe, so sollt auch ihr einander die F\u00fc\u00dfe waschen.<br>15 Ich habe euch ein Beispiel gegeben, damit auch ihr so handelt, wie ich an euch gehandelt habe.<br>16 Wahrlich, ich sage euch: Ein Diener ist nicht gr\u00f6\u00dfer als sein Herr, und ein Gesandter nicht gr\u00f6\u00dfer als der, der ihn gesandt hat.<br>17 Wenn ihr dies wisst, seid ihr selig, wenn ihr es auch tut.\u201c<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hallo zusammen, ich bin Kiki. Der chinesische Name unserer zweiten Programmphase lautet \u201e\u8bfb\u7ecf\u5927\u8bb2\u5802\u201c, auf Englisch \u201eBible study\u201c (Bibelstudium).<br>Wir werden einen entspannten und angenehmen Lernmodus einf\u00fchren, um euch in eine neue Lernwelt zu f\u00fchren. Jedes Mal werde ich aus der Perspektive eines Lernenden eine pers\u00f6nliche Zusammenfassung und Analyse machen, und dann wird Schwester Ingrid mir helfen, mit allen ein vertieftes Lernen und Problemdiskussionen zu f\u00fchren.<br>Ich hoffe, dass ein solch interessanter und interaktiver Prozess euch allen neue Lernerfahrungen bringen kann. Im Folgenden ist mein Interview mit meiner Schwester zu verwandten Themen. Heute ist der zweiundzwanzigste Vortrag \u00fcber das Johannesevangelium.<br>Alle sind herzlich eingeladen, eine Nachricht im Kommentarbereich f\u00fcr Diskussionen zu hinterlassen!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>2. Meine Zusammenfassung des zweiundzwanzigsten Studiums \u00fcber Johannes:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nun, alle zusammen! Zun\u00e4chst kommt wieder meine pers\u00f6nliche Studienzusammenfassung f\u00fcr heute.<br>Also, kurz vor dem Passahfest wusste Jesus, dass es fast an der Zeit war, diese Welt zu verlassen und zu seinem Vater im Himmel zur\u00fcckzukehren. Er liebte seine J\u00fcnger so sehr und wollte ihnen zeigen, wie tief seine Liebe zu ihnen ging. W\u00e4hrend des Abendessens, obwohl Jesus wusste, dass Judas ihn verraten w\u00fcrde, tat er etwas wirklich \u00dcberraschendes. Er stand auf, zog seine \u00e4u\u00dferen Kleider aus und band sich ein Handtuch um die H\u00fcften. Dann goss er Wasser in ein Becken und begann, die F\u00fc\u00dfe seiner J\u00fcnger zu waschen.<br>Das mag seltsam erscheinen, aber damals war das Waschen der F\u00fc\u00dfe normalerweise die Aufgabe von Dienern, da die F\u00fc\u00dfe der Menschen durch das Gehen in Sandalen sehr schmutzig wurden.<br>Als Jesus zu Petrus kam, sagte dieser: \u201eAuf keinen Fall wirst du mir die F\u00fc\u00dfe waschen!\u201c Aber Jesus sagte ihm, dass, wenn er seine F\u00fc\u00dfe nicht w\u00e4scht, Petrus keinen Anteil an ihm haben w\u00fcrde.<br>Daraufhin bat Petrus Jesus, nicht nur seine F\u00fc\u00dfe, sondern auch seine H\u00e4nde und seinen Kopf zu waschen! Jesus erkl\u00e4rte, dass jemand, der gebadet hat, nur seine F\u00fc\u00dfe waschen muss, um rein zu sein.<br>Nachdem er allen die F\u00fc\u00dfe gewaschen hatte, fragte Jesus sie, ob sie verstanden h\u00e4tten, was er getan hatte. Er erinnerte sie daran, dass sie ihn Lehrer und Herr nannten, was auch richtig war. Und da er, ihr Lehrer und Herr, ihnen die F\u00fc\u00dfe gewaschen hatte, sollten sie das Gleiche f\u00fcreinander tun.<br>Jesus gab ihnen ein Beispiel f\u00fcr Demut und Dienst, indem er zeigte, dass niemand zu wichtig ist, um anderen zu dienen. Er schloss, indem er sagte, dass sie gesegnet sein w\u00fcrden, wenn sie seinem Beispiel folgten und dies f\u00fcreinander taten.<br>Nun wird Schwester Ingrid eine weitergehende Zusammenfassung machen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>3. Kommentar der Schwester zu meiner Studienzusammenfassung:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus wollte zeigen, dass Liebe nicht aus guten Gef\u00fchlen und Romantik besteht, sondern darin, zu dienen und zu geben.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Deshalb steht in Johannes 3,16: \u201eDenn so sehr hat Gott die Welt geliebt, dass er seinen einzigen Sohn gab.\u201c<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus ist Teil dieser Liebe und Teil seines Vaters, und deshalb w\u00e4scht er hier die F\u00fc\u00dfe der J\u00fcnger: Er m\u00f6chte die Liebe, die er f\u00fcr sie hat, in Taten zeigen. Wenn wir dem zustimmen, hat er die gleiche Liebe auch f\u00fcr uns und reinigt uns heute mit dem Wasser der Bibel und dem Heiligen Geist.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Heute sind wir herausgefordert, auch die F\u00fc\u00dfe anderer Christen zu waschen, indem wir ihnen mit Liebe und dem Wort des Evangeliums dienen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Als Christen geh\u00f6ren wir nicht zu dieser Welt, aber wir leben in dieser Welt. Deshalb werden wir oft mit Dingen kontaminiert, die nicht zum Evangelium geh\u00f6ren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Doch wenn wir einander auf diesem Weg in den Himmel dienen, k\u00f6nnen wir standhaft bleiben, bis wir das Ziel erreicht haben.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Fragen zur Diskussion basierend auf Johannes 13:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Okay. Auf der Grundlage des obigen Bibelstudiums m\u00f6chte ich meiner Schwester einige verwandte Fragen stellen. Wir hoffen, dass die folgenden Fragen unseren Br\u00fcdern und Schwestern, die gerade Christen geworden sind, hilfreich sein k\u00f6nnen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Warum hat Jesus sich entschieden, seinen J\u00fcngern die F\u00fc\u00dfe zu waschen, und was symbolisierte diese Handlung?<br>\u2013 Seine Handlung symbolisierte die Liebe, die er f\u00fcr diejenigen hat, die zu ihm geh\u00f6ren.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Wie reagierte Petrus, als Jesus ihm die F\u00fc\u00dfe waschen wollte, und warum \u00e4nderte er seine Meinung?<br>\u2013 Petrus wollte nicht, dass Jesus ihm die F\u00fc\u00dfe w\u00e4scht, weil er in Jesus den K\u00f6nig sah und nicht den Diener. Jesus erkl\u00e4rte, dass es notwendig sei, was Petrus zum Umdenken brachte.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Was meinte Jesus, als er sagte: \u201eWenn ich dich nicht wasche, hast du keinen Anteil an mir\u201c?<br>\u2013 Es ist wichtig, die Liebe Christi anzunehmen und sie nicht abzulehnen. Wir m\u00fcssen von den t\u00e4glichen Verunreinigungen durch das Leben auf der Erde gereinigt werden.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Warum sagte Jesus, dass nicht alle am Tisch rein waren?<br>\u2013 Er bezog sich auf Judas Iskariot, der ihn sp\u00e4ter am Abend verraten w\u00fcrde.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Welches Beispiel wollte Jesus seinen J\u00fcngern geben, indem er ihnen die F\u00fc\u00dfe wusch?<br>\u2013 Er zeigte ihnen, wie sie einander lieben sollten. Sp\u00e4ter wird er sagen, dass die Welt sie daran erkennen wird, dass sie seine J\u00fcnger sind, weil sie einander lieben.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Was lehrt uns die Fu\u00dfwaschung durch Jesus \u00fcber F\u00fchrung und Demut?<br>\u2013 Jesus erniedrigte sich selbst bis zum Kreuz. Er strebte keine irdische F\u00fchrung an. Er hatte nur diese kleine Herde, die er drei Jahre lang lehrte, um sie auf den Dienst vorzubereiten, nachdem er zu seinem Vater im Himmel zur\u00fcckgekehrt war.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Warum ist es bedeutsam, dass Jesus die F\u00fc\u00dfe aller J\u00fcnger, auch die von Judas, wusch?<br>\u2013 Judas hatte alle M\u00f6glichkeiten, umzukehren und Jesus nicht zu verraten. Er entschied sich jedoch selbst, dies zu tun, aber Jesus versuchte, ihn auf diese Weise nicht zu verlieren.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Wie k\u00f6nnen wir Jesu Beispiel des Dienens in unserem t\u00e4glichen Leben folgen?<br>\u2013 Wir m\u00fcssen sensibel sein, wer in einem bestimmten Moment ein ermutigendes oder korrigierendes Wort braucht, und nicht z\u00f6gern, jemanden anzurufen, von dem wir wissen, dass er einsam ist und jemanden braucht, der sich um ihn k\u00fcmmert.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Was meint Jesus, wenn er sagt: \u201eEin Diener ist nicht gr\u00f6\u00dfer als sein Herr\u201c?<br>\u2013 Wir sollten nicht nach irdischer F\u00fchrung streben, sondern dem\u00fctig gegen\u00fcber den Menschen um uns herum handeln.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:list {\"ordered\":true,\"start\":10} -->\n<ol start=\"10\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Wie sagt Jesus, dass wir gesegnet werden, wenn wir die Dinge tun, die Er uns gelehrt hat?<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>In der Bibel steht mehrfach geschrieben: Wenn ihr diese Dinge h\u00f6rt und sie tut, dann wird es gute Folgen f\u00fcr euer Leben haben.<\/p>\n<!-- \/wp:paragraph -->","_de_post_name":"","_de_post_excerpt":"","_de_post_title":"Johannes 13,1-17","_nb_post_content":"<!-- wp:paragraph -->\n<p>&nbsp;P\u00e5skeh\u00f8ytiden<sup>[<a href=\"https:\/\/www.biblegateway.com\/passage\/?search=John%2013&amp;version=LB#fno-LB-3380a\">a<\/a>]<\/sup> skulle snart begynne. Jesus visste at den tiden som hans Far i himmelen hadde bestemt, n\u00e5 var kommet. Han skulle forlate jorden og vende tilbake til sin Far i himmelen. Jesus ga derfor et siste bevis p\u00e5 hvor h\u00f8yt han elsket disiplene.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>2&nbsp;<\/sup>Jesus og disiplene var samlet for \u00e5 spise sammen. Djevelen hadde allerede gitt Judas, han som var s\u00f8nn til Simon Iskariot, den tanken at han skulle forr\u00e5de Jesus. <sup>3&nbsp;<\/sup>Jesus visste at Far i himmelen hadde gitt alt over i hans h\u00e5nd, og at han selv var kommet fra Gud og skulle vende tilbake til Gud. <sup>4&nbsp;<\/sup>Jesus reiste seg fra bordet, tok av seg kappen og bandt et h\u00e5ndkle om livet. <sup>5&nbsp;<\/sup>Han helte vann i et fat og begynte \u00e5 vaske disiplene sine f\u00f8tter og t\u00f8rke dem med h\u00e5ndkleet som han hadde bundet om seg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>6&nbsp;<\/sup>Da han kom til Simon Peter, sa Simon til ham: \u201dHerre, du skal ikke vaske f\u00f8ttene mine.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>7&nbsp;<\/sup>Da svarte Jesus: \u201dAkkurat n\u00e5 forst\u00e5r du ikke det jeg gj\u00f8r, men det kommer en dag du skal skj\u00f8nne meningen med det.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>8&nbsp;<\/sup>\u201dNei\u201d, protesterte Peter, \u201daldri i livet om du skal vaske f\u00f8ttene mine!\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus sa til ham: \u201dDersom jeg ikke gj\u00f8r deg ren, kan du ikke tilh\u00f8re meg.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>9&nbsp;<\/sup>Da ropte Peter: \u201dHerre, vask ikke bare f\u00f8ttene mine, men ogs\u00e5 hendene og hodet.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>10&nbsp;<\/sup>Jesus sa til ham: \u201dDen som har badet, trenger bare f\u00e5 f\u00f8ttene vasket for \u00e5 v\u00e6re ordentlig ren. Dere er rene, men det gjelder ikke alle.\u201d <sup>11&nbsp;<\/sup>Jesus visste nemlig hvem som skulle forr\u00e5de ham. Det var derfor han sa at ikke alle var rene.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><sup>12&nbsp;<\/sup>Da Jesus hadde vasket f\u00f8ttene deres, tok han p\u00e5 seg kappen igjen og tok plass ved bordet. Han spurte dem: \u201dForst\u00e5r dere det jeg har gjort med dere? <sup>13&nbsp;<\/sup>Dere kaller meg Mester og Herre, og det gj\u00f8r dere rett i, for det er nettopp det jeg er. <sup>14&nbsp;<\/sup>Dersom n\u00e5 jeg, som er deres Herre og Mester, har vasket f\u00f8ttene deres, da er ogs\u00e5 dere skyldige i \u00e5 vaske f\u00f8ttene til hverandre. <sup>15&nbsp;<\/sup>Jeg har gitt dere et eksempel til \u00e5 f\u00f8lge: Gj\u00f8r som jeg har gjort mot dere. <sup>16&nbsp;<\/sup>Jeg forsikrer dere at en tjener st\u00e5r ikke over sin herre, og en utsending st\u00e5r ikke over han som har sendt ham. <sup>17&nbsp;<\/sup>N\u00e5r dere n\u00e5 vet dette, da er dere lykkelige dersom dere ogs\u00e5 praktiserer det.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Selvf\u00f8lgelig! Her er hele teksten oversatt til norsk (bokm\u00e5l):<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hei alle sammen, jeg er Kiki.<\/strong><br>Det kinesiske navnet p\u00e5 andre fase av programmet v\u00e5rt er \u00ab\u8bfb\u7ecf\u5927\u8bb2\u5802\u00bb, p\u00e5 engelsk \u00abBible Study\u00bb (bibelstudium).<br>Vi vil innf\u00f8re en avslappet og behagelig l\u00e6ringsform for \u00e5 f\u00f8re dere inn i en ny l\u00e6ringsverden.<br>Hver gang vil jeg lage en personlig oppsummering og analyse fra perspektivet til en som l\u00e6rer, og deretter vil s\u00f8ster Ingrid hjelpe meg med \u00e5 lede fordypet l\u00e6ring og diskusjon med alle.<br>Jeg h\u00e5per at en slik interessant og interaktiv prosess kan gi dere alle nye l\u00e6ringserfaringer.<br>Nedenfor finner dere mitt intervju med min s\u00f8ster om relaterte temaer.<br>I dag er det det tjuetoende foredraget om Johannesevangeliet.<br>Alle er hjertelig velkommen til \u00e5 legge igjen en melding i kommentarfeltet for diskusjon!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>2. Min oppsummering av det tjuetoende studiet om Johannes:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>S\u00e5, alle sammen! F\u00f8rst kommer igjen min personlige studiumoppsummering for i dag.<br>Rett f\u00f8r p\u00e5skefeiringen visste Jesus at tiden n\u00e6rmet seg for at han skulle forlate denne verden og vende tilbake til sin Far i himmelen.<br>Han elsket disiplene sine s\u00e5 h\u00f8yt og \u00f8nsket \u00e5 vise dem hvor dyp hans kj\u00e6rlighet til dem var.<br>Under m\u00e5ltidet \u2013 selv om Jesus visste at Judas ville forr\u00e5de ham \u2013 gjorde han noe virkelig overraskende.<br>Han reiste seg, tok av seg de ytre kl\u00e6rne og bandt et h\u00e5ndkle rundt livet.<br>Deretter helte han vann i et fat og begynte \u00e5 vaske disiplenes f\u00f8tter.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Det kan virke rart, men den gang var det vanlig at tjenere vasket gjestenes f\u00f8tter, fordi de ble sv\u00e6rt skitne etter \u00e5 ha g\u00e5tt i sandaler.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Da Jesus kom til Peter, sa Peter: \u00abAldri i evighet skal du vaske mine f\u00f8tter!\u00bb<br>Men Jesus svarte at hvis han ikke vasket Peters f\u00f8tter, kunne Peter ikke ha del i ham.<br>Da ba Peter Jesus om \u00e5 vaske ikke bare f\u00f8ttene hans, men ogs\u00e5 hendene og hodet.<br>Jesus forklarte at den som allerede er badet, bare trenger \u00e5 f\u00e5 f\u00f8ttene vasket for \u00e5 v\u00e6re ren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Etter at han hadde vasket alles f\u00f8tter, spurte Jesus dem om de forstod hva han hadde gjort.<br>Han minnet dem p\u00e5 at de kalte ham l\u00e6rer og Herre \u2013 og det var rett.<br>Og n\u00e5r han, deres Herre og l\u00e6rer, hadde vasket deres f\u00f8tter, burde de ogs\u00e5 vaske hverandres f\u00f8tter.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus ga dem et eksempel p\u00e5 ydmykhet og tjeneste, ved \u00e5 vise at ingen er for viktig til \u00e5 tjene andre.<br>Han avsluttet med \u00e5 si at de ville v\u00e6re salige hvis de fulgte hans eksempel og gjorde det samme for hverandre.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>N\u00e5 vil s\u00f8ster Ingrid gi en videreg\u00e5ende oppsummering.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>3. S\u00f8sterens kommentar til min studiumoppsummering:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus \u00f8nsket \u00e5 vise at kj\u00e6rlighet ikke handler om gode f\u00f8lelser og romantikk, men om \u00e5 tjene og gi.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Derfor st\u00e5r det i Johannes 3,16: \u00abFor s\u00e5 h\u00f8yt har Gud elsket verden at han ga sin enb\u00e5rne S\u00f8nn.\u00bb<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus er en del av denne kj\u00e6rligheten og en del av sin Far, og derfor vasker han disiplenes f\u00f8tter:<br>Han \u00f8nsker \u00e5 vise kj\u00e6rligheten han har for dem i handling.<br>Hvis vi sier ja til det, har han den samme kj\u00e6rligheten for oss i dag og renser oss med vannet i Bibelen og Den hellige \u00e5nd.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I dag blir vi utfordret til \u00e5 vaske andre kristnes f\u00f8tter, ved \u00e5 tjene dem med kj\u00e6rlighet og evangeliets ord.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Som kristne tilh\u00f8rer vi ikke denne verden, men vi lever i den.<br>Derfor blir vi ofte forurenset av ting som ikke tilh\u00f8rer evangeliet.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Men n\u00e5r vi tjener hverandre p\u00e5 veien mot himmelen, kan vi st\u00e5 fast til vi n\u00e5r m\u00e5let.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Sp\u00f8rsm\u00e5l til diskusjon basert p\u00e5 Johannes 13:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hvorfor valgte Jesus \u00e5 vaske disiplenes f\u00f8tter, og hva symboliserte denne handlingen?<\/strong><br>\u2013 Handlingene hans symboliserte kj\u00e6rligheten han har til dem som tilh\u00f8rer ham.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hvordan reagerte Peter da Jesus ville vaske f\u00f8ttene hans, og hvorfor endret han mening?<\/strong><br>\u2013 Peter ville ikke at Jesus skulle vaske f\u00f8ttene hans, fordi han s\u00e5 Jesus som konge, ikke som tjener.<br>Jesus forklarte at det var n\u00f8dvendig, og da endret Peter mening.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hva mente Jesus da han sa: \u00abHvis jeg ikke vasker deg, har du ingen del i meg\u00bb?<\/strong><br>\u2013 Det er viktig \u00e5 ta imot Kristi kj\u00e6rlighet og ikke avvise den.<br>Vi trenger \u00e5 bli renset fra hverdagens forurensninger i livet p\u00e5 jorden.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hvorfor sa Jesus at ikke alle ved bordet var rene?<\/strong><br>\u2013 Han siktet til Judas Iskariot, som senere den kvelden skulle forr\u00e5de ham.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hvilket eksempel ville Jesus gi disiplene ved \u00e5 vaske f\u00f8ttene deres?<\/strong><br>\u2013 Han ville vise hvordan de skulle elske hverandre.<br>Senere sier han at verden vil kjenne dem som hans disipler fordi de elsker hverandre.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hva l\u00e6rer Jesu fotvask oss om lederskap og ydmykhet?<\/strong><br>\u2013 Jesus ydmyket seg selv helt til korset.<br>Han s\u00f8kte ikke jordisk lederskap.<br>Han hadde bare denne lille flokken, som han l\u00e6rte i tre \u00e5r for \u00e5 forberede dem p\u00e5 tjenesten etter at han skulle tilbake til sin Far.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hvorfor er det betydningsfullt at Jesus vasket alles f\u00f8tter \u2013 ogs\u00e5 Judas sine?<\/strong><br>\u2013 Judas hadde alle muligheter til \u00e5 vende om og ikke forr\u00e5de Jesus.<br>Han tok valget selv, men Jesus pr\u00f8vde fortsatt \u00e5 n\u00e5 ham gjennom denne handlingen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hvordan kan vi f\u00f8lge Jesu eksempel p\u00e5 tjeneste i hverdagen?<\/strong><br>\u2013 Vi m\u00e5 v\u00e6re f\u00f8lsomme for hvem som trenger et oppmuntrende eller rettledende ord i \u00f8yeblikket.<br>Vi m\u00e5 ikke n\u00f8le med \u00e5 ringe noen vi vet er ensomme og trenger noen som bryr seg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hva mener Jesus n\u00e5r han sier: \u00abEn tjener er ikke st\u00f8rre enn sin herre\u00bb?<\/strong><br>\u2013 Vi skal ikke strebe etter jordisk makt, men handle ydmykt mot dem rundt oss.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Hva sier Jesus om at vi blir salige n\u00e5r vi gj\u00f8r det han har l\u00e6rt oss?<\/strong><br>\u2013 I Bibelen st\u00e5r det flere steder: Hvis dere h\u00f8rer disse ordene og gj\u00f8r etter dem, vil det f\u00e5 gode konsekvenser for livet deres.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","_nb_post_name":"","_nb_post_excerpt":"","_nb_post_title":"John 13,1-17","edit_language":"de","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","iawp_total_views":78,"footnotes":""},"categories":[25],"tags":[],"series":[32],"class_list":["post-798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcaststrans","series-bibelstudies"],"episode_featured_image":"https:\/\/loveforasia.org\/wp-content\/uploads\/2024\/09\/OIG4.QFTq4ap8fwMga94YDFgv.jpg","episode_player_image":"https:\/\/loveforasia.org\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-04-04-at-9.09.02-PM.jpeg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"}},"rssFeedUrl":"https:\/\/loveforasia.org\/de\/feed\/podcast\/bibelstudies","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"mx7FTzVSBO\"><a href=\"https:\/\/loveforasia.org\/de\/john-131-17\/\">Johannes 13,1-17<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/loveforasia.org\/de\/john-131-17\/embed\/#?secret=mx7FTzVSBO\" width=\"500\" height=\"350\" title=\"&#8222;Johannes 13,1-17&#8220; &#8211; Love for Asia\" data-secret=\"mx7FTzVSBO\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/loveforasia.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/comments?post=798"}],"version-history":[{"count":4,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts\/798\/revisions"}],"predecessor-version":[{"id":945,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts\/798\/revisions\/945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/media\/797"}],"wp:attachment":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/media?parent=798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/categories?post=798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/tags?post=798"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/series?post=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}