{"id":957,"date":"2024-12-22T22:05:36","date_gmt":"2024-12-22T22:05:36","guid":{"rendered":"https:\/\/loveforasia.org\/?p=957"},"modified":"2026-04-18T15:21:52","modified_gmt":"2026-04-18T15:21:52","slug":"","status":"publish","type":"post","link":"https:\/\/loveforasia.org\/de\/christmas-special\/","title":{"rendered":"Weihnachtsprogramm 2024","raw":"Weihnachtsprogramm 2024"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/loveforasia.org\/wp-content\/uploads\/2024\/12\/Der_Kaiser_als_Schachfigur_Gottes.mp3\"><\/audio><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">26 Und im sechsten Monat ward der Engel Gabriel gesandt von Gott in eine Stadt in Galil\u00e4a, die hei\u00dft Nazareth,<br>27 zu einer Jungfrau, die vertraut war einem Manne mit Namen Joseph, vom Hause David: und die Jungfrau hie\u00df Maria.<br>28 Und der Engel kam zu ihr hinein und sprach: Gegr\u00fc\u00dfet seist du, Holdselige! Der HERR ist mit dir, du Gebenedeite unter den Weibern!<br>29 Da sie aber ihn sah, erschrak sie \u00fcber seine Rede und gedachte: Welch ein Gru\u00df ist das?<br>30 Und der Engel sprach zu ihr: F\u00fcrchte dich nicht, Maria! du hast Gnade bei Gott gefunden.<br>31 Siehe, du wirst schwanger werden und einen Sohn geb\u00e4ren, des Namen sollst du Jesus hei\u00dfen.<br>32 Der wird gro\u00df sein und ein Sohn des H\u00f6chsten genannt werden; und Gott der HERR wird ihm den Stuhl seines Vaters David geben;<br>33 und er wird ein K\u00f6nig sein \u00fcber das Haus Jakob ewiglich, und seines K\u00f6nigreiches wird kein Ende sein.<br>34 Da sprach Maria zu dem Engel: Wie soll das zugehen, da ich von keinem Manne wei\u00df?<br>35 Der Engel antwortete und sprach zu ihr: Der heilige Geist wird \u00fcber dich kommen, und die Kraft des H\u00f6chsten wird dich \u00fcberschatten; darum wird auch das Heilige, das von dir geboren wird, Gottes Sohn genannt werden.<br>36 Und siehe, Elisabeth, deine Gefreunde, ist auch schwanger mit einem Sohn in ihrem Alter und geht jetzt im sechsten Monat, von der man sagt, da\u00df sie unfruchtbar sei.<br>37 Denn bei Gott ist kein Ding unm\u00f6glich.<br>38 Maria aber sprach: Siehe ich bin des HERRN Magd; mir geschehe, wie du gesagt hast. Und der Engel schied von ihr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18 Die Geburt Christi war aber also getan. Als Maria, seine Mutter, dem Joseph vertraut war, fand sich&#8217;s ehe er sie heimholte, da\u00df sie schwanger war von dem heiligen Geist.<br>19 Joseph aber, ihr Mann, war fromm und wollte sie nicht in Schande bringen, gedachte aber, sie heimlich zu verlassen.<br>20 Indem er aber also gedachte, siehe, da erschien ihm ein Engel des HERRN im Traum und sprach: Joseph, du Sohn Davids, f\u00fcrchte dich nicht, Maria, dein Gemahl, zu dir zu nehmen; denn das in ihr geboren ist, das ist von dem heiligen Geist.<br>21 Und sie wird einen Sohn geb\u00e4ren, des Namen sollst du Jesus hei\u00dfen; denn er wird sein Volk selig machen von ihren S\u00fcnden.<br>22 Das ist aber alles geschehen, auf da\u00df erf\u00fcllt w\u00fcrde, was der HERR durch den Propheten gesagt hat, der da spricht:<br>23 &#8222;Siehe, eine Jungfrau wird schwanger sein und einen Sohn geb\u00e4ren, und sie werden seinen Namen Immanuel hei\u00dfen&#8220;, das ist verdolmetscht: Gott mit uns.<br>24 Da nun Joseph vom Schlaf erwachte, tat er, wie ihm des HERRN Engel befohlen hatte, und nahm sein Gemahl zu sich.<br>25 Und er erkannte sie nicht, bis sie ihren ersten Sohn gebar; und hie\u00df seinen Namen Jesus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lukas 2,1-21<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 Es begab sich aber zu der Zeit, da\u00df ein Gebot von dem Kaiser Augustus ausging, da\u00df alle Welt gesch\u00e4tzt w\u00fcrde.<br>2 Und diese Sch\u00e4tzung war die allererste und geschah zu der Zeit, da Cyrenius Landpfleger von Syrien war.<br>3 Und jedermann ging, da\u00df er sich sch\u00e4tzen lie\u00dfe, ein jeglicher in seine Stadt.<br>4 Da machte sich auch auf Joseph aus Galil\u00e4a, aus der Stadt Nazareth, in das j\u00fcdische Land zur Stadt Davids, die da hei\u00dft Bethlehem, darum da\u00df er von dem Hause und Geschlechte Davids war,<br>5 auf da\u00df er sich sch\u00e4tzen lie\u00dfe mit Maria, seinem vertrauten Weibe, die ward schwanger.<br>6 Und als sie daselbst waren, kam die Zeit, da sie geb\u00e4ren sollte.<br>7 Und sie gebar ihren ersten Sohn und wickelte ihn in Windeln und legte ihn in eine Krippe; denn sie hatten sonst keinen Raum in der Herberge.<br>8 Und es waren Hirten in derselben Gegend auf dem Felde bei den H\u00fcrden, die h\u00fcteten des Nachts ihre Herde.<br>9 Und siehe, des HERRN Engel trat zu ihnen, und die Klarheit des HERRN leuchtete um sie; und sie f\u00fcrchteten sich sehr.<br>10 Und der Engel sprach zu ihnen: F\u00fcrchtet euch nicht! siehe, ich verk\u00fcndige euch gro\u00dfe Freude, die allem Volk widerfahren wird;<br>11 denn euch ist heute der Heiland geboren, welcher ist Christus, der HERR, in der Stadt Davids.<br>12 Und das habt zum Zeichen: ihr werdet finden das Kind in Windeln gewickelt und in einer Krippe liegen.<br>13 Und alsbald war da bei dem Engel die Menge der himmlischen Heerscharen, die lobten Gott und sprachen:<br>14 Ehre sei Gott in der H\u00f6he und Frieden auf Erden und den Menschen ein Wohlgefallen.<br>15 Und da die Engel von ihnen gen Himmel fuhren, sprachen die Hirten untereinander: La\u00dft uns nun gehen gen Bethlehem und die Geschichte sehen, die da geschehen ist, die uns der HERR kundgetan hat.<br>16 Und sie kamen eilend und fanden beide, Maria und Joseph, dazu das Kind in der Krippe liegen.<br>17 Da sie es aber gesehen hatten, breiteten sie das Wort aus, welches zu ihnen von diesem Kinde gesagt war.<br>18 Und alle, vor die es kam, wunderten sich der Rede, die ihnen die Hirten gesagt hatten.<br>19 Maria aber behielt alle diese Worte und bewegte sie in ihrem Herzen.<br>20 Und die Hirten kehrten wieder um, priesen und lobten Gott um alles, was sie geh\u00f6rt und gesehen hatten, wie denn zu ihnen gesagt war.<br>21 Und da acht Tage um waren, da\u00df das Kind beschnitten w\u00fcrde, da ward sein Name genannt Jesus, welcher genannt war von dem Engel, ehe denn er in Mutterleibe empfangen ward.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Johannes 1,4-5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4 In ihm war das Leben, und das Leben war das Licht der Menschen.<br>5 Und das Licht scheint in der Finsternis, und die Finsternis hat&#8217;s nicht begriffen.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Zusammenfassung von Ingrid Schwester:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Heute haben wir die Texte mehrerer Evangelisten betrachtet, um die gesamte Geschichte \u00fcber die Geburt von Jesus Christus in Bethlehem, Jud\u00e4a, zu erfassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zuerst erschien der Engel Gabriel Maria und k\u00fcndigte ihr an, dass sie schwanger werden und der Messias von ihr geboren werden w\u00fcrde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden wir ein sehr wichtiges Detail, das wir bereits im Johannesevangelium gelesen haben: Jesus Christus begann nicht erst zu existieren, als der Heilige Geist \u00fcber Maria kam und die Kraft des H\u00f6chsten sie \u00fcberschattete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben gelernt, dass Jesus Christus keinen Anfang hat, und sowohl im Johannesevangelium als auch im Brief des Paulus erfahren wir, dass Jesus bereits bei der Erschaffung der Erde anwesend war. Als er auf die Erde kam, nahm er menschliche Gestalt an. Johannes macht in seinem Brief deutlich, dass jeder, der nicht bekennt, dass Jesus Christus im Fleisch gekommen ist, ein Verf\u00fchrer und der Antichrist ist \u2013 der Feind Gottes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn wir uns also auf der Erde umsehen:<br>Wir sehen den Stall, Maria und Josef und das kleine Jesuskind in der Krippe. Aber wenn wir nicht bekennen, dass dieses kleine Kind vom Himmel gekommen ist, sind wir Verf\u00fchrer und keine Kinder Gottes. Heute reduzieren viele Menschen Weihnachten auf den Weihnachtsmann, der absolut nichts mit Weihnachten zu tun hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maria stimmte dem Engel zu, dass sie die Mutter des Messias werden w\u00fcrde, ohne zu fragen, was mit ihr geschehen w\u00fcrde, wenn ihr Verlobter herausfindet, dass sie schwanger war. Sie \u00fcberlie\u00df alle Sorgen und Fragen Gott, der immer einen perfekten Plan hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gehen wir weiter mit der Geschichte im Matth\u00e4usevangelium: W\u00e4hrend Josef dar\u00fcber nachdachte, Maria heimlich zu verlassen, sandte Gott einen Engel, der ihm im Traum sagte, dass er Maria zu sich nehmen und mit ihr zusammenleben solle. Also heirateten sie, aber Josef r\u00fchrte sie nicht an, bis Jesus geboren wurde. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach der Geburt Jesu f\u00fchrten sie eine normale Ehe mit weiteren Kindern, nicht nur Jesus. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Interessante an diesem Teil der Geschichte ist, dass Gott die Anweisungen Josef gab, nicht Maria, was sie tun sollten und was geschehen w\u00fcrde. In einem Haushalt ist immer der Mann \u2013 der Ehemann \u2013 die Hauptverantwortliche Person, und deshalb sprach Gott mit Josef, was er mit Maria tun und sp\u00e4ter, dass sie nach \u00c4gypten fliehen sollten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir kehren zum Lukasevangelium zur\u00fcck, wo wir mehr \u00fcber die Nacht erfahren, in der Jesus geboren wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In den alten Prophezeiungen war geschrieben, dass der Messias in Bethlehem geboren werden sollte. Josef und Maria kamen aus Nazareth in Galil\u00e4a, aber genau zu der Zeit, als der Messias geboren werden sollte, fand in Bethlehem eine Volksz\u00e4hlung statt. Dorthin mussten Josef und Maria reisen, um sich registrieren zu lassen, da sie Nachkommen von K\u00f6nig David waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gab keinen Platz in der Herberge, also musste Maria in einem Stall geb\u00e4ren, und Jesus wurde in eine Krippe gelegt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zun\u00e4chst zeigt dies, wie sehr Gott sich selbst erniedrigte, und zweitens war Jesus das Lamm Gottes. So befand er sich in einem Stall, als die anderen Schafe hinausgef\u00fchrt worden waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Schafe waren mit ihren Hirten auf dem Feld, und als die Engel die Geburt des Messias mit den Worten verk\u00fcndeten: \u201eEhre sei Gott in der H\u00f6he und Frieden auf Erden bei den Menschen seines Wohlgefallens!\u201c, kamen sie zum Stall, um zu sehen, was geschehen war. Sie sahen die kleine Familie und den Messias in der Krippe und kehrten zur\u00fcck, indem sie Gott f\u00fcr das, was geschehen war, verherrlichten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun liegt es an uns: Werden wir diesen Messias als unseren pers\u00f6nlichen Retter annehmen, ein Kind Gottes werden und im Licht leben, auch wenn wir hier auf Erden niemals vollkommen sein werden? Oder werden wir in der Dunkelheit bleiben und dem neugeborenen Jesus den R\u00fccken kehren, der 30 Jahre sp\u00e4ter f\u00fcr uns am Kreuz gestorben ist, um als Gottes Lamm die S\u00fcnden der Welt wegzunehmen?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fragen zur Weihnachtsgeschichte: Basierend auf den Weihnachtsartikeln zur Geburt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Okay, basierend auf dem obigen Bibelstudium m\u00f6chte ich Schwester einige dazugeh\u00f6rige Fragen stellen. Wir hoffen, dass die folgenden Fragen unseren Br\u00fcdern und Schwestern, die gerade Christen geworden sind, hilfreich sein k\u00f6nnen.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Wer k\u00fcndigte Maria die Geburt von Jesus an, und wie reagierte Maria?<\/strong><br>Der Engel Gabriel k\u00fcndigte Maria die Geburt von Jesus an, und Maria sagte sinngem\u00e4\u00df: \u201eGott, ich bin deine Dienerin. Tu mit mir, wie du m\u00f6chtest.\u201c<\/li>\n\n\n\n<li><strong>Wie wurde Maria zur Mutter von Jesus gew\u00e4hlt? Warum wurde sie und keine andere Frau ausgew\u00e4hlt?<\/strong><br>Es war wichtig, dass Maria eine Nachfahrin von K\u00f6nig David war, ebenso wie ihr Verlobter Josef.<br>Gott hatte K\u00f6nig David im Alten Testament versprochen, dass sein Thron f\u00fcr immer bestehen w\u00fcrde.<br>Nat\u00fcrlich endete sein irdischer Thron mit der Zerst\u00f6rung des Tempels von Salomo und der babylonischen Gefangenschaft. Aber wenn Gott etwas verspricht, erf\u00fcllt er es. Da es keinen irdischen Thron von K\u00f6nig David mehr gab, wird Jesus, der Messias und Nachfahre Davids, f\u00fcr immer auf dem himmlischen Thron sitzen.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiteres Detail: Gott sagte zu einem K\u00f6nig aus Davids Linie, dass dessen Nachkommen nie mehr auf Davids Thron sitzen w\u00fcrden. Doch Gott ist allm\u00e4chtig: Josef erhielt Davids Blutlinie nicht direkt, sondern durch Maria, die eine direkte Nachfahrin von David war.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um dies zu beweisen, schrieben die Evangelisten Matth\u00e4us und Lukas den Stammbaum von Maria und Josef nieder. Das Matth\u00e4usevangelium, das f\u00fcr die Juden geschrieben wurde, f\u00fchrt den Stammbaum von Abraham bis zu Maria auf.<br>Das Lukasevangelium, das f\u00fcr die Heiden geschrieben wurde, f\u00fchrt den Stammbaum von Josef bis zu Adam auf.<br>Das Paar Josef und Maria entsprach genau den Voraussetzungen, die die Propheten vorausgesagt hatten, und so wurde Maria zur Mutter von Jesus.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Was sagte der Engel Josef im Traum \u00fcber Maria und ihr Kind?<\/strong><br>Josef fragte sich, warum seine Verlobte schwanger war. Es war offensichtlich, dass er dachte, Maria sei untreu gewesen, und er plante, sich heimlich von ihr zu trennen. Deshalb sprach der Engel zu ihm im Traum und erkl\u00e4rte ihm, was geschehen war.<\/li>\n\n\n\n<li><strong>Welchen Namen sollten Maria und Josef ihrem Kind geben, und was bedeutet dieser Name?<\/strong><br>Sie sollten das Kind Jesus nennen, weil er sein Volk von ihren S\u00fcnden retten w\u00fcrde. Ein weiterer Name f\u00fcr Jesus ist Immanuel, was bedeutet: \u201eGott ist mit uns.\u201c<\/li>\n\n\n\n<li><strong>Warum reisten Josef und Maria vor Jesu Geburt nach Bethlehem?<\/strong><br>Zu jener Zeit erlie\u00df Kaiser Augustus, der Herrscher des R\u00f6mischen Reiches, ein Dekret. Alle Menschen mussten sich in ihrer Heimatstadt registrieren lassen. Maria und Josef lebten in Nazareth in Galil\u00e4a, aber ihre Stadt war Bethlehem, die Stadt Davids, da sie Nachkommen Davids waren. Dort mussten sie sich eintragen lassen.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Wieder sehen wir hier ein scheinbar zuf\u00e4lliges Ereignis, das jedoch Teil von Gottes gr\u00f6\u00dferem Plan war. Der Messias wurde vorhergesagt, in Bethlehem geboren zu werden, aber er sollte auch ein Nazarener genannt werden. Alles, was Gott tut, ist bis ins Detail geplant.<\/p>\n\n\n\n<ol start=\"6\" class=\"wp-block-list\">\n<li><strong>Wo wurde Jesus geboren, und warum wurde er in eine Krippe gelegt?<\/strong><br>Jesus wurde in Bethlehem geboren. Es gab keinen Platz in der Herberge, also mussten Maria und Josef die Nacht in einem Stall verbringen, und das Baby wurde in eine Krippe gelegt.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Aber das hat eine tiefere Bedeutung: Da Jesus das Lamm ist, das die S\u00fcnde der Welt wegnimmt, wurde er an einen Ort gelegt, wo sonst Tiere sind. Zudem zeigt dies, wie sehr Gott sich erniedrigte, indem er sich mit einer Krippe als Bett zufrieden gab.<\/p>\n\n\n\n<ol start=\"7\" class=\"wp-block-list\">\n<li><strong>Wie erfuhren die Hirten von der Geburt Jesu, und wie reagierten sie?<\/strong><br>Engel erschienen den Hirten auf dem Feld, wo sie ihre Schafe h\u00fcteten. Sie sagten: \u201eLasst uns nach Bethlehem gehen und sehen, was geschehen ist.\u201c<\/li>\n\n\n\n<li><strong>Welche Bedeutung hatte die Verk\u00fcndigung der Engel an die Hirten?<\/strong><br>Zum Zeitpunkt von Jesu Geburt hatte die Menschheit keinen Frieden mit Gott, da die S\u00fcnde zwischen ihnen stand. Die Engel verk\u00fcndeten, dass der Messias gekommen ist, der Frieden zu allen bringen wird, die ihn als ihren Retter annehmen.<\/li>\n\n\n\n<li><strong>Was tat Maria, als sie alles h\u00f6rte, was die Hirten erz\u00e4hlten?<\/strong><br>Maria bewahrte diese Worte in ihrem Herzen.<\/li>\n\n\n\n<li><strong>Was sagt Johannes \u00fcber Jesus als das Licht der Welt, und warum dachte er so?<\/strong><br>Jesus ist das Leben und das Licht. Wenn wir zu Jesus kommen, kann die Dunkelheit ihn nicht \u00fcberw\u00e4ltigen.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">An dem Tag, als Jesus gekreuzigt wurde, schien es, als h\u00e4tte die Dunkelheit gesiegt. Doch die Wahrheit ist, dass Jesus auferstanden ist und die Dunkelheit \u00fcberwunden hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn wir mit Jesus im Licht leben, hat die Dunkelheit keine Macht \u00fcber uns. Oft denken Menschen, es sei ein Kampf zwischen Gott und dem Teufel. Aber nein, Gott ist allm\u00e4chtig und der Sch\u00f6pfer von allem. Der Teufel ist ebenfalls ein Gesch\u00f6pf, und auch wenn er klug ist, hat er nicht dieselbe Macht wie Gott.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Entscheidung liegt bei uns: Gehen wir im Licht und sind in Christus sicher, oder bleiben wir in der Dunkelheit und landen am Ende der Zeit mit dem Teufel und seinen Engeln in der H\u00f6lle?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das wird der einsamste Ort im Universum sein, denn Liebe, Gemeinschaft, Frieden \u2013 all die Dinge, die unsere Seele gl\u00fccklich machen \u2013 geh\u00f6ren zu Gott, dem Herrn Jesus und dem Heiligen Geist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich w\u00fcnsche allen Zuh\u00f6rern eine fr\u00f6hliche Weihnacht und hoffe, dass sie lernen, im Licht in der Gegenwart von Gott Vater, Jesus Christus und durch den Heiligen Geist zu leben, der uns an Jesu Worte erinnert.<\/p>\n","protected":false,"raw":"<!-- wp:audio {\"id\":1496} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/loveforasia.org\/wp-content\/uploads\/2024\/12\/Der_Kaiser_als_Schachfigur_Gottes.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\n\n<!-- wp:paragraph -->\n<p>26 Und im sechsten Monat ward der Engel Gabriel gesandt von Gott in eine Stadt in Galil\u00e4a, die hei\u00dft Nazareth,<br>27 zu einer Jungfrau, die vertraut war einem Manne mit Namen Joseph, vom Hause David: und die Jungfrau hie\u00df Maria.<br>28 Und der Engel kam zu ihr hinein und sprach: Gegr\u00fc\u00dfet seist du, Holdselige! Der HERR ist mit dir, du Gebenedeite unter den Weibern!<br>29 Da sie aber ihn sah, erschrak sie \u00fcber seine Rede und gedachte: Welch ein Gru\u00df ist das?<br>30 Und der Engel sprach zu ihr: F\u00fcrchte dich nicht, Maria! du hast Gnade bei Gott gefunden.<br>31 Siehe, du wirst schwanger werden und einen Sohn geb\u00e4ren, des Namen sollst du Jesus hei\u00dfen.<br>32 Der wird gro\u00df sein und ein Sohn des H\u00f6chsten genannt werden; und Gott der HERR wird ihm den Stuhl seines Vaters David geben;<br>33 und er wird ein K\u00f6nig sein \u00fcber das Haus Jakob ewiglich, und seines K\u00f6nigreiches wird kein Ende sein.<br>34 Da sprach Maria zu dem Engel: Wie soll das zugehen, da ich von keinem Manne wei\u00df?<br>35 Der Engel antwortete und sprach zu ihr: Der heilige Geist wird \u00fcber dich kommen, und die Kraft des H\u00f6chsten wird dich \u00fcberschatten; darum wird auch das Heilige, das von dir geboren wird, Gottes Sohn genannt werden.<br>36 Und siehe, Elisabeth, deine Gefreunde, ist auch schwanger mit einem Sohn in ihrem Alter und geht jetzt im sechsten Monat, von der man sagt, da\u00df sie unfruchtbar sei.<br>37 Denn bei Gott ist kein Ding unm\u00f6glich.<br>38 Maria aber sprach: Siehe ich bin des HERRN Magd; mir geschehe, wie du gesagt hast. Und der Engel schied von ihr.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>18 Die Geburt Christi war aber also getan. Als Maria, seine Mutter, dem Joseph vertraut war, fand sich's ehe er sie heimholte, da\u00df sie schwanger war von dem heiligen Geist.<br>19 Joseph aber, ihr Mann, war fromm und wollte sie nicht in Schande bringen, gedachte aber, sie heimlich zu verlassen.<br>20 Indem er aber also gedachte, siehe, da erschien ihm ein Engel des HERRN im Traum und sprach: Joseph, du Sohn Davids, f\u00fcrchte dich nicht, Maria, dein Gemahl, zu dir zu nehmen; denn das in ihr geboren ist, das ist von dem heiligen Geist.<br>21 Und sie wird einen Sohn geb\u00e4ren, des Namen sollst du Jesus hei\u00dfen; denn er wird sein Volk selig machen von ihren S\u00fcnden.<br>22 Das ist aber alles geschehen, auf da\u00df erf\u00fcllt w\u00fcrde, was der HERR durch den Propheten gesagt hat, der da spricht:<br>23 \"Siehe, eine Jungfrau wird schwanger sein und einen Sohn geb\u00e4ren, und sie werden seinen Namen Immanuel hei\u00dfen\", das ist verdolmetscht: Gott mit uns.<br>24 Da nun Joseph vom Schlaf erwachte, tat er, wie ihm des HERRN Engel befohlen hatte, und nahm sein Gemahl zu sich.<br>25 Und er erkannte sie nicht, bis sie ihren ersten Sohn gebar; und hie\u00df seinen Namen Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lukas 2,1-21<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1 Es begab sich aber zu der Zeit, da\u00df ein Gebot von dem Kaiser Augustus ausging, da\u00df alle Welt gesch\u00e4tzt w\u00fcrde.<br>2 Und diese Sch\u00e4tzung war die allererste und geschah zu der Zeit, da Cyrenius Landpfleger von Syrien war.<br>3 Und jedermann ging, da\u00df er sich sch\u00e4tzen lie\u00dfe, ein jeglicher in seine Stadt.<br>4 Da machte sich auch auf Joseph aus Galil\u00e4a, aus der Stadt Nazareth, in das j\u00fcdische Land zur Stadt Davids, die da hei\u00dft Bethlehem, darum da\u00df er von dem Hause und Geschlechte Davids war,<br>5 auf da\u00df er sich sch\u00e4tzen lie\u00dfe mit Maria, seinem vertrauten Weibe, die ward schwanger.<br>6 Und als sie daselbst waren, kam die Zeit, da sie geb\u00e4ren sollte.<br>7 Und sie gebar ihren ersten Sohn und wickelte ihn in Windeln und legte ihn in eine Krippe; denn sie hatten sonst keinen Raum in der Herberge.<br>8 Und es waren Hirten in derselben Gegend auf dem Felde bei den H\u00fcrden, die h\u00fcteten des Nachts ihre Herde.<br>9 Und siehe, des HERRN Engel trat zu ihnen, und die Klarheit des HERRN leuchtete um sie; und sie f\u00fcrchteten sich sehr.<br>10 Und der Engel sprach zu ihnen: F\u00fcrchtet euch nicht! siehe, ich verk\u00fcndige euch gro\u00dfe Freude, die allem Volk widerfahren wird;<br>11 denn euch ist heute der Heiland geboren, welcher ist Christus, der HERR, in der Stadt Davids.<br>12 Und das habt zum Zeichen: ihr werdet finden das Kind in Windeln gewickelt und in einer Krippe liegen.<br>13 Und alsbald war da bei dem Engel die Menge der himmlischen Heerscharen, die lobten Gott und sprachen:<br>14 Ehre sei Gott in der H\u00f6he und Frieden auf Erden und den Menschen ein Wohlgefallen.<br>15 Und da die Engel von ihnen gen Himmel fuhren, sprachen die Hirten untereinander: La\u00dft uns nun gehen gen Bethlehem und die Geschichte sehen, die da geschehen ist, die uns der HERR kundgetan hat.<br>16 Und sie kamen eilend und fanden beide, Maria und Joseph, dazu das Kind in der Krippe liegen.<br>17 Da sie es aber gesehen hatten, breiteten sie das Wort aus, welches zu ihnen von diesem Kinde gesagt war.<br>18 Und alle, vor die es kam, wunderten sich der Rede, die ihnen die Hirten gesagt hatten.<br>19 Maria aber behielt alle diese Worte und bewegte sie in ihrem Herzen.<br>20 Und die Hirten kehrten wieder um, priesen und lobten Gott um alles, was sie geh\u00f6rt und gesehen hatten, wie denn zu ihnen gesagt war.<br>21 Und da acht Tage um waren, da\u00df das Kind beschnitten w\u00fcrde, da ward sein Name genannt Jesus, welcher genannt war von dem Engel, ehe denn er in Mutterleibe empfangen ward.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Johannes 1,4-5<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>4 In ihm war das Leben, und das Leben war das Licht der Menschen.<br>5 Und das Licht scheint in der Finsternis, und die Finsternis hat's nicht begriffen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":2} -->\n<ol start=\"2\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Zusammenfassung von Ingrid Schwester:<\/strong><\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Heute haben wir die Texte mehrerer Evangelisten betrachtet, um die gesamte Geschichte \u00fcber die Geburt von Jesus Christus in Bethlehem, Jud\u00e4a, zu erfassen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Zuerst erschien der Engel Gabriel Maria und k\u00fcndigte ihr an, dass sie schwanger werden und der Messias von ihr geboren werden w\u00fcrde.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hier finden wir ein sehr wichtiges Detail, das wir bereits im Johannesevangelium gelesen haben: Jesus Christus begann nicht erst zu existieren, als der Heilige Geist \u00fcber Maria kam und die Kraft des H\u00f6chsten sie \u00fcberschattete.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wir haben gelernt, dass Jesus Christus keinen Anfang hat, und sowohl im Johannesevangelium als auch im Brief des Paulus erfahren wir, dass Jesus bereits bei der Erschaffung der Erde anwesend war. Als er auf die Erde kam, nahm er menschliche Gestalt an. Johannes macht in seinem Brief deutlich, dass jeder, der nicht bekennt, dass Jesus Christus im Fleisch gekommen ist, ein Verf\u00fchrer und der Antichrist ist \u2013 der Feind Gottes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wenn wir uns also auf der Erde umsehen:<br>Wir sehen den Stall, Maria und Josef und das kleine Jesuskind in der Krippe. Aber wenn wir nicht bekennen, dass dieses kleine Kind vom Himmel gekommen ist, sind wir Verf\u00fchrer und keine Kinder Gottes. Heute reduzieren viele Menschen Weihnachten auf den Weihnachtsmann, der absolut nichts mit Weihnachten zu tun hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Maria stimmte dem Engel zu, dass sie die Mutter des Messias werden w\u00fcrde, ohne zu fragen, was mit ihr geschehen w\u00fcrde, wenn ihr Verlobter herausfindet, dass sie schwanger war. Sie \u00fcberlie\u00df alle Sorgen und Fragen Gott, der immer einen perfekten Plan hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Gehen wir weiter mit der Geschichte im Matth\u00e4usevangelium: W\u00e4hrend Josef dar\u00fcber nachdachte, Maria heimlich zu verlassen, sandte Gott einen Engel, der ihm im Traum sagte, dass er Maria zu sich nehmen und mit ihr zusammenleben solle. Also heirateten sie, aber Josef r\u00fchrte sie nicht an, bis Jesus geboren wurde. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nach der Geburt Jesu f\u00fchrten sie eine normale Ehe mit weiteren Kindern, nicht nur Jesus. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Das Interessante an diesem Teil der Geschichte ist, dass Gott die Anweisungen Josef gab, nicht Maria, was sie tun sollten und was geschehen w\u00fcrde. In einem Haushalt ist immer der Mann \u2013 der Ehemann \u2013 die Hauptverantwortliche Person, und deshalb sprach Gott mit Josef, was er mit Maria tun und sp\u00e4ter, dass sie nach \u00c4gypten fliehen sollten.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wir kehren zum Lukasevangelium zur\u00fcck, wo wir mehr \u00fcber die Nacht erfahren, in der Jesus geboren wurde.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In den alten Prophezeiungen war geschrieben, dass der Messias in Bethlehem geboren werden sollte. Josef und Maria kamen aus Nazareth in Galil\u00e4a, aber genau zu der Zeit, als der Messias geboren werden sollte, fand in Bethlehem eine Volksz\u00e4hlung statt. Dorthin mussten Josef und Maria reisen, um sich registrieren zu lassen, da sie Nachkommen von K\u00f6nig David waren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es gab keinen Platz in der Herberge, also musste Maria in einem Stall geb\u00e4ren, und Jesus wurde in eine Krippe gelegt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Zun\u00e4chst zeigt dies, wie sehr Gott sich selbst erniedrigte, und zweitens war Jesus das Lamm Gottes. So befand er sich in einem Stall, als die anderen Schafe hinausgef\u00fchrt worden waren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Die Schafe waren mit ihren Hirten auf dem Feld, und als die Engel die Geburt des Messias mit den Worten verk\u00fcndeten: \u201eEhre sei Gott in der H\u00f6he und Frieden auf Erden bei den Menschen seines Wohlgefallens!\u201c, kamen sie zum Stall, um zu sehen, was geschehen war. Sie sahen die kleine Familie und den Messias in der Krippe und kehrten zur\u00fcck, indem sie Gott f\u00fcr das, was geschehen war, verherrlichten.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nun liegt es an uns: Werden wir diesen Messias als unseren pers\u00f6nlichen Retter annehmen, ein Kind Gottes werden und im Licht leben, auch wenn wir hier auf Erden niemals vollkommen sein werden? Oder werden wir in der Dunkelheit bleiben und dem neugeborenen Jesus den R\u00fccken kehren, der 30 Jahre sp\u00e4ter f\u00fcr uns am Kreuz gestorben ist, um als Gottes Lamm die S\u00fcnden der Welt wegzunehmen?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Fragen zur Weihnachtsgeschichte: Basierend auf den Weihnachtsartikeln zur Geburt<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Okay, basierend auf dem obigen Bibelstudium m\u00f6chte ich Schwester einige dazugeh\u00f6rige Fragen stellen. Wir hoffen, dass die folgenden Fragen unseren Br\u00fcdern und Schwestern, die gerade Christen geworden sind, hilfreich sein k\u00f6nnen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Wer k\u00fcndigte Maria die Geburt von Jesus an, und wie reagierte Maria?<\/strong><br>Der Engel Gabriel k\u00fcndigte Maria die Geburt von Jesus an, und Maria sagte sinngem\u00e4\u00df: \u201eGott, ich bin deine Dienerin. Tu mit mir, wie du m\u00f6chtest.\u201c<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Wie wurde Maria zur Mutter von Jesus gew\u00e4hlt? Warum wurde sie und keine andere Frau ausgew\u00e4hlt?<\/strong><br>Es war wichtig, dass Maria eine Nachfahrin von K\u00f6nig David war, ebenso wie ihr Verlobter Josef.<br>Gott hatte K\u00f6nig David im Alten Testament versprochen, dass sein Thron f\u00fcr immer bestehen w\u00fcrde.<br>Nat\u00fcrlich endete sein irdischer Thron mit der Zerst\u00f6rung des Tempels von Salomo und der babylonischen Gefangenschaft. Aber wenn Gott etwas verspricht, erf\u00fcllt er es. Da es keinen irdischen Thron von K\u00f6nig David mehr gab, wird Jesus, der Messias und Nachfahre Davids, f\u00fcr immer auf dem himmlischen Thron sitzen.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Ein weiteres Detail: Gott sagte zu einem K\u00f6nig aus Davids Linie, dass dessen Nachkommen nie mehr auf Davids Thron sitzen w\u00fcrden. Doch Gott ist allm\u00e4chtig: Josef erhielt Davids Blutlinie nicht direkt, sondern durch Maria, die eine direkte Nachfahrin von David war.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Um dies zu beweisen, schrieben die Evangelisten Matth\u00e4us und Lukas den Stammbaum von Maria und Josef nieder. Das Matth\u00e4usevangelium, das f\u00fcr die Juden geschrieben wurde, f\u00fchrt den Stammbaum von Abraham bis zu Maria auf.<br>Das Lukasevangelium, das f\u00fcr die Heiden geschrieben wurde, f\u00fchrt den Stammbaum von Josef bis zu Adam auf.<br>Das Paar Josef und Maria entsprach genau den Voraussetzungen, die die Propheten vorausgesagt hatten, und so wurde Maria zur Mutter von Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":3} -->\n<ol start=\"3\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Was sagte der Engel Josef im Traum \u00fcber Maria und ihr Kind?<\/strong><br>Josef fragte sich, warum seine Verlobte schwanger war. Es war offensichtlich, dass er dachte, Maria sei untreu gewesen, und er plante, sich heimlich von ihr zu trennen. Deshalb sprach der Engel zu ihm im Traum und erkl\u00e4rte ihm, was geschehen war.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Welchen Namen sollten Maria und Josef ihrem Kind geben, und was bedeutet dieser Name?<\/strong><br>Sie sollten das Kind Jesus nennen, weil er sein Volk von ihren S\u00fcnden retten w\u00fcrde. Ein weiterer Name f\u00fcr Jesus ist Immanuel, was bedeutet: \u201eGott ist mit uns.\u201c<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Warum reisten Josef und Maria vor Jesu Geburt nach Bethlehem?<\/strong><br>Zu jener Zeit erlie\u00df Kaiser Augustus, der Herrscher des R\u00f6mischen Reiches, ein Dekret. Alle Menschen mussten sich in ihrer Heimatstadt registrieren lassen. Maria und Josef lebten in Nazareth in Galil\u00e4a, aber ihre Stadt war Bethlehem, die Stadt Davids, da sie Nachkommen Davids waren. Dort mussten sie sich eintragen lassen.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Wieder sehen wir hier ein scheinbar zuf\u00e4lliges Ereignis, das jedoch Teil von Gottes gr\u00f6\u00dferem Plan war. Der Messias wurde vorhergesagt, in Bethlehem geboren zu werden, aber er sollte auch ein Nazarener genannt werden. Alles, was Gott tut, ist bis ins Detail geplant.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":6} -->\n<ol start=\"6\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Wo wurde Jesus geboren, und warum wurde er in eine Krippe gelegt?<\/strong><br>Jesus wurde in Bethlehem geboren. Es gab keinen Platz in der Herberge, also mussten Maria und Josef die Nacht in einem Stall verbringen, und das Baby wurde in eine Krippe gelegt.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Aber das hat eine tiefere Bedeutung: Da Jesus das Lamm ist, das die S\u00fcnde der Welt wegnimmt, wurde er an einen Ort gelegt, wo sonst Tiere sind. Zudem zeigt dies, wie sehr Gott sich erniedrigte, indem er sich mit einer Krippe als Bett zufrieden gab.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":7} -->\n<ol start=\"7\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Wie erfuhren die Hirten von der Geburt Jesu, und wie reagierten sie?<\/strong><br>Engel erschienen den Hirten auf dem Feld, wo sie ihre Schafe h\u00fcteten. Sie sagten: \u201eLasst uns nach Bethlehem gehen und sehen, was geschehen ist.\u201c<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Welche Bedeutung hatte die Verk\u00fcndigung der Engel an die Hirten?<\/strong><br>Zum Zeitpunkt von Jesu Geburt hatte die Menschheit keinen Frieden mit Gott, da die S\u00fcnde zwischen ihnen stand. Die Engel verk\u00fcndeten, dass der Messias gekommen ist, der Frieden zu allen bringen wird, die ihn als ihren Retter annehmen.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Was tat Maria, als sie alles h\u00f6rte, was die Hirten erz\u00e4hlten?<\/strong><br>Maria bewahrte diese Worte in ihrem Herzen.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Was sagt Johannes \u00fcber Jesus als das Licht der Welt, und warum dachte er so?<\/strong><br>Jesus ist das Leben und das Licht. Wenn wir zu Jesus kommen, kann die Dunkelheit ihn nicht \u00fcberw\u00e4ltigen.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>An dem Tag, als Jesus gekreuzigt wurde, schien es, als h\u00e4tte die Dunkelheit gesiegt. Doch die Wahrheit ist, dass Jesus auferstanden ist und die Dunkelheit \u00fcberwunden hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wenn wir mit Jesus im Licht leben, hat die Dunkelheit keine Macht \u00fcber uns. Oft denken Menschen, es sei ein Kampf zwischen Gott und dem Teufel. Aber nein, Gott ist allm\u00e4chtig und der Sch\u00f6pfer von allem. Der Teufel ist ebenfalls ein Gesch\u00f6pf, und auch wenn er klug ist, hat er nicht dieselbe Macht wie Gott.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Die Entscheidung liegt bei uns: Gehen wir im Licht und sind in Christus sicher, oder bleiben wir in der Dunkelheit und landen am Ende der Zeit mit dem Teufel und seinen Engeln in der H\u00f6lle?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Das wird der einsamste Ort im Universum sein, denn Liebe, Gemeinschaft, Frieden \u2013 all die Dinge, die unsere Seele gl\u00fccklich machen \u2013 geh\u00f6ren zu Gott, dem Herrn Jesus und dem Heiligen Geist.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ich w\u00fcnsche allen Zuh\u00f6rern eine fr\u00f6hliche Weihnacht und hoffe, dass sie lernen, im Licht in der Gegenwart von Gott Vater, Jesus Christus und durch den Heiligen Geist zu leben, der uns an Jesu Worte erinnert.<\/p>\n<!-- \/wp:paragraph -->"},"excerpt":{"rendered":"","protected":false,"raw":""},"author":1,"featured_media":959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_en_post_content":"<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"964\"} \/-->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Birth of Jesus Foretold<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Luke 1,26-38<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><br>26 In the sixth month the angel Gabriel was sent from God to a city of Galilee named Nazareth,\u200227 to a virgin betrothed to a man whose name was Joseph, of the house of David. And the virgin\u2019s name was Mary.\u200228 And he came to her and said, \u201cGreetings, O favored one, the Lord is with you!\u201d<br>29 But she was greatly troubled at the saying, and tried to discern what sort of greeting this might be.\u200230 And the angel said to her, \u201cDo not be afraid, Mary, for you have found favor with God.\u200231 And behold, you will conceive in your womb and bear a son, and you shall call his name Jesus.\u2002<br>32 He will be great and will be called the Son of the Highest. And the Lord God will give to him the throne of his father David,\u200233 and he will reign over the house of Jacob forever, and of his kingdom there will be no end.\u201d\u200234 And Mary said to the angel, \u201cHow will this be, since I am a virgin?\u201d35 And the angel answered her, \u201cThe Holy Spirit will come upon you, and the power of the Most High will overshadow you; therefore the child to be born[5] will be called holy\u2014the Son of God.\u200236 And behold, your relative Elizabeth in her old age has also conceived a son, and this is the sixth month with her who was called barren.\u200237 For nothing will be impossible with God.\u201d\u200238 And Mary said, \u201cBehold, I am the servant of the Lord; let it be to me according to your word.\u201d And the angel departed from her.\u2002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><br><br>The Birth of Jesus Christ<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Matthew 1,18-25<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><br>18 Now the birth of Jesus Christ took place in this way. When his mother Mary had been betrothed to Joseph, before they came together, she was found to be with child from the Holy Spirit.\u2002<br>19 And her husband Joseph, being a just man and unwilling to put her to shame, resolved to divorce her quietly.\u2002<br>20 But as he considered these things, behold, an angel of the Lord appeared to him in a dream, saying, \u201cJoseph, son of David, do not fear to take Mary as your wife, for that which is conceived in her is from the Holy Spirit.\u200221 She will bear a son, and you shall call his name Jesus, for he will save his people from their sins.\u201d\u200222 All this took place to fulfill what the Lord had spoken by the prophet:\u200223 \u201cBehold, the virgin shall conceive and bear a son, and they shall call his name Immanuel\u201d (which means, God with us).\u200224 When Joseph woke from sleep, he did as the angel of the Lord commanded him: he took his wife,\u200225 but knew her not until she had given birth to a son. And he called his name Jesus.\u2002<br><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><br>The Birth of Jesus Christ<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Luke 2,1-21<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>1 In those days a decree went out from Caesar Augustus that all the world should be registered.\u20022 This was the first registration when Quirinius was governor of Syria.\u2002<br>3 And all went to be registered, each to his own town.\u2002<br>4 And Joseph also went up from Galilee, from the town of Nazareth, to Judea, to the city of David, which is called Bethlehem, because he was of the house and lineage of David,\u20025 to be registered with Mary, his betrothed, who was with child.\u2002<br>6 And while they were there, the time came for her to give birth.\u2002<br>7 And she gave birth to her firstborn son and wrapped him in swaddling clothes and laid him in a manger, because there was no place for them in the inn.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><br>The Shepherds and the Angels<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><br>8 And in the same region there were shepherds out in the field, keeping watch over their flock by night.\u20029 And an angel of the Lord appeared to them, and the glory of the Lord shone around them, and they were filled with great fear.\u200210 And the angel said to them, \u201cFear not, for behold, I bring you good news of great joy that will be for all the people.\u200211 For unto you is born this day in the city of David a Savior, who is Christ the Lord.\u200212 And this will be a sign for you: you will find a baby wrapped in swaddling clothes and lying in a manger.\u201d\u200213 And suddenly there was with the angel a multitude of the heavenly host praising God and saying,\u200214 \u201cGlory to God in the highest, and on earth peace among those with whom he is pleased!\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>15 When the angels went away from them into heaven, the shepherds said to one another, \u201cLet us go over to Bethlehem and see this thing that has happened, which the Lord has made known to us.\u201d\u200216 And they went with haste and found Mary and Joseph, and the baby lying in a manger.\u200217 And when they saw it, they made known the saying that had been told them concerning this child.\u200218 And all who heard it wondered at what the shepherds told them.\u200219 But Mary treasured up all these things, pondering them in her heart.\u200220 And the shepherds returned, glorifying and praising God for all they had heard and seen, as it had been told them.\u200221 And at the end of eight days, when he was circumcised, he was called Jesus, the name given by the angel before he was conceived in the womb.\u2002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><br>John 1,4-5<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><br>4 In him was life, and the life was the light of men.\u20025 The light shines in the darkness, and the darkness has not overcome it.\u2002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hello everyone, I am the host Kiki.<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><br>Today is the 2024 Christmas special program. I wish all listeners peace and joy in 2025.<br>Now let's talk about the birth of Jesus.<br>Slightly different from the previous program, the following is Ingrid sister\u2019s explanation of this important historical moment of the birth of Jesus, and then following is my interview with sister Ingrid on related issues.<br>Everyone is welcome to leave a message in the comment area for discussion!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Summary of Ingrid Sister:<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Today we have looked on the text of several evangelists for to get the whole story about the birth of Jesus Christ in Bethlehem, Jud\u00e4a.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>First, the angel Gabriel came to Maria and announced her, that she will become pregnant and the Messiah will be born of her<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Here we have a very important detail, that we already read in the Gospel of John: Jesus Christ did not begin to exist, when the Holy Spirit came over her and the Power of the Most High will overshaddow her.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>We learned, that Jesus Christ has no beginning and we learn both in the Gospel of John and in the Epistel of Paul, that Jesus was there when the earth was created. When he came down on earth, he was incarnated and John says it clearly in his epistel, everyone, who does not confess that Jesus Christ came in flesh is a deceiver and the Antichrist, who is the enemy of God. So when we look around on earth:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>We have the stable, we have Mary and Joseph and the little Jesus boy in the manger. But if we don t confess, that this little boy came from heaven, we are a deceiver and we are not a child of God. Well, today a lot of people reduce Christmas on Santa Claus, which has absolutely nothing to do with Christmas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Mary agreed with the angel, that she will be the mother of the Messias without asking, what will be with her, when her fiancee finds out, that she was pregnant. She overlefted all worries and questions to God who always has a perfect plan:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Let us go on with the story in the Gospel of Matthew: While Joseph considered to leave Mary in secret, God send an angel to talk to Joseph in a dream, that he should take Mary home and live with her. So they got married but Joseph did not touch her until Jesus was born. After the birth of Jesus, the had a normal marriage with more children, not only Jesus. The interessting in this part of the story was, that God gave the instruccion to Joseph, not to Mary, what they shall do and what will happen. In a household always the man is the husband is the most responsible and that is why God talked to Joseph, what he should do with Mary and later, that they shall flee to Eigypt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>We return to the Gospel of Luke, there we get more information about the night, when Jesus was born.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In the old profecies, it was written, that the Messias has to be born in Bethlehem. Joseph and Mary came from Nazareth in Galil\u00e4a , but just in the time, when the Messias was to be born, there was a sensus in Bethlehem, there Joseph and Mary had to go to be registrated, because they were desendents of king David.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>There was no space in the hostal, so she had to give birth in a stable and Jesus was layed in a mager.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>First of all, this show how much God humbled himself, second Jesus was the lamb of God, so he was there in a stable when the other sheep had gone out.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>The sheep were with their shepherds on the field and when the angels announced the birth of the Messias to them with the words \u201cGlory to God in the highest, and on earth peace among those with whom he is pleased!\u201d, they came to the stable for to see what happened. They saw the little family and the Messias in the manger and returned gloryfying God for what had happened.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>So it is up to us: Will we take this Messiah as our personal saviour and become a Child of God and live in the light even we never will be perfect here on earth or will we remain in the darkness and move our back to the newborn Jesus who has died 30 years later for us on the cross for to be God s lamb that washed away the sin of the world.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Q list part: base on Christmas Birth items:<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Okay. Base on above bible study content, now let me ask sister some related questions.<br>We hope the following questions can be helpful to our brothers and sisters who have just become Christians.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Who announced the birth of Jesus to Mary, and what was Mary\u2019s response?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>The angel Gabriel announced to Mary the birth of Jesus and Mary said in other words, God I am your servant, do with me like you would like to do.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">How was Mary chosen to be the mother of Jesus? Why chosen her no other women?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>It was important that she was a descendent of king David and her fianc\u00e9e is descendent of King David, too.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>To King David in the Old Testament was promised, that his throne will last forever.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Of course, his throne here on earth terminated, because the time of the kings of Juda in the Old Testament terminated with the destroying of the temple of Salomon and the exile in Babylonia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>But when God promises something, he fulfills it. So, when there was no throne of King David on earth, Jesus, the Messias as a descendent of King David will sit on the throne in heaven forever.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Another thing is, that God said to one king: You never will have more children on the throne of David and this was one of the kingly linages. But God is almighty: Joseph did not get the blood of David directly, he inherited from Mary, who was direct decedent of the throne of David.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>To proof all this, the evangelists Mattew and Luke wrote down the geological tree both from Mary and Joseph.<br>The Gospel of Matthew was written for the Jews, so we find the geological tree from Abraham to Mary.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>The gospel of Luke is dedicated to the gentile people, so we find in Luke 3 the geological tree from Joseph back to Adam.<br>So, the couple of Joseph and Mary matched exactly to the requisites that the prophets spoke before and so Mary became the mother of Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">What did the angel tell Joseph in his dream about Mary and her child?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Joseph thought why is his fianc\u00e9 pregnant? It is an obvious, that he thought, that Mary has been unfaithful and his plan was to leave Mary. That is why the Angel had to talk to him and to explain what happened.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">What name was Mary and Joseh instructed to give their child, and what does it mean?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>They were instructed to give the name Jesus, because he will save his people from sin. Another name for Jesus is Immanuel which means: God is with us.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Why did Joseh and Mary travel to Bethlehem before Jesus was born?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>In those days was a decree from Cesar August, the governor of the Roman empire. All people had to go to their own city. Mary and Joseph lived in Nazareth, in Galilea, but her city was Bethlehem, the city of David since they were descents of David. There they had to go for to enroll themselves.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>We see here again, an event, that occasional happened, but has a higher plan, because the Messiah was poeticized to be born in Betlehem, but be called the Nazarene. Everything that God does has been planned exactly with all details before.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Where was Jesus born, and why was he laid in a manger?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Jesus was born in Bethlehem. There was no place in the inn, so they had to spend the night in a stable and put the baby in a manger.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>But there is a higher meaning: Since Jesus is the lamb that takes away the sin of the world, he was put in a place, there animals were put. And of course, God humbles himself so much, that he agreed with a manger as his bed when he was born.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">How did the shepherds learn about Jesus\u2019 birth, and what was their reaction?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Angels appeared on the field; there they were pastoring their sheep. So, they said: Let us go and see what happened in Bethlehem.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">What was the significance of the angel's announcement to the shepherds?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>At the moment Jesus was born, mankind had no peace with God, because sin stood between them. The angels announced that the Messiah has come, that will bring peace to everyone who receives him as his savior.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">What did Mary do when she heard everything that the shepherds shared?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>She kept the words in her heart.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">What does John say about Jesus being the light of the world? And why he thought like that?<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Jesus is the life and the light. When we come to Jesus, the darkness cannot overcome him.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>On that day when Jesus was crucified, it seamed that the darkness had won, but the truth was, that Jesus arose again and has overcome the darkness.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>If we choose to live with Jesus in the light, the darkness has no power over us.<br>Often people think, that it is a fight between God and the devil. But no. God is almighty and the creator of all. The devil is a created being, too and even he is smart, he does not have such power as God.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>All is our decision: Are we walking in the light and be save in Christ or are we staying in the darkness and go at the end of time to hell with the devil and his angels.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>This will be the loneliest place we can meet in universe, because love and fellowship and peace, all those things, that make our soul happy belong to God, the Lord Jesus and the Holy Spirit.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I wish all our listeners a merrily Christmas and that they learn to live in the light in the presence of God father, Jesus Christ through the Holy Spirit who remains us on Jesus words.<\/p>\n<!-- \/wp:paragraph -->","_en_post_name":"christmas-special","_en_post_excerpt":"","_en_post_title":"Christmas Special 2024","_zh_post_content":"<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"964\"} \/-->\n\n<!-- wp:paragraph -->\n<p>Luke 1,26-38<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>26 \u5230 \u4e86 \u7b2c \u516d \u4e2a \u6708 \uff0c \u5929 \u4f7f \u52a0 \u767e \u5217 \u5949 \u795e \u7684 \u5dee \u9063 \u5f80 \u52a0 \u5229 \u5229 \u7684 \u4e00 \u5ea7 \u57ce \u53bb \uff0c \u8fd9 \u57ce \u540d \u53eb \u62ff \u6492 \u52d2 \uff0c<br>27 \u5230 \u4e00 \u4e2a \u7ae5 \u5973 \u90a3 \u91cc \uff0c \u662f \u5df2 \u7ecf \u8bb8 \u914d \u5927 \u536b \u5bb6 \u7684 \u4e00 \u4e2a \u4eba \uff0c \u540d \u53eb \u7ea6 \u745f \u3002 \u7ae5 \u5973 \u7684 \u540d \u5b57 \u53eb \u9a6c \u5229 \u4e9a \uff1b<br>28 \u5929 \u4f7f \u8fdb \u53bb \uff0c \u5bf9 \u4ed6 \u8bf4 \uff1a \u8499 \u5927 \u6069 \u7684 \u5973 \u5b50 \uff0c \u6211 \u95ee \u4f60 \u5b89 \uff0c \u4e3b \u548c \u4f60 \u540c \u5728 \u4e86 \uff01<br>29 \u9a6c \u5229 \u4e9a \u56e0 \u8fd9 \u8bdd \u5c31 \u5f88 \u60ca \u614c \uff0c \u53c8 \u53cd \u590d \u601d \u60f3 \u8fd9 \u6837 \u95ee \u5b89 \u662f \u751a \u9ebd \u610f \u601d \u3002<br>30 \u5929 \u4f7f \u5bf9 \u4ed6 \u8bf4 \uff1a \u9a6c \u5229 \u4e9a \uff0c \u4e0d \u8981 \u6015 \uff01 \u4f60 \u5728 \u795e \u9762 \u524d \u5df2 \u7ecf \u8499 \u6069 \u4e86 \u3002<br>31 \u4f60 \u8981 \u6000 \u5b55 \u751f \u5b50 \uff0c \u53ef \u4ee5 \u7ed9 \u4ed6 \u8d77 \u540d \u53eb \u8036 \u7a23 \u3002<br>32 \u4ed6 \u8981 \u4e3a \u5927 \uff0c \u79f0 \u4e3a \u81f3 \u9ad8 \u8005 \u7684 \u513f \u5b50 \uff1b \u4e3b \u795e \u8981 \u628a \u4ed6 \u7956 \u5927 \u536b \u7684 \u4f4d \u7ed9 \u4ed6 \u3002<br>33 \u4ed6 \u8981 \u4f5c \u96c5 \u5404 \u5bb6 \u7684 \u738b \uff0c \u76f4 \u5230 \u6c38 \u8fdc \uff1b \u4ed6 \u7684 \u56fd \u4e5f \u6ca1 \u6709 \u7a77 \u5c3d \u3002<br>34 \u9a6c \u5229 \u4e9a \u5bf9 \u5929 \u4f7f \u8bf4 \uff1a \u6211 \u6ca1 \u6709 \u51fa \u5ac1 \uff0c \u600e \u9ebd \u6709 \u8fd9 \u4e8b \u5462 \uff1f<br>35 \u5929 \u4f7f \u56de \u7b54 \u8bf4 \uff1a \u5723 \u7075 \u8981 \u4e34 \u5230 \u4f60 \u8eab \u4e0a \uff0c \u81f3 \u9ad8 \u8005 \u7684 \u80fd \u529b \u8981 \u836b \u5e87 \u4f60 \uff0c \u56e0 \u6b64 \u6240 \u8981 \u751f \u7684 \u5723 \u8005 \u5fc5 \u79f0 \u4e3a \u795e \u7684 \u513f \u5b50 \uff08 \u6216 \u4f5c \uff1a \u6240 \u8981 \u751f \u7684 \uff0c \u5fc5 \u79f0 \u4e3a \u5723 \uff0c \u79f0 \u4e3a \u795e \u7684 \u513f \u5b50 \uff09 \u3002<br>36 \u51b5 \u4e14 \u4f60 \u7684 \u4eb2 \u621a \u4ee5 \u5229 \u6c99 \u4f2f \uff0c \u5728 \u5e74 \u8001 \u7684 \u65f6 \u5019 \u4e5f \u6000 \u4e86 \u7537 \u80ce \uff0c \u5c31 \u662f \u90a3 \u7d20 \u6765 \u79f0 \u4e3a \u4e0d \u751f \u80b2 \u7684 \uff0c \u73b0 \u5728 \u6709 \u5b55 \u516d \u4e2a \u6708 \u4e86 \u3002<br>37 \u56e0 \u4e3a \uff0c \u51fa \u65bc \u795e \u7684 \u8bdd \uff0c \u6ca1 \u6709 \u4e00 \u53e5 \u4e0d \u5e26 \u80fd \u529b \u7684 \u3002<br>38 \u9a6c \u5229 \u4e9a \u8bf4 \uff1a \u6211 \u662f \u4e3b \u7684 \u4f7f \u5973 \uff0c \u60c5 \u613f \u7167 \u4f60 \u7684 \u8bdd \u6210 \u5c31 \u5728 \u6211 \u8eab \u4e0a \u3002 \u5929 \u4f7f \u5c31 \u79bb \u5f00 \u4ed6 \u53bb \u4e86 \u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Matthew 1,18-25<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>18 \u8036 \u7a23 \u57fa \u7763 \u964d \u751f \u7684 \u4e8b \u8bb0 \u5728 \u4e0b \u9762 \uff1a \u4ed6 \u6bcd \u4eb2 \u9a6c \u5229 \u4e9a \u5df2 \u7ecf \u8bb8 \u914d \u4e86 \u7ea6 \u745f \uff0c \u8fd8 \u6ca1 \u6709 \u8fce \u5a36 \uff0c \u9a6c \u5229 \u4e9a \u5c31 \u4ece \u5723 \u7075 \u6000 \u4e86 \u5b55 \u3002<br>19 \u4ed6 \u4e08 \u592b \u7ea6 \u745f \u662f \u4e2a \u4e49 \u4eba \uff0c \u4e0d \u613f \u610f \u660e \u660e \u7684 \u7f9e \u8fb1 \u4ed6 \uff0c \u60f3 \u8981 \u6697 \u6697 \u7684 \u628a \u4ed6 \u4f11 \u4e86 \u3002<br>20 \u6b63 \u601d \u5ff5 \u8fd9 \u4e8b \u7684 \u65f6 \u5019 \uff0c \u6709 \u4e3b \u7684 \u4f7f \u8005 \u5411 \u4ed6 \u68a6 \u4e2d \u663e \u73b0 \uff0c \u8bf4 \uff1a \u5927 \u536b \u7684 \u5b50 \u5b59 \u7ea6 \u745f \uff0c \u4e0d \u8981 \u6015 \uff01 \u53ea \u7ba1 \u5a36 \u8fc7 \u4f60 \u7684 \u59bb \u5b50 \u9a6c \u5229 \u4e9a \u6765 \uff0c \u56e0 \u4ed6 \u6240 \u6000 \u7684 \u5b55 \u662f \u4ece \u5723 \u7075 \u6765 \u7684 \u3002<br>21 \u4ed6 \u5c06 \u8981 \u751f \u4e00 \u4e2a \u513f \u5b50 \uff0c \u4f60 \u8981 \u7ed9 \u4ed6 \u8d77 \u540d \u53eb \u8036 \u7a23 \uff0c \u56e0 \u4ed6 \u8981 \u5c06 \u81ea \u5df1 \u7684 \u767e \u59d3 \u4ece \u7f6a \u6076 \u91cc \u6551 \u51fa \u6765 \u3002<br>22 \u8fd9 \u4e00 \u5207 \u7684 \u4e8b \u6210 \u5c31 \u662f \u8981 \u5e94 \u9a8c \u4e3b \u85c9 \u5148 \u77e5 \u6240 \u8bf4 \u7684 \u8bdd \uff0c<br>23 \u8bf4 \uff1a \u5fc5 \u6709 \u7ae5 \u5973 \u6000 \u5b55 \u751f \u5b50 \uff1b \u4eba \u8981 \u79f0 \u4ed6 \u7684 \u540d \u4e3a \u4ee5 \u9a6c \u5185 \u5229 \u3002 \uff08 \u4ee5 \u9a6c \u5185 \u5229 \u7ffb \u51fa \u6765 \u5c31 \u662f \u795e \u4e0e \u6211 \u4eec \u540c \u5728 \u3002 \uff09<br>24 \u7ea6 \u745f \u9192 \u4e86 \uff0c \u8d77 \u6765 \uff0c \u5c31 \u9075 \u7740 \u4e3b \u4f7f \u8005 \u7684 \u5429 \u5490 \u628a \u59bb \u5b50 \u5a36 \u8fc7 \u6765 \uff1b<br>25 \u53ea \u662f \u6ca1 \u6709 \u548c \u4ed6 \u540c \u623f \uff0c \u7b49 \u4ed6 \u751f \u4e86 \u513f \u5b50 \uff08 \u6709 \u53e4 \u5377 \uff1a \u7b49 \u4ed6 \u751f \u4e86 \u5934 \u80ce \u7684 \u513f \u5b50 \uff09 \uff0c \u5c31 \u7ed9 \u4ed6 \u8d77 \u540d \u53eb \u8036 \u7a23 \u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Luke 2,1-21<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1 \u5f53 \u90a3 \u4e9b \u65e5 \u5b50 \uff0c \u8be5 \u6492 \u4e9a \u53e4 \u58eb \u7763 \u6709 \u65e8 \u610f \u4e0b \u6765 \uff0c \u53eb \u5929 \u4e0b \u4eba \u6c11 \u90fd \u62a5 \u540d \u4e0a \u518c \u3002<br>2 \u8fd9 \u662f \u5c45 \u91cc \u626d \u4f5c \u53d9 \u5229 \u4e9a \u5de1 \u629a \u7684 \u65f6 \u5019 \uff0c \u5934 \u4e00 \u6b21 \u884c \u62a5 \u540d \u4e0a \u518c \u7684 \u4e8b \u3002<br>3 \u4f17 \u4eba \u5404 \u5f52 \u5404 \u57ce \uff0c \u62a5 \u540d \u4e0a \u518c \u3002<br>4 \u7ea6 \u745f \u4e5f \u4ece \u52a0 \u5229 \u5229 \u7684 \u62ff \u6492 \u52d2 \u57ce \u4e0a \u72b9 \u592a \u53bb \uff0c \u5230 \u4e86 \u5927 \u536b \u7684 \u57ce \uff0c \u540d \u53eb \u4f2f \u5229 \u6052 \uff0c \u56e0 \u4ed6 \u672c \u662f \u5927 \u536b \u4e00 \u65cf \u4e00 \u5bb6 \u7684 \u4eba \uff0c<br>5 \u8981 \u548c \u4ed6 \u6240 \u8058 \u4e4b \u59bb \u9a6c \u5229 \u4e9a \u4e00 \u540c \u62a5 \u540d \u4e0a \u518c \u3002 \u90a3 \u65f6 \u9a6c \u5229 \u4e9a \u7684 \u8eab \u5b55 \u5df2 \u7ecf \u91cd \u4e86 \u3002<br>6 \u4ed6 \u4eec \u5728 \u90a3 \u91cc \u7684 \u65f6 \u5019 \uff0c \u9a6c \u5229 \u4e9a \u7684 \u4ea7 \u671f \u5230 \u4e86 \uff0c<br>7 \u5c31 \u751f \u4e86 \u5934 \u80ce \u7684 \u513f \u5b50 \uff0c \u7528 \u5e03 \u5305 \u8d77 \u6765 \uff0c \u653e \u5728 \u9a6c \u69fd \u91cc \uff0c \u56e0 \u4e3a \u5ba2 \u5e97 \u91cc \u6ca1 \u6709 \u5730 \u65b9 \u3002<br>8 \u5728 \u4f2f \u5229 \u6052 \u4e4b \u91ce \u5730 \u91cc \u6709 \u7267 \u7f8a \u7684 \u4eba \uff0c \u591c \u95f4 \u6309 \u7740 \u66f4 \u6b21 \u770b \u5b88 \u7f8a \u7fa4 \u3002<br>9 \u6709 \u4e3b \u7684 \u4f7f \u8005 \u7ad9 \u5728 \u4ed6 \u4eec \u65c1 \u8fb9 \uff0c \u4e3b \u7684 \u8363 \u5149 \u56db \u9762 \u7167 \u7740 \u4ed6 \u4eec \uff1b \u7267 \u7f8a \u7684 \u4eba \u5c31 \u751a \u60e7 \u6015 \u3002<br>10 \u90a3 \u5929 \u4f7f \u5bf9 \u4ed6 \u4eec \u8bf4 \uff1a \u4e0d \u8981 \u60e7 \u6015 \uff01 \u6211 \u62a5 \u7ed9 \u4f60 \u4eec \u5927 \u559c \u7684 \u4fe1 \u606f \uff0c \u662f \u5173 \u4e4e \u4e07 \u6c11 \u7684 \uff1b<br>11 \u56e0 \u4eca \u5929 \u5728 \u5927 \u536b \u7684 \u57ce \u91cc \uff0c \u4e3a \u4f60 \u4eec \u751f \u4e86 \u6551 \u4e3b \uff0c \u5c31 \u662f \u4e3b \u57fa \u7763 \u3002<br>12 \u4f60 \u4eec \u8981 \u770b \u89c1 \u4e00 \u4e2a \u5a74 \u5b69 \uff0c \u5305 \u7740 \u5e03 \uff0c \u5367 \u5728 \u9a6c \u69fd \u91cc \uff0c \u90a3 \u5c31 \u662f \u8bb0 \u53f7 \u4e86 \u3002<br>13 \u5ffd \u7136 \uff0c \u6709 \u4e00 \u5927 \u961f \u5929 \u5175 \u540c \u90a3 \u5929 \u4f7f \u8d5e \u7f8e \u795e \u8bf4 \uff1a<br>14 \u5728 \u81f3 \u9ad8 \u4e4b \u5904 \u8363 \u8000 \u5f52 \u4e0e \u795e \uff01 \u5728 \u5730 \u4e0a \u5e73 \u5b89 \u5f52 \u4e0e \u4ed6 \u6240 \u559c \u60a6 \u7684 \u4eba \uff08 \u6709 \u53e4 \u5377 \u4f5c \uff1a \u559c \u60a6 \u5f52 \u4e0e \u4eba \uff09 \uff01<br>15 \u4f17 \u5929 \u4f7f \u79bb \u5f00 \u4ed6 \u4eec \uff0c \u5347 \u5929 \u53bb \u4e86 \u3002 \u7267 \u7f8a \u7684 \u4eba \u5f7c \u6b64 \u8bf4 \uff1a \u6211 \u4eec \u5f80 \u4f2f \u5229 \u6052 \u53bb \uff0c \u770b \u770b \u6240 \u6210 \u7684 \u4e8b \uff0c \u5c31 \u662f \u4e3b \u6240 \u6307 \u793a \u6211 \u4eec \u7684 \u3002<br>16 \u4ed6 \u4eec \u6025 \u5fd9 \u53bb \u4e86 \uff0c \u5c31 \u5bfb \u89c1 \u9a6c \u5229 \u4e9a \u548c \u7ea6 \u745f \uff0c \u53c8 \u6709 \u90a3 \u5a74 \u5b69 \u5367 \u5728 \u9a6c \u69fd \u91cc \uff1b<br>17 \u65e2 \u7136 \u770b \u89c1 \uff0c \u5c31 \u628a \u5929 \u4f7f \u8bba \u8fd9 \u5b69 \u5b50 \u7684 \u8bdd \u4f20 \u5f00 \u4e86 \u3002<br>18 \u51e1 \u542c \u89c1 \u7684 \uff0c \u5c31 \u8be7 \u5f02 \u7267 \u7f8a \u4e4b \u4eba \u5bf9 \u4ed6 \u4eec \u6240 \u8bf4 \u7684 \u8bdd \u3002<br>19 \u9a6c \u5229 \u4e9a \u5374 \u628a \u8fd9 \u4e00 \u5207 \u7684 \u4e8b \u5b58 \u5728 \u5fc3 \u91cc \uff0c \u53cd \u590d \u601d \u60f3 \u3002<br>20 \u7267 \u7f8a \u7684 \u4eba \u56de \u53bb \u4e86 \uff0c \u56e0 \u6240 \u542c \u89c1 \u6240 \u770b \u89c1 \u7684 \u4e00 \u5207 \u4e8b \uff0c \u6b63 \u5982 \u5929 \u4f7f \u5411 \u4ed6 \u4eec \u6240 \u8bf4 \u7684 \uff0c \u5c31 \u5f52 \u8363 \u8000 \u4e0e \u795e \uff0c \u8d5e \u7f8e \u4ed6 \u3002<br>21 \u6ee1 \u4e86 \u516b \u5929 \uff0c \u5c31 \u7ed9 \u5b69 \u5b50 \u884c \u5272 \u793c \uff0c \u4e0e \u4ed6 \u8d77 \u540d \u53eb \u8036 \u7a23 \uff1b \u8fd9 \u5c31 \u662f \u6ca1 \u6709 \u6210 \u80ce \u4ee5 \u524d \uff0c \u5929 \u4f7f \u6240 \u8d77 \u7684 \u540d \u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>John 1,4-5<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>4 \u751f \u547d \u5728 \u4ed6 \u91cc \u5934 \uff0c \u8fd9 \u751f \u547d \u5c31 \u662f \u4eba \u7684 \u5149 \u3002<br>5 \u5149 \u7167 \u5728 \u9ed1 \u6697 \u91cc \uff0c \u9ed1 \u6697 \u5374 \u4e0d \u63a5 \u53d7 \u5149 \u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1.\u5927\u5bb6\u597d\u6211\u662f\u4e3b\u64adkiki,\u4eca\u5929\u662f2024\u5723\u8bde\u8282\u7279\u522b\u8282\u76ee\uff0c\u795d\u613f\u6240\u6709\u542c\u4f172025\u5e74\u5e73\u5b89\u559c\u4e50\u3002\u73b0\u5728\u8ba9\u6211\u4eec\u4e00\u8d77\u6765\u8c08\u8bba\u4e00\u4e0b\u8036\u7a23\u7684\u8bde\u751f\uff0c\u548c\u6b64\u524d\u8282\u76ee\u7565\u6709\u4e0d\u540c\u7684\u662f\uff0c\u4e0b\u9762\u662fIngrid\u5bf9\u8036\u7a23\u8bde\u751f\u8fd9\u4e00\u91cd\u5927\u5386\u53f2\u65f6\u523b\u7684\u8bb2\u89e3\uff0c\u540e\u9762\u5219\u662f\u6211\u5bf9Ingrid\u59d0\u59d0\u7684\u76f8\u5173\u95ee\u9898\u91c7\u8bbf\uff0c\u6b22\u8fce\u5927\u5bb6\u5728\u8bc4\u8bba\u533a\u7559\u8a00\u8ba8\u8bba\uff01<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5927\u5bb6\u597d\uff01\u4eca\u5929\u6211\u4eec\u67e5\u9605\u4e86\u51e0\u4f4d\u798f\u97f3\u4f20\u9053\u8005\u7684\u6587\u5b57\uff0c\u4ee5\u4e86\u89e3\u8036\u7a23\u57fa\u7763\u5728\u4f2f\u5229\u6052\u72b9\u5927\u7684\u8bde\u751f\u7684\u6574\u4e2a\u6545\u4e8b\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u9996\u5148\uff0c\u5929\u4f7f\u52a0\u767e\u5217\u6765\u5230\u739b\u5229\u4e9a\u9762\u524d\uff0c\u5411\u5979\u5ba3\u544a\uff0c\u5979\u5c06\u6000\u5b55\uff0c\u5f25\u8d5b\u4e9a\u5c06\u7531\u5979\u800c\u751f\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8fd9\u91cc\u6709\u4e00\u4e2a\u975e\u5e38\u91cd\u8981\u7684\u7ec6\u8282\uff0c\u6211\u4eec\u5df2\u7ecf\u5728\u7ea6\u7ff0\u798f\u97f3\u4e2d\u8bfb\u5230\u8fc7\uff1a\u5f53\u5723\u7075\u964d\u4e34\u5230\u5979\u8eab\u4e0a\u5e76\u4e14\u81f3\u9ad8\u8005\u7684\u529b\u91cf\u7b3c\u7f69\u5979\u65f6\uff0c\u8036\u7a23\u57fa\u7763\u8fd8\u6ca1\u6709\u5f00\u59cb\u5b58\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u77e5\u9053\uff0c\u8036\u7a23\u57fa\u7763\u662f\u65e0\u59cb\u7684\uff0c\u6211\u4eec\u5728\u7ea6\u7ff0\u798f\u97f3\u548c\u4fdd\u7f57\u4e66\u4fe1\u4e2d\u90fd\u4e86\u89e3\u5230\uff0c\u5f53\u4e16\u754c\u88ab\u521b\u9020\u65f6\uff0c\u8036\u7a23\u5c31\u5728\u90a3\u91cc\u3002\u5f53\u4ed6\u964d\u4e34\u4eba\u95f4\u65f6\uff0c\u4ed6\u5316\u8eab\u4e3a\u4eba\uff0c\u7ea6\u7ff0\u5728\u4ed6\u7684\u4e66\u4fe1\u4e2d\u660e\u786e\u8868\u793a\uff0c\u51e1\u4e0d\u627f\u8ba4\u8036\u7a23\u57fa\u7763\u5316\u8eab\u4e3a\u4eba\u7684\u4eba\u90fd\u662f\u9a97\u5b50\u548c\u654c\u57fa\u7763\u8005\uff0c\u662f\u4e0a\u5e1d\u7684\u654c\u4eba\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6240\u4ee5\uff0c\u5f53\u6211\u4eec\u73af\u987e\u5730\u7403\u65f6\uff1a<br>\u6211\u4eec\u6709\u9a6c\u53a9\uff0c\u6709\u739b\u4e3d\u548c\u7ea6\u745f\u592b\uff0c\u8fd8\u6709\u9a6c\u69fd\u91cc\u7684\u5c0f\u7537\u5b69\u8036\u7a23\u3002\u4f46\u5982\u679c\u6211\u4eec\u4e0d\u627f\u8ba4\u8fd9\u4e2a\u5c0f\u7537\u5b69\u6765\u81ea\u5929\u5802\uff0c\u6211\u4eec\u5c31\u662f\u4e00\u4e2a\u9a97\u5b50\uff0c\u6211\u4eec\u5c31\u4e0d\u662f\u4e0a\u5e1d\u7684\u5b69\u5b50\u3002\u597d\u5427\uff0c\u4eca\u5929\u5f88\u591a\u4eba\u628a\u5723\u8bde\u8282\u5f52\u7ed3\u4e3a\u5723\u8bde\u8001\u4eba\uff0c\u8fd9\u4e0e\u5723\u8bde\u8282\u5b8c\u5168\u65e0\u5173\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u739b\u4e3d\u540c\u610f\u5929\u4f7f\u7684\u8bdd\uff0c\u5979\u5c06\u6210\u4e3a\u5f25\u8d5b\u4e9a\u7684\u6bcd\u4eb2\uff0c\u4f46\u5979\u6ca1\u6709\u95ee\uff0c\u5f53\u5979\u7684\u672a\u5a5a\u592b\u53d1\u73b0\u5979\u6000\u5b55\u65f6\uff0c\u5979\u4f1a\u600e\u4e48\u6837\u3002<br>\u5979\u628a\u6240\u6709\u7684\u62c5\u5fe7\u548c\u7591\u95ee\u90fd\u4ea4\u7ed9\u4e86\u4e0a\u5e1d\uff0c\u4e0a\u5e1d\u603b\u662f\u6709\u4e00\u4e2a\u5b8c\u7f8e\u7684\u8ba1\u5212\uff1a<br>\u8ba9\u6211\u4eec\u7ee7\u7eed\u9a6c\u592a\u798f\u97f3\u4e2d\u7684\u6545\u4e8b\uff1a\u5f53\u7ea6\u745f\u8003\u8651\u79d8\u5bc6\u79bb\u5f00\u739b\u4e3d\u65f6\uff0c\u4e0a\u5e1d\u6d3e\u4e86\u4e00\u4f4d\u5929\u4f7f\u5728\u68a6\u4e2d\u548c\u7ea6\u745f\u8bf4\u8bdd\uff0c\u8ba9\u4ed6\u628a\u739b\u4e3d\u5e26\u56de\u5bb6\u548c\u5979\u4e00\u8d77\u751f\u6d3b<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6240\u4ee5\uff0c\u4ed6\u4eec\u7ed3\u5a5a\u4e86\uff0c\u4f46\u7ea6\u745f\u76f4\u5230\u8036\u7a23\u51fa\u751f\u624d\u89e6\u78b0\u5979\u3002\u8036\u7a23\u51fa\u751f\u540e\uff0c\u4ed6\u4eec\u7684\u5a5a\u59fb\u5f88\u6b63\u5e38\uff0c\u4e0d\u4ec5\u6709\u8036\u7a23\uff0c\u8fd8\u6709\u66f4\u591a\u7684\u5b69\u5b50\u3002\u6545\u4e8b\u8fd9\u90e8\u5206\u6709\u8da3\u7684\u5730\u65b9\u5728\u4e8e\uff0c\u4e0a\u5e1d\u7ed9\u4e86\u7ea6\u745f\u6307\u793a\uff0c\u800c\u4e0d\u662f\u7ed9\u739b\u4e3d\u4e9a\u6307\u793a\u4ed6\u4eec\u5e94\u8be5\u505a\u4ec0\u4e48\u4ee5\u53ca\u4f1a\u53d1\u751f\u4ec0\u4e48\u3002\u5728\u4e00\u4e2a\u5bb6\u5ead\u4e2d\uff0c\u4e08\u592b\u603b\u662f\u6700\u8d1f\u8d23\u4efb\u7684\uff0c\u8fd9\u5c31\u662f\u4e3a\u4ec0\u4e48\u4e0a\u5e1d\u544a\u8bc9\u7ea6\u745f\u4ed6\u5e94\u8be5\u5982\u4f55\u5bf9\u5f85\u739b\u4e3d\u4e9a\uff0c\u540e\u6765\uff0c\u4ed6\u4eec\u5e94\u8be5\u9003\u5f80\u57c3\u53ca\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u56de\u5230\u8def\u52a0\u798f\u97f3\uff0c\u5728\u90a3\u91cc\u6211\u4eec\u5f97\u5230\u4e86\u66f4\u591a\u5173\u4e8e\u8036\u7a23\u8bde\u751f\u4e4b\u591c\u7684\u4fe1\u606f\u3002<br>\u5728\u53e4\u8001\u7684\u6559\u8bf2\u4e2d\uff0c\u5199\u5230\u5f25\u8d5b\u4e9a\u5fc5\u987b\u51fa\u751f\u5728\u4f2f\u5229\u6052\u3002\u7ea6\u745f\u548c\u739b\u4e3d\u6765\u81ea\u52a0\u5229\u5229\u7684\u62ff\u6492\u52d2\uff0c\u4f46\u5c31\u5728\u5f25\u8d5b\u4e9a\u5373\u5c06\u51fa\u751f\u7684\u65f6\u5019\uff0c\u4f2f\u5229\u6052\u6709\u4e00\u4e2a Sensus\uff0c\u7ea6\u745f\u548c\u739b\u4e3d\u5fc5\u987b\u53bb\u90a3\u91cc\u767b\u8bb0\uff0c\u56e0\u4e3a\u4ed6\u4eec\u662f\u5927\u536b\u738b\u7684\u5bb6\u5c5e\u3002<br>\u5bbf\u820d\u91cc\u6ca1\u6709\u5730\u65b9\uff0c\u6240\u4ee5\u5979\u4e0d\u5f97\u4e0d\u5728\u9a6c\u53a9\u91cc\u751f\u4e0b\u8036\u7a23\uff0c\u8036\u7a23\u88ab\u653e\u5728\u9a6c\u53a9\u91cc\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u9996\u5148\uff0c\u8fd9\u8868\u660e\u4e0a\u5e1d\u591a\u4e48\u8c26\u5351\u81ea\u5df1\uff0c\u5176\u6b21\uff0c\u8036\u7a23\u662f\u4e0a\u5e1d\u7684\u7f94\u7f8a\uff0c\u6240\u4ee5\u5f53\u5176\u4ed6\u7f8a\u51fa\u53bb\u65f6\uff0c\u4ed6\u5374\u5728\u9a6c\u53a9\u91cc\u3002<br>\u7f8a\u7fa4\u548c\u7267\u7f8a\u4eba\u4e00\u8d77\u5728\u7530\u91ce\u91cc\uff0c\u5f53\u5929\u4f7f\u5411\u4ed6\u4eec\u5ba3\u544a\u5f25\u8d5b\u4e9a\u8bde\u751f\u65f6\uff0c\u4ed6\u4eec\u8bf4\uff1a\u201c\u8363\u8000\u5f52\u4e8e\u81f3\u9ad8\u4e4b\u5904\u7684\u4e0a\u5e1d\uff0c\u5730\u4e0a\u5e73\u5b89\u5f52\u4e8e\u4ed6\u6240\u559c\u60a6\u7684\u4eba\uff01\u201d\uff0c\u4ed6\u4eec\u6765\u5230\u9a6c\u53a9\u770b\u770b\u53d1\u751f\u4e86\u4ec0\u4e48\u3002\u4ed6\u4eec\u770b\u5230\u9a6c\u69fd\u91cc\u7684\u5c0f\u5bb6\u5ead\u548c\u5f25\u8d5b\u4e9a\uff0c\u56de\u6765\u540e\u4e3a\u6240\u53d1\u751f\u7684\u4e8b\u8d5e\u7f8e\u4e0a\u5e1d\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6240\u4ee5\uff0c\u8fd9\u53d6\u51b3\u4e8e\u6211\u4eec\uff1a\u6211\u4eec\u662f\u5426\u4f1a\u63a5\u53d7\u8fd9\u4f4d\u5f25\u8d5b\u4e9a\u4f5c\u4e3a\u6211\u4eec\u4e2a\u4eba\u7684\u6551\u4e16\u4e3b\uff0c\u6210\u4e3a\u4e0a\u5e1d\u7684\u5b69\u5b50\uff0c\u751f\u6d3b\u5728\u5149\u660e\u4e2d\uff0c\u5373\u4f7f\u6211\u4eec\u5728\u5730\u7403\u4e0a\u6c38\u8fdc\u4e0d\u4f1a\u5b8c\u7f8e\uff0c\u6216\u8005\u6211\u4eec\u662f\u5426\u4f1a\u7ee7\u7eed\u7559\u5728\u9ed1\u6697\u4e2d\uff0c\u56de\u5230\u65b0\u751f\u7684\u8036\u7a23\u8eab\u8fb9\uff0c30\u5e74\u540e\uff0c\u4ed6\u4e3a\u4e86\u6211\u4eec\u6b7b\u5728\u5341\u5b57\u67b6\u4e0a\uff0c\u6210\u4e3a\u4e0a\u5e1d\u7684\u7f94\u7f8a\uff0c\u6d17\u6e05\u4e86\u4e16\u4eba\u7684\u7f6a\u5b7d\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1.<br>\u8c01\u5411\u739b\u5229\u4e9a\u5ba3\u5e03\u4e86\u8036\u7a23\u7684\u8bde\u751f\uff1f\u739b\u5229\u4e9a\u662f\u5982\u4f55\u56de\u5e94\u7684\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5929\u4f7f\u52a0\u767e\u5217\u5411\u739b\u4e3d\u5ba3\u544a\u8036\u7a23\u7684\u8bde\u751f\uff0c\u739b\u4e3d\u6362\u53e5\u8bdd\u8bf4\uff0c\u4e0a\u5e1d\uff0c\u6211\u662f\u4f60\u7684\u4ec6\u4eba\uff0c\u8bf7\u6309\u7167\u4f60\u5e0c\u671b\u7684\u65b9\u5f0f\u5bf9\u5f85\u6211\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>2.\u739b\u5229\u4e9a\u662f\u5982\u4f55\u88ab\u9009\u4e3a\u8036\u7a23\u7684\u6bcd\u4eb2\u7684\uff1f\u4e3a\u4ec0\u4e48\u9009\u62e9\u5979\u800c\u4e0d\u662f\u522b\u7684\u5973\u4eba\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u91cd\u8981\u7684\u662f\uff0c\u5979\u662f\u5927\u536b\u738b\u7684\u540e\u88d4\uff0c\u5979\u7684\u672a\u5a5a\u592b\u4e5f\u662f\u5927\u536b\u738b\u7684\u540e\u88d4\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u300a\u65e7\u7ea6\u300b\u4e2d\u5bf9\u5927\u536b\u738b\u7684\u8bb8\u8bfa\u662f\uff0c\u4ed6\u7684\u738b\u4f4d\u5c06\u6c38\u8fdc\u5b58\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u7136\uff0c\u4ed6\u5728\u5730\u7403\u4e0a\u7684\u738b\u4f4d\u5df2\u7ecf\u7ec8\u7ed3\uff0c\u56e0\u4e3a\u300a\u65e7\u7ea6\u300b\u4e2d\u72b9\u5927\u56fd\u738b\u7684\u65f6\u4ee3\u968f\u7740\u6240\u7f57\u95e8\u5723\u6bbf\u7684\u6bc1\u706d\u548c\u6d41\u4ea1\u5df4\u6bd4\u4f26\u800c\u7ec8\u7ed3\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u5f53\u795e\u5e94\u8bb8\u4e86\u67d0\u4ef6\u4e8b\uff0c\u4ed6\u5c31\u4f1a\u5b9e\u73b0\u5b83\u3002\u6240\u4ee5\uff0c\u5f53\u5927\u536b\u738b\u7684\u5b9d\u5ea7\u4e0d\u5728\u5730\u4e0a\u65f6\uff0c\u8036\u7a23\uff0c\u4f5c\u4e3a\u5927\u536b\u738b\u7684\u540e\u88d4\u7684\u5f25\u8d5b\u4e9a\u5c06\u6c38\u8fdc\u5750\u5728\u5929\u4e0a\u7684\u5b9d\u5ea7\u4e0a\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u53e6\u4e00\u4ef6\u4e8b\u662f\uff0c\u4e0a\u5e1d\u5bf9\u4e00\u4f4d\u56fd\u738b\u8bf4\uff1a\u4f60\u6c38\u8fdc\u4e0d\u4f1a\u6709\u66f4\u591a\u7684\u5b69\u5b50\u767b\u4e0a\u5927\u536b\u7684\u5b9d\u5ea7\uff0c\u800c\u8fd9\u662f\u738b\u5ba4\u8840\u7edf\u4e4b\u4e00\u3002\u4f46\u4e0a\u5e1d\u662f\u4e07\u80fd\u7684\uff1a\u7ea6\u745f\u5e76\u6ca1\u6709\u76f4\u63a5\u7ee7\u627f\u5927\u536b\u7684\u8840\u7edf\uff0c\u4ed6\u7ee7\u627f\u4e86\u739b\u4e3d\u7684\u8840\u7edf\uff0c\u739b\u4e3d\u662f\u5927\u536b\u5b9d\u5ea7\u7684\u76f4\u7cfb\u540e\u88d4\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u8bc1\u660e\u8fd9\u4e00\u5207\uff0c\u798f\u97f3\u4f20\u9053\u8005\u9a6c\u592a\u548c\u8def\u52a0\u5199\u4e0b\u4e86\u4ece\u739b\u5229\u4e9a\u5230\u7ea6\u745f\u7684\u5bb6\u65cf\u65cf\u8c31\u3002<br>\u9a6c\u592a\u798f\u97f3\u662f\u4e3a\u72b9\u592a\u4eba\u5199\u7684\uff0c\u6240\u4ee5\u6211\u4eec\u627e\u5230\u4e86\u4ece\u4e9a\u4f2f\u62c9\u7f55\u5230\u739b\u5229\u4e9a\u7684\u5bb6\u65cf\u8840\u7edf\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8def\u52a0\u798f\u97f3\u662f\u732e\u7ed9\u5916\u90a6\u4eba\u7684\uff0c\u6240\u4ee5\u6211\u4eec\u5728\u8def\u52a0\u798f\u97f3\u7b2c 3 \u7ae0\u4e2d\u627e\u5230\u4e86\u4ece\u7ea6\u745f\u5230\u4e9a\u5f53\u7684\u5386\u53f2\u5173\u8054\u3002<br>\u56e0\u6b64\uff0c\u7ea6\u745f\u548c\u739b\u5229\u4e9a\u8fd9\u5bf9\u592b\u5987\u5b8c\u5168\u7b26\u5408\u5148\u77e5\u4e4b\u524d\u6240\u8bf4\u7684\u6761\u4ef6\uff0c\u56e0\u6b64\u739b\u5229\u4e9a\u6210\u4e3a\u4e86\u8036\u7a23\u7684\u6bcd\u4eb2\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>3.<br>\u5929\u4f7f\u5728\u68a6\u4e2d\u5bf9\u7ea6\u745f\u8bf4\u4e86\u5173\u4e8e\u739b\u5229\u4e9a\u548c\u5979\u5b69\u5b50\u7684\u4ec0\u4e48\u4e8b\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u7ea6\u745f\u60f3\uff0c\u4e3a\u4ec0\u4e48\u4ed6\u7684\u672a\u5a5a\u59bb\u4f1a\u6000\u5b55\uff1f\u5f88\u660e\u663e\uff0c\u4ed6\u8ba4\u4e3a\u739b\u4e3d\u4e0d\u5fe0\uff0c\u800c\u4ed6\u7684\u8ba1\u5212\u662f\u79bb\u5f00\u739b\u4e3d\u3002\u8fd9\u5c31\u662f\u4e3a\u4ec0\u4e48\u5929\u4f7f\u5fc5\u987b\u548c\u4ed6\u8bf4\u8bdd\u5e76\u89e3\u91ca\u53d1\u751f\u7684\u4e8b\u60c5\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>4.<br>\u739b\u5229\u4e9a\u548c\u7ea6\u745f\u88ab\u6307\u793a\u7ed9\u5b69\u5b50\u53d6\u4ec0\u4e48\u540d\u5b57\uff1f\u8fd9\u4e2a\u540d\u5b57\u662f\u4ec0\u4e48\u610f\u601d\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4ed6\u4eec\u88ab\u6307\u793a\u8981\u7ed9\u8036\u7a23\u8d77\u540d\uff0c\u56e0\u4e3a\u4ed6\u5c06\u62ef\u6551\u4ed6\u7684\u4eba\u6c11\u8131\u79bb\u7f6a\u6076\u3002\u8036\u7a23\u7684\u53e6\u4e00\u4e2a\u540d\u5b57\u662f\u4ee5\u9a6c\u5185\u5229\uff0c\u610f\u601d\u662f\uff1a\u4e0a\u5e1d\u4e0e\u6211\u4eec\u540c\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>5.<br>\u4e3a\u4ec0\u4e48\u8036\u7a23\u51fa\u751f\u524d\u7ea6\u745f\u548c\u739b\u5229\u4e9a\u8981\u53bb\u4f2f\u5229\u6052\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u65f6\uff0c\u7f57\u9a6c\u5e1d\u56fd\u603b\u7763\u51ef\u6492\u00b7\u5965\u53e4\u65af\u7279\u9881\u5e03\u4e86\u4e00\u9879\u6cd5\u4ee4\u3002\u6240\u6709\u4eba\u90fd\u5fc5\u987b\u53bb\u81ea\u5df1\u7684\u57ce\u5e02\u3002\u739b\u4e3d\u548c\u7ea6\u745f\u592b\u4f4f\u5728\u52a0\u5229\u5229\u7684\u62ff\u6492\u52d2\uff0c\u4f46\u5979\u7684\u57ce\u5e02\u662f\u4f2f\u5229\u6052\uff0c\u5927\u536b\u4e4b\u57ce\uff0c\u56e0\u4e3a\u4ed6\u4eec\u662f\u5927\u536b\u7684\u540e\u88d4\u3002\u4ed6\u4eec\u5fc5\u987b\u53bb\u90a3\u91cc\u767b\u8bb0\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>6.Where was Jesus born, and why was he laid in a manger?<br>\u8036\u7a23\u662f\u5728\u54ea\u91cc\u51fa\u751f\u7684\uff1f\u4e3a\u4ec0\u4e48\u4ed6\u88ab\u653e\u5728\u9a6c\u69fd\u91cc\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u51fa\u751f\u5728\u4f2f\u5229\u6052\uff0c\u5ba2\u5e97\u91cc\u6ca1\u6709\u5730\u65b9\uff0c\u4ed6\u4eec\u53ea\u597d\u5728\u9a6c\u53a9\u91cc\u8fc7\u591c\uff0c\u5e76\u628a\u5a74\u513f\u653e\u5728\u9a6c\u69fd\u91cc\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u8fd8\u6709\u66f4\u6df1\u5c42\u7684\u542b\u4e49\uff1a\u56e0\u4e3a\u8036\u7a23\u662f\u9664\u53bb\u4e16\u4eba\u7f6a\u5b7d\u7684\u7f94\u7f8a\uff0c\u6240\u4ee5\u4ed6\u88ab\u5b89\u7f6e\u5728\u67d0\u4e2a\u5730\u65b9\uff0c\u90a3\u91cc\u7684\u52a8\u7269\u4e5f\u88ab\u5b89\u7f6e\u5728\u90a3\u91cc\u3002\u5f53\u7136\uff0c\u4e0a\u5e1d\u5982\u6b64\u8c26\u5351\u81ea\u5df1\uff0c\u4ee5\u81f3\u4e8e\u4ed6\u540c\u610f\u5728\u9a6c\u69fd\u91cc\u51fa\u751f\u65f6\u5c06\u9a6c\u5e8a\u4f5c\u4e3a\u4ed6\u7684\u5e8a\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>7.<br>\u7267\u7f8a\u4eba\u662f\u5982\u4f55\u5f97\u77e5\u8036\u7a23\u7684\u8bde\u751f\u7684\uff1f\u4ed6\u4eec\u6709\u4f55\u53cd\u5e94\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5929\u4f7f\u51fa\u73b0\u5728\u7530\u91ce\u4e0a\uff0c\u4ed6\u4eec\u6b63\u5728\u90a3\u91cc\u653e\u7267\u7f8a\u7fa4\u3002\u4e8e\u662f\u4ed6\u4eec\u8bf4\uff1a\u6211\u4eec\u53bb\u770b\u770b\u4f2f\u5229\u6052\u53d1\u751f\u4e86\u4ec0\u4e48\u4e8b\u5427\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>8.<br>\u5929\u4f7f\u5bf9\u7267\u7f8a\u4eba\u7684\u5ba3\u5e03\u6709\u4f55\u610f\u4e49\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u8bde\u751f\u7684\u90a3\u4e00\u523b\uff0c\u4eba\u7c7b\u4e0e\u4e0a\u5e1d\u4e4b\u95f4\u8fd8\u6ca1\u6709\u548c\u5e73\uff0c\u56e0\u4e3a\u7f6a\u5b7d\u59cb\u7ec8\u5b58\u5728\u4e8e\u4ed6\u4eec\u4e4b\u95f4\u3002\u5929\u4f7f\u5ba3\u544a\u5f25\u8d5b\u4e9a\u5df2\u7ecf\u5230\u6765\uff0c\u4ed6\u5c06\u4e3a\u6240\u6709\u63a5\u53d7\u4ed6\u4e3a\u6551\u4e16\u4e3b\u7684\u4eba\u5e26\u6765\u548c\u5e73\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>9.<br>\u5f53\u739b\u5229\u4e9a\u542c\u5230\u7267\u7f8a\u4eba\u6240\u8bf4\u7684\u4e00\u5207\u65f6\uff0c\u5979\u505a\u4e86\u4ec0\u4e48\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5979\u628a\u8fd9\u4e9b\u8bdd\u6df1\u6df1\u7684\u85cf\u5728\u5fc3\u5e95.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>10.<br>\u7ea6\u7ff0\u798f\u97f3\u5982\u4f55\u5f62\u5bb9\u8036\u7a23\u662f\u4e16\u754c\u7684\u5149\uff1f\u4e3a\u4ec0\u4e48\u4ed6\u8fd9\u6837\u60f3\u5462\uff1f<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u662f\u751f\u547d\uff0c\u662f\u5149\u3002\u5f53\u6211\u4eec\u6765\u5230\u8036\u7a23\u9762\u524d\u65f6\uff0c\u9ed1\u6697\u5c31\u4e0d\u80fd\u80dc\u8fc7\u4ed6\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8036\u7a23\u88ab\u9489\u5728\u5341\u5b57\u67b6\u4e0a\u7684\u90a3\u4e00\u5929\uff0c\u770b\u4e0a\u53bb\u9ed1\u6697\u5df2\u7ecf\u80dc\u5229\u4e86\uff0c\u4f46\u4e8b\u5b9e\u662f\uff0c\u8036\u7a23\u590d\u6d3b\u4e86\uff0c\u6218\u80dc\u4e86\u9ed1\u6697\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:code -->\n<pre class=\"wp-block-code\"><code>\u5982\u679c\u6211\u4eec\u9009\u62e9\u4e0e\u8036\u7a23\u4e00\u8d77\u751f\u6d3b\u5728\u5149\u660e\u4e2d\uff0c\u9ed1\u6697\u5c31\u65e0\u6cd5\u63a7\u5236\u6211\u4eec\u3002<\/code><\/pre>\n<!-- \/wp:code -->\n\n<!-- wp:paragraph -->\n<p>\u4eba\u4eec\u5e38\u5e38\u8ba4\u4e3a\uff0c\u8fd9\u662f\u4e0a\u5e1d\u4e0e\u9b54\u9b3c\u4e4b\u95f4\u7684\u6597\u4e89\u3002\u4f46\u4e8b\u5b9e\u5e76\u975e\u5982\u6b64\u3002\u4e0a\u5e1d\u662f\u4e07\u80fd\u7684\uff0c\u662f\u4e07\u7269\u7684\u521b\u9020\u8005\u3002\u9b54\u9b3c\u4e5f\u662f\u88ab\u521b\u9020\u7684\u751f\u7269\uff0c\u5373\u4f7f\u4ed6\u5f88\u806a\u660e\uff0c\u4ed6\u4e5f\u6ca1\u6709\u4e0a\u5e1d\u90a3\u6837\u7684\u529b\u91cf\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4e00\u5207\u90fd\u53d6\u51b3\u4e8e\u6211\u4eec\u81ea\u5df1\uff1a\u6211\u4eec\u662f\u884c\u8d70\u5728\u5149\u660e\u4e2d\u5e76\u5728\u57fa\u7763\u91cc\u5f97\u5230\u62ef\u6551\uff0c\u8fd8\u662f\u7559\u5728\u9ed1\u6697\u4e2d\u5e76\u5728\u6700\u7ec8\u4e0e\u9b54\u9b3c\u53ca\u5176\u5929\u4f7f\u4e00\u8d77\u4e0b\u5730\u72f1\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u8fd9\u5c06\u662f\u6211\u4eec\u5728\u5b87\u5b99\u4e2d\u76f8\u9047\u7684\u6700\u5b64\u72ec\u7684\u5730\u65b9\uff0c\u56e0\u4e3a\u7231\u3001\u53cb\u8c0a\u548c\u548c\u5e73\uff0c\u6240\u6709\u90a3\u4e9b\u8ba9\u6211\u4eec\u7684\u7075\u9b42\u5feb\u4e50\u7684\u4e8b\u7269\u90fd\u5c5e\u4e8e\u4e0a\u5e1d\u3001\u4e3b\u8036\u7a23\u548c\u5723\u7075\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u795d\u613f\u6211\u4eec\u6240\u6709\u7684\u542c\u4f17\u5723\u8bde\u5feb\u4e50\uff0c\u5e76\u5e0c\u671b\u4ed6\u4eec\u901a\u8fc7\u5723\u7075\u5b66\u4f1a\u5728\u5929\u7236\u8036\u7a23\u57fa\u7763\u9762\u524d\u751f\u6d3b\u5728\u5149\u660e\u4e2d\uff0c\u5723\u7075\u5219\u4f1a\u8ba9\u6211\u4eec\u94ed\u8bb0\u8036\u7a23\u7684\u8bdd\u8bed\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4eca\u5929\u7684\u8282\u76ee\u5c31\u5230\u8fd9\u91cc\uff0c\u611f\u8c22\u5927\u5bb6\u7684\u6536\u542c\uff01 \u795d\u5927\u5bb62024\u51ac\u81f3\u5feb\u4e50\u5723\u8bde\u8282\u5feb\u4e50\uff01\u6211\u4eec\u4e0b\u671f\u518d\u4f1a\uff01<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","_zh_post_name":"","_zh_post_excerpt":"","_zh_post_title":"Christmas Special - ZN 2024","_es_post_content":"<!-- wp:paragraph -->\n<p>26 Y al sexto mes, el \u00e1ngel Gabriel fu\u00e9 enviado de Dios \u00e1 una ciudad de Galilea, llamada Nazaret,<br>27 A una virgen desposada con un var\u00f3n que se llamaba Jos\u00e9, de la casa de David: y el nombre de la virgen era Mar\u00eda.<br>28 Y entrando el \u00e1ngel \u00e1 donde estaba, dijo, \u00a1Salve, muy favorecida! el Se\u00f1or es contigo: bendita t\u00fa entre las mujeres.<br>29 Mas ella, cuando le vi\u00f3, se turb\u00f3 de sus palabras, y pensaba qu\u00e9 salutaci\u00f3n fuese \u00e9sta.<br>30 Entonces el \u00e1ngel le dijo: Mar\u00eda, no temas, porque has hallado gracia cerca de Dios.<br>31 Y he aqu\u00ed, concebir\u00e1s en tu seno, y parir\u00e1s un hijo, y llamar\u00e1s su nombre JESUS.<br>32 Este ser\u00e1 grande, y ser\u00e1 llamado Hijo del Alt\u00edsimo: y le dar\u00e1 el Se\u00f1or Dios el trono de David su padre:<br>33 Y reinar\u00e1 en la casa de Jacob por siempre; y de su reino no habr\u00e1 fin.<br>34 Entonces Mar\u00eda dijo al \u00e1ngel: \u00bfC\u00f3mo ser\u00e1 esto? porque no conozco var\u00f3n.<br>35 Y respondiendo el \u00e1ngel le dijo: El Esp\u00edritu Santo vendr\u00e1 sobre ti, y la virtud del Alt\u00edsimo te har\u00e1 sombra; por lo cual tambi\u00e9n lo Santo que nacer\u00e1, ser\u00e1 llamado Hijo de Dios.<br>36 Y he aqu\u00ed, Elisabet tu parienta, tambi\u00e9n ella ha concebido hijo en su vejez; y este es el sexto mes \u00e1 ella que es llamada la est\u00e9ril:<br>37 Porque ninguna cosa es imposible para Dios.<br>38 Entonces Mar\u00eda dijo: He aqu\u00ed la sierva del Se\u00f1or; h\u00e1gase \u00e1 m\u00ed conforme \u00e1 tu palabra. Y el \u00e1ngel parti\u00f3 de ella.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Mateo 1,18-25<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>18 Y el nacimiento de Jesucristo fu\u00e9 as\u00ed: Que siendo Mar\u00eda su madre desposada con Jos\u00e9, antes que se juntasen, se hall\u00f3 haber concebido del Esp\u00edritu Santo.<br>19 Y Jos\u00e9 su marido, como era justo, y no quisiese infamarla, quiso dejarla secretamente.<br>20 Y pensando \u00e9l en esto, he aqu\u00ed el \u00e1ngel del Se\u00f1or le aparece en sue\u00f1os, diciendo: Jos\u00e9, hijo de David, no temas de recibir \u00e1 Mar\u00eda tu mujer, porque lo que en ella es engendrado, del Esp\u00edritu Santo es.<br>21 Y parir\u00e1 un hijo, y llamar\u00e1s su nombre JESUS, porque \u00e9l salvar\u00e1 \u00e1 su pueblo de sus pecados.<br>22 Todo esto aconteci\u00f3 para que se cumpliese lo que fu\u00e9 dicho por el Se\u00f1or, por el profeta que dijo:<br>23 He aqu\u00ed la virgen concebir\u00e1 y parir\u00e1 un hijo, Y llamar\u00e1s su nombre Emmanuel, que declarado, es: Con nosotros Dios.<br>24 Y despertando Jos\u00e9 del sue\u00f1o, hizo como el \u00e1ngel del Se\u00f1or le hab\u00eda mandado, y recibi\u00f3 \u00e1 su mujer.<br>25 Y no la conoci\u00f3 hasta que pari\u00f3 \u00e1 su hijo primog\u00e9nito: y llam\u00f3 su nombre JESUS.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lucas 2,1-21<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1 Y ACONTECIO en aquellos d\u00edas que sali\u00f3 edicto de parte de Augusto C\u00e9sar, que toda la tierra fuese empadronada.<br>2 Este empadronamiento primero fu\u00e9 hecho siendo Cirenio gobernador de la Siria.<br>3 E iban todos para ser empadronados, cada uno \u00e1 su ciudad.<br>4 Y subi\u00f3 Jos\u00e9 de Galilea, de la ciudad de Nazaret, \u00e1 Judea, \u00e1 la ciudad de David, que se llama Bethlehem, por cuanto era de la casa y familia de David;<br>5 Para ser empadronado con Mar\u00eda su mujer, desposada con \u00e9l, la cual estaba encinta.<br>6 Y aconteci\u00f3 que estando ellos all\u00ed, se cumplieron los d\u00edas en que ella hab\u00eda de parir.<br>7 Y pari\u00f3 \u00e1 su hijo primog\u00e9nito, y le envolvi\u00f3 en pa\u00f1ales, y acost\u00f3le en un pesebre, porque no hab\u00eda lugar para ellos en el mes\u00f3n.<br>8 Y hab\u00eda pastores en la misma tierra, que velaban y guardaban las vigilias de la noche sobre su ganado.<br>9 Y he aqu\u00ed el \u00e1ngel del Se\u00f1or vino sobre ellos, y la claridad de Dios los cerc\u00f3 de resplandor; y tuvieron gran temor.<br>10 Mas el \u00e1ngel les dijo: No tem\u00e1is; porque he aqu\u00ed os doy nuevas de gran gozo, que ser\u00e1 para todo el pueblo:<br>11 Que os ha nacido hoy, en la ciudad de David, un Salvador, que es CRISTO el Se\u00f1or.<br>12 Y esto os ser\u00e1 por se\u00f1al: hallar\u00e9is al ni\u00f1o envuelto en pa\u00f1ales, echado en un pesebre.<br>13 Y repentinamente fu\u00e9 con el \u00e1ngel una multitud de los ej\u00e9rcitos celestiales, que alababan \u00e1 Dios, y dec\u00edan:<br>14 Gloria en las alturas \u00e1 Dios, Y en la tierra paz, buena voluntad para con los hombres.<br>15 Y aconteci\u00f3 que como los \u00e1ngeles se fueron de ellos al cielo, los pastores dijeron los unos \u00e1 los otros: Pasemos pues hasta Bethlehem, y veamos esto que ha sucedido, que el Se\u00f1or nos ha manifestado.<br>16 Y vinieron apriesa, y hallaron \u00e1 Mar\u00eda, y \u00e1 Jos\u00e9, y al ni\u00f1o acostado en el pesebre.<br>17 Y vi\u00e9ndolo, hicieron notorio lo que les hab\u00eda sido dicho del ni\u00f1o.<br>18 Y todos los que oyeron, se maravillaron de lo que los pastores les dec\u00edan.<br>19 Mas Mar\u00eda guardaba todas estas cosas, confiri\u00e9ndolas en su coraz\u00f3n.<br>20 Y se volvieron los pastores glorificando y alabando \u00e1 Dios de todas las cosas que hab\u00edan o\u00eddo y visto, como les hab\u00eda sido dicho.<br>21 Y pasados los ocho d\u00edas para circuncidar al ni\u00f1o, llamaron su nombre JESUS; el cual le fu\u00e9 puesto por el \u00e1ngel antes que \u00e9l fuese concebido en el vientre.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hoy hemos examinado los textos de varios evangelistas para comprender toda la historia sobre el nacimiento de Jesucristo en Bel\u00e9n, Judea.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Primero, el \u00e1ngel Gabriel se apareci\u00f3 a Mar\u00eda y le anunci\u00f3 que quedar\u00eda embarazada y que de ella nacer\u00eda el Mes\u00edas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aqu\u00ed encontramos un detalle muy importante que ya le\u00edmos en el Evangelio de Juan: Jesucristo no comenz\u00f3 a existir cuando el Esp\u00edritu Santo vino sobre Mar\u00eda y la fuerza del Alt\u00edsimo la cubri\u00f3 con su sombra.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hemos aprendido que Jesucristo no tiene principio, y tanto en el Evangelio de Juan como en la carta de Pablo descubrimos que Jes\u00fas ya estaba presente cuando se cre\u00f3 la tierra. Cuando vino a la tierra, tom\u00f3 forma humana. Juan lo deja claro en su carta: cualquiera que no confiese que Jesucristo vino en carne es un enga\u00f1ador y el anticristo, el enemigo de Dios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si miramos alrededor en la tierra:<br>Vemos el establo, a Mar\u00eda, a Jos\u00e9 y al peque\u00f1o ni\u00f1o Jes\u00fas en el pesebre. Pero si no confesamos que este peque\u00f1o ni\u00f1o vino del cielo, somos enga\u00f1adores y no somos hijos de Dios. Hoy en d\u00eda, muchas personas reducen la Navidad a Pap\u00e1 Noel, quien no tiene absolutamente nada que ver con la Navidad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Mar\u00eda acept\u00f3 al \u00e1ngel que le anunciaba que ser\u00eda la madre del Mes\u00edas sin preguntar qu\u00e9 suceder\u00eda con ella si su prometido descubr\u00eda que estaba embarazada. Dej\u00f3 todas sus preocupaciones y preguntas en manos de Dios, quien siempre tiene un plan perfecto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Continuemos con la historia en el Evangelio de Mateo: Mientras Jos\u00e9 pensaba en dejar a Mar\u00eda en secreto, Dios envi\u00f3 a un \u00e1ngel para que le hablara en un sue\u00f1o y le dijera que deb\u00eda llevar a Mar\u00eda a su hogar y vivir con ella. Entonces se casaron, pero Jos\u00e9 no la toc\u00f3 hasta que Jes\u00fas naci\u00f3.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Despu\u00e9s del nacimiento de Jes\u00fas, llevaron una vida matrimonial normal con m\u00e1s hijos, no solo Jes\u00fas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lo interesante de esta parte de la historia es que Dios dio las instrucciones a Jos\u00e9, no a Mar\u00eda, sobre qu\u00e9 deb\u00edan hacer y qu\u00e9 suceder\u00eda. En un hogar, siempre el hombre \u2013 el esposo \u2013 es el principal responsable, y por eso Dios habl\u00f3 con Jos\u00e9, indic\u00e1ndole qu\u00e9 deb\u00eda hacer con Mar\u00eda y, m\u00e1s adelante, que deb\u00edan huir a Egipto.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Volvemos al Evangelio de Lucas, donde obtenemos m\u00e1s informaci\u00f3n sobre la noche en que naci\u00f3 Jes\u00fas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En las antiguas profec\u00edas estaba escrito que el Mes\u00edas deb\u00eda nacer en Bel\u00e9n. Jos\u00e9 y Mar\u00eda ven\u00edan de Nazaret en Galilea, pero justo en el momento en que el Mes\u00edas deb\u00eda nacer, se llev\u00f3 a cabo un censo en Bel\u00e9n. Jos\u00e9 y Mar\u00eda tuvieron que viajar all\u00ed para registrarse, ya que eran descendientes del rey David.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>No hab\u00eda lugar en la posada, por lo que Mar\u00eda tuvo que dar a luz en un establo, y Jes\u00fas fue puesto en un pesebre.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Primero, esto muestra cu\u00e1n grande fue la humildad de Dios; y segundo, Jes\u00fas era el Cordero de Dios, por lo que estaba en un establo, como los dem\u00e1s corderos que hab\u00edan sido sacados.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los pastores estaban con sus ovejas en el campo, y cuando los \u00e1ngeles anunciaron el nacimiento del Mes\u00edas con las palabras: \u201c\u00a1Gloria a Dios en las alturas, y en la tierra paz a los hombres de buena voluntad!\u201d, ellos fueron al establo para ver lo que hab\u00eda sucedido. Vieron a la peque\u00f1a familia y al Mes\u00edas en el pesebre, y regresaron glorificando a Dios por lo que hab\u00eda ocurrido.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ahora depende de nosotros: \u00bfAceptaremos a este Mes\u00edas como nuestro Salvador personal, nos convertiremos en hijos de Dios y viviremos en la luz, aunque nunca seremos perfectos aqu\u00ed en la tierra? \u00bfO permaneceremos en la oscuridad y le daremos la espalda al reci\u00e9n nacido Jes\u00fas, quien 30 a\u00f1os despu\u00e9s muri\u00f3 por nosotros en la cruz como el Cordero de Dios que quita el pecado del mundo?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Preguntas sobre la historia de Navidad: Basadas en los art\u00edculos navide\u00f1os sobre el nacimiento<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Bien, bas\u00e1ndome en el estudio b\u00edblico anterior, me gustar\u00eda hacerle a la hermana algunas preguntas relacionadas. Esperamos que las siguientes preguntas sean \u00fatiles para nuestros hermanos y hermanas que reci\u00e9n han aceptado la fe cristiana.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>\u00bfQui\u00e9n anunci\u00f3 a Mar\u00eda el nacimiento de Jes\u00fas, y c\u00f3mo respondi\u00f3 ella?<\/strong><br>El \u00e1ngel Gabriel anunci\u00f3 a Mar\u00eda el nacimiento de Jes\u00fas, y Mar\u00eda dijo en otras palabras: \"Dios, soy tu sierva. Haz conmigo como desees.\"<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfC\u00f3mo fue elegida Mar\u00eda para ser la madre de Jes\u00fas? \u00bfPor qu\u00e9 fue elegida ella y no otra mujer?<\/strong><br>Era importante que Mar\u00eda fuera descendiente del rey David, al igual que su prometido Jos\u00e9.<br>Dios le hab\u00eda prometido al rey David en el Antiguo Testamento que su trono durar\u00eda para siempre.<br>Por supuesto, su trono terrenal termin\u00f3 con la destrucci\u00f3n del templo de Salom\u00f3n y el exilio en Babilonia. Pero cuando Dios promete algo, \u00c9l lo cumple. Aunque no hab\u00eda un trono terrenal de David, Jes\u00fas, el Mes\u00edas y descendiente de David, se sentar\u00e1 en el trono celestial para siempre.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Otro detalle: Dios le dijo a un rey de la l\u00ednea de David que ninguno de sus descendientes volver\u00eda a sentarse en el trono. Pero Dios es todopoderoso: Jos\u00e9 no recibi\u00f3 la l\u00ednea sangu\u00ednea de David directamente, sino a trav\u00e9s de Mar\u00eda, quien era una descendiente directa de David.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Para probar esto, los evangelistas Mateo y Lucas escribieron los \u00e1rboles geneal\u00f3gicos de Mar\u00eda y Jos\u00e9. El Evangelio de Mateo, escrito para los jud\u00edos, traza el linaje desde Abraham hasta Mar\u00eda.<br>El Evangelio de Lucas, dirigido a los gentiles, traza el linaje desde Jos\u00e9 hasta Ad\u00e1n.<br>La pareja de Jos\u00e9 y Mar\u00eda cumpl\u00eda exactamente los requisitos que los profetas hab\u00edan anunciado, y por eso Mar\u00eda fue elegida para ser la madre de Jes\u00fas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":3} -->\n<ol start=\"3\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 le dijo el \u00e1ngel a Jos\u00e9 en su sue\u00f1o sobre Mar\u00eda y su hijo?<\/strong><br>Jos\u00e9 se preguntaba por qu\u00e9 su prometida estaba embarazada. Era evidente que pensaba que Mar\u00eda hab\u00eda sido infiel y planeaba separarse de ella en secreto. Por eso, el \u00e1ngel le habl\u00f3 en un sue\u00f1o y le explic\u00f3 lo que hab\u00eda sucedido.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 nombre deb\u00edan darle Mar\u00eda y Jos\u00e9 a su hijo, y qu\u00e9 significa este nombre?<\/strong><br>Deb\u00edan llamarlo Jes\u00fas, porque \u00e9l salvar\u00eda a su pueblo de sus pecados. Otro nombre para Jes\u00fas es Emanuel, que significa: \"Dios est\u00e1 con nosotros.\"<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfPor qu\u00e9 viajaron Jos\u00e9 y Mar\u00eda a Bel\u00e9n antes del nacimiento de Jes\u00fas?<\/strong><br>En aquellos d\u00edas, el emperador C\u00e9sar Augusto, gobernante del Imperio Romano, emiti\u00f3 un decreto. Todas las personas deb\u00edan registrarse en su ciudad de origen. Mar\u00eda y Jos\u00e9 viv\u00edan en Nazaret, en Galilea, pero su ciudad de origen era Bel\u00e9n, la ciudad de David, ya que eran descendientes de David. Por esta raz\u00f3n, deb\u00edan ir all\u00ed para registrarse.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Aqu\u00ed vemos nuevamente un evento que parec\u00eda casual, pero que era parte del gran plan de Dios. Se hab\u00eda profetizado que el Mes\u00edas nacer\u00eda en Bel\u00e9n, pero tambi\u00e9n se le llamar\u00eda Nazareno. Todo lo que Dios hace est\u00e1 planeado con todos los detalles.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":6} -->\n<ol start=\"6\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>\u00bfD\u00f3nde naci\u00f3 Jes\u00fas, y por qu\u00e9 fue colocado en un pesebre?<\/strong><br>Jes\u00fas naci\u00f3 en Bel\u00e9n. No hab\u00eda lugar en la posada, as\u00ed que Mar\u00eda y Jos\u00e9 tuvieron que pasar la noche en un establo y colocaron al beb\u00e9 en un pesebre.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Pero esto tiene un significado m\u00e1s profundo: Como Jes\u00fas es el Cordero que quita el pecado del mundo, fue colocado en un lugar donde se encuentran los animales. Adem\u00e1s, esto muestra c\u00f3mo Dios se humill\u00f3 a s\u00ed mismo al aceptar un pesebre como su cuna.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":7} -->\n<ol start=\"7\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>\u00bfC\u00f3mo se enteraron los pastores del nacimiento de Jes\u00fas y c\u00f3mo reaccionaron?<\/strong><br>Unos \u00e1ngeles se aparecieron a los pastores en el campo donde cuidaban sus ovejas. Ellos dijeron: \"Vayamos a Bel\u00e9n y veamos lo que ha sucedido.\"<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 significado tuvo el anuncio de los \u00e1ngeles a los pastores?<\/strong><br>En el momento del nacimiento de Jes\u00fas, la humanidad no ten\u00eda paz con Dios porque el pecado estaba entre ellos. Los \u00e1ngeles anunciaron que hab\u00eda llegado el Mes\u00edas, quien traer\u00eda paz a todos los que lo reciban como su Salvador.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 hizo Mar\u00eda cuando escuch\u00f3 todo lo que compartieron los pastores?<\/strong><br>Mar\u00eda guard\u00f3 estas palabras en su coraz\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>\u00bfQu\u00e9 dice Juan acerca de Jes\u00fas como la luz del mundo y por qu\u00e9 lo pensaba?<\/strong><br>Jes\u00fas es la vida y la luz. Cuando venimos a Jes\u00fas, la oscuridad no puede vencerlo.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>El d\u00eda en que Jes\u00fas fue crucificado, parec\u00eda que la oscuridad hab\u00eda triunfado. Pero la verdad es que Jes\u00fas resucit\u00f3 y venci\u00f3 la oscuridad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si vivimos con Jes\u00fas en la luz, la oscuridad no tiene poder sobre nosotros. A menudo, las personas piensan que es una lucha entre Dios y el diablo. Pero no. Dios es todopoderoso y el creador de todo. El diablo tambi\u00e9n es una criatura, y aunque es astuto, no tiene el mismo poder que Dios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La decisi\u00f3n es nuestra: \u00bfCaminamos en la luz y estamos seguros en Cristo, o permanecemos en la oscuridad y terminamos al final de los tiempos en el infierno con el diablo y sus \u00e1ngeles?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ese ser\u00e1 el lugar m\u00e1s solitario del universo, porque el amor, la comuni\u00f3n, la paz, todas las cosas que hacen feliz a nuestra alma, pertenecen a Dios, al Se\u00f1or Jes\u00fas y al Esp\u00edritu Santo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Deseo a todos nuestros oyentes una Feliz Navidad y espero que aprendan a vivir en la luz en la presencia de Dios Padre, Jes\u00fas Cristo y el Esp\u00edritu Santo, quien nos recuerda las palabras de Jes\u00fas.<\/p>\n<!-- \/wp:paragraph -->","_es_post_name":"","_es_post_excerpt":"","_es_post_title":"Especial de Navidad 2024","_de_post_content":"<!-- wp:audio {\"id\":1496} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/loveforasia.org\/wp-content\/uploads\/2024\/12\/Der_Kaiser_als_Schachfigur_Gottes.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\n\n<!-- wp:paragraph -->\n<p>26 Und im sechsten Monat ward der Engel Gabriel gesandt von Gott in eine Stadt in Galil\u00e4a, die hei\u00dft Nazareth,<br>27 zu einer Jungfrau, die vertraut war einem Manne mit Namen Joseph, vom Hause David: und die Jungfrau hie\u00df Maria.<br>28 Und der Engel kam zu ihr hinein und sprach: Gegr\u00fc\u00dfet seist du, Holdselige! Der HERR ist mit dir, du Gebenedeite unter den Weibern!<br>29 Da sie aber ihn sah, erschrak sie \u00fcber seine Rede und gedachte: Welch ein Gru\u00df ist das?<br>30 Und der Engel sprach zu ihr: F\u00fcrchte dich nicht, Maria! du hast Gnade bei Gott gefunden.<br>31 Siehe, du wirst schwanger werden und einen Sohn geb\u00e4ren, des Namen sollst du Jesus hei\u00dfen.<br>32 Der wird gro\u00df sein und ein Sohn des H\u00f6chsten genannt werden; und Gott der HERR wird ihm den Stuhl seines Vaters David geben;<br>33 und er wird ein K\u00f6nig sein \u00fcber das Haus Jakob ewiglich, und seines K\u00f6nigreiches wird kein Ende sein.<br>34 Da sprach Maria zu dem Engel: Wie soll das zugehen, da ich von keinem Manne wei\u00df?<br>35 Der Engel antwortete und sprach zu ihr: Der heilige Geist wird \u00fcber dich kommen, und die Kraft des H\u00f6chsten wird dich \u00fcberschatten; darum wird auch das Heilige, das von dir geboren wird, Gottes Sohn genannt werden.<br>36 Und siehe, Elisabeth, deine Gefreunde, ist auch schwanger mit einem Sohn in ihrem Alter und geht jetzt im sechsten Monat, von der man sagt, da\u00df sie unfruchtbar sei.<br>37 Denn bei Gott ist kein Ding unm\u00f6glich.<br>38 Maria aber sprach: Siehe ich bin des HERRN Magd; mir geschehe, wie du gesagt hast. Und der Engel schied von ihr.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>18 Die Geburt Christi war aber also getan. Als Maria, seine Mutter, dem Joseph vertraut war, fand sich's ehe er sie heimholte, da\u00df sie schwanger war von dem heiligen Geist.<br>19 Joseph aber, ihr Mann, war fromm und wollte sie nicht in Schande bringen, gedachte aber, sie heimlich zu verlassen.<br>20 Indem er aber also gedachte, siehe, da erschien ihm ein Engel des HERRN im Traum und sprach: Joseph, du Sohn Davids, f\u00fcrchte dich nicht, Maria, dein Gemahl, zu dir zu nehmen; denn das in ihr geboren ist, das ist von dem heiligen Geist.<br>21 Und sie wird einen Sohn geb\u00e4ren, des Namen sollst du Jesus hei\u00dfen; denn er wird sein Volk selig machen von ihren S\u00fcnden.<br>22 Das ist aber alles geschehen, auf da\u00df erf\u00fcllt w\u00fcrde, was der HERR durch den Propheten gesagt hat, der da spricht:<br>23 \"Siehe, eine Jungfrau wird schwanger sein und einen Sohn geb\u00e4ren, und sie werden seinen Namen Immanuel hei\u00dfen\", das ist verdolmetscht: Gott mit uns.<br>24 Da nun Joseph vom Schlaf erwachte, tat er, wie ihm des HERRN Engel befohlen hatte, und nahm sein Gemahl zu sich.<br>25 Und er erkannte sie nicht, bis sie ihren ersten Sohn gebar; und hie\u00df seinen Namen Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lukas 2,1-21<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>1 Es begab sich aber zu der Zeit, da\u00df ein Gebot von dem Kaiser Augustus ausging, da\u00df alle Welt gesch\u00e4tzt w\u00fcrde.<br>2 Und diese Sch\u00e4tzung war die allererste und geschah zu der Zeit, da Cyrenius Landpfleger von Syrien war.<br>3 Und jedermann ging, da\u00df er sich sch\u00e4tzen lie\u00dfe, ein jeglicher in seine Stadt.<br>4 Da machte sich auch auf Joseph aus Galil\u00e4a, aus der Stadt Nazareth, in das j\u00fcdische Land zur Stadt Davids, die da hei\u00dft Bethlehem, darum da\u00df er von dem Hause und Geschlechte Davids war,<br>5 auf da\u00df er sich sch\u00e4tzen lie\u00dfe mit Maria, seinem vertrauten Weibe, die ward schwanger.<br>6 Und als sie daselbst waren, kam die Zeit, da sie geb\u00e4ren sollte.<br>7 Und sie gebar ihren ersten Sohn und wickelte ihn in Windeln und legte ihn in eine Krippe; denn sie hatten sonst keinen Raum in der Herberge.<br>8 Und es waren Hirten in derselben Gegend auf dem Felde bei den H\u00fcrden, die h\u00fcteten des Nachts ihre Herde.<br>9 Und siehe, des HERRN Engel trat zu ihnen, und die Klarheit des HERRN leuchtete um sie; und sie f\u00fcrchteten sich sehr.<br>10 Und der Engel sprach zu ihnen: F\u00fcrchtet euch nicht! siehe, ich verk\u00fcndige euch gro\u00dfe Freude, die allem Volk widerfahren wird;<br>11 denn euch ist heute der Heiland geboren, welcher ist Christus, der HERR, in der Stadt Davids.<br>12 Und das habt zum Zeichen: ihr werdet finden das Kind in Windeln gewickelt und in einer Krippe liegen.<br>13 Und alsbald war da bei dem Engel die Menge der himmlischen Heerscharen, die lobten Gott und sprachen:<br>14 Ehre sei Gott in der H\u00f6he und Frieden auf Erden und den Menschen ein Wohlgefallen.<br>15 Und da die Engel von ihnen gen Himmel fuhren, sprachen die Hirten untereinander: La\u00dft uns nun gehen gen Bethlehem und die Geschichte sehen, die da geschehen ist, die uns der HERR kundgetan hat.<br>16 Und sie kamen eilend und fanden beide, Maria und Joseph, dazu das Kind in der Krippe liegen.<br>17 Da sie es aber gesehen hatten, breiteten sie das Wort aus, welches zu ihnen von diesem Kinde gesagt war.<br>18 Und alle, vor die es kam, wunderten sich der Rede, die ihnen die Hirten gesagt hatten.<br>19 Maria aber behielt alle diese Worte und bewegte sie in ihrem Herzen.<br>20 Und die Hirten kehrten wieder um, priesen und lobten Gott um alles, was sie geh\u00f6rt und gesehen hatten, wie denn zu ihnen gesagt war.<br>21 Und da acht Tage um waren, da\u00df das Kind beschnitten w\u00fcrde, da ward sein Name genannt Jesus, welcher genannt war von dem Engel, ehe denn er in Mutterleibe empfangen ward.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Johannes 1,4-5<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>4 In ihm war das Leben, und das Leben war das Licht der Menschen.<br>5 Und das Licht scheint in der Finsternis, und die Finsternis hat's nicht begriffen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":2} -->\n<ol start=\"2\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Zusammenfassung von Ingrid Schwester:<\/strong><\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Heute haben wir die Texte mehrerer Evangelisten betrachtet, um die gesamte Geschichte \u00fcber die Geburt von Jesus Christus in Bethlehem, Jud\u00e4a, zu erfassen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Zuerst erschien der Engel Gabriel Maria und k\u00fcndigte ihr an, dass sie schwanger werden und der Messias von ihr geboren werden w\u00fcrde.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hier finden wir ein sehr wichtiges Detail, das wir bereits im Johannesevangelium gelesen haben: Jesus Christus begann nicht erst zu existieren, als der Heilige Geist \u00fcber Maria kam und die Kraft des H\u00f6chsten sie \u00fcberschattete.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wir haben gelernt, dass Jesus Christus keinen Anfang hat, und sowohl im Johannesevangelium als auch im Brief des Paulus erfahren wir, dass Jesus bereits bei der Erschaffung der Erde anwesend war. Als er auf die Erde kam, nahm er menschliche Gestalt an. Johannes macht in seinem Brief deutlich, dass jeder, der nicht bekennt, dass Jesus Christus im Fleisch gekommen ist, ein Verf\u00fchrer und der Antichrist ist \u2013 der Feind Gottes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wenn wir uns also auf der Erde umsehen:<br>Wir sehen den Stall, Maria und Josef und das kleine Jesuskind in der Krippe. Aber wenn wir nicht bekennen, dass dieses kleine Kind vom Himmel gekommen ist, sind wir Verf\u00fchrer und keine Kinder Gottes. Heute reduzieren viele Menschen Weihnachten auf den Weihnachtsmann, der absolut nichts mit Weihnachten zu tun hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Maria stimmte dem Engel zu, dass sie die Mutter des Messias werden w\u00fcrde, ohne zu fragen, was mit ihr geschehen w\u00fcrde, wenn ihr Verlobter herausfindet, dass sie schwanger war. Sie \u00fcberlie\u00df alle Sorgen und Fragen Gott, der immer einen perfekten Plan hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Gehen wir weiter mit der Geschichte im Matth\u00e4usevangelium: W\u00e4hrend Josef dar\u00fcber nachdachte, Maria heimlich zu verlassen, sandte Gott einen Engel, der ihm im Traum sagte, dass er Maria zu sich nehmen und mit ihr zusammenleben solle. Also heirateten sie, aber Josef r\u00fchrte sie nicht an, bis Jesus geboren wurde. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nach der Geburt Jesu f\u00fchrten sie eine normale Ehe mit weiteren Kindern, nicht nur Jesus. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Das Interessante an diesem Teil der Geschichte ist, dass Gott die Anweisungen Josef gab, nicht Maria, was sie tun sollten und was geschehen w\u00fcrde. In einem Haushalt ist immer der Mann \u2013 der Ehemann \u2013 die Hauptverantwortliche Person, und deshalb sprach Gott mit Josef, was er mit Maria tun und sp\u00e4ter, dass sie nach \u00c4gypten fliehen sollten.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wir kehren zum Lukasevangelium zur\u00fcck, wo wir mehr \u00fcber die Nacht erfahren, in der Jesus geboren wurde.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In den alten Prophezeiungen war geschrieben, dass der Messias in Bethlehem geboren werden sollte. Josef und Maria kamen aus Nazareth in Galil\u00e4a, aber genau zu der Zeit, als der Messias geboren werden sollte, fand in Bethlehem eine Volksz\u00e4hlung statt. Dorthin mussten Josef und Maria reisen, um sich registrieren zu lassen, da sie Nachkommen von K\u00f6nig David waren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es gab keinen Platz in der Herberge, also musste Maria in einem Stall geb\u00e4ren, und Jesus wurde in eine Krippe gelegt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Zun\u00e4chst zeigt dies, wie sehr Gott sich selbst erniedrigte, und zweitens war Jesus das Lamm Gottes. So befand er sich in einem Stall, als die anderen Schafe hinausgef\u00fchrt worden waren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Die Schafe waren mit ihren Hirten auf dem Feld, und als die Engel die Geburt des Messias mit den Worten verk\u00fcndeten: \u201eEhre sei Gott in der H\u00f6he und Frieden auf Erden bei den Menschen seines Wohlgefallens!\u201c, kamen sie zum Stall, um zu sehen, was geschehen war. Sie sahen die kleine Familie und den Messias in der Krippe und kehrten zur\u00fcck, indem sie Gott f\u00fcr das, was geschehen war, verherrlichten.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nun liegt es an uns: Werden wir diesen Messias als unseren pers\u00f6nlichen Retter annehmen, ein Kind Gottes werden und im Licht leben, auch wenn wir hier auf Erden niemals vollkommen sein werden? Oder werden wir in der Dunkelheit bleiben und dem neugeborenen Jesus den R\u00fccken kehren, der 30 Jahre sp\u00e4ter f\u00fcr uns am Kreuz gestorben ist, um als Gottes Lamm die S\u00fcnden der Welt wegzunehmen?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Fragen zur Weihnachtsgeschichte: Basierend auf den Weihnachtsartikeln zur Geburt<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Okay, basierend auf dem obigen Bibelstudium m\u00f6chte ich Schwester einige dazugeh\u00f6rige Fragen stellen. Wir hoffen, dass die folgenden Fragen unseren Br\u00fcdern und Schwestern, die gerade Christen geworden sind, hilfreich sein k\u00f6nnen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Wer k\u00fcndigte Maria die Geburt von Jesus an, und wie reagierte Maria?<\/strong><br>Der Engel Gabriel k\u00fcndigte Maria die Geburt von Jesus an, und Maria sagte sinngem\u00e4\u00df: \u201eGott, ich bin deine Dienerin. Tu mit mir, wie du m\u00f6chtest.\u201c<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Wie wurde Maria zur Mutter von Jesus gew\u00e4hlt? Warum wurde sie und keine andere Frau ausgew\u00e4hlt?<\/strong><br>Es war wichtig, dass Maria eine Nachfahrin von K\u00f6nig David war, ebenso wie ihr Verlobter Josef.<br>Gott hatte K\u00f6nig David im Alten Testament versprochen, dass sein Thron f\u00fcr immer bestehen w\u00fcrde.<br>Nat\u00fcrlich endete sein irdischer Thron mit der Zerst\u00f6rung des Tempels von Salomo und der babylonischen Gefangenschaft. Aber wenn Gott etwas verspricht, erf\u00fcllt er es. Da es keinen irdischen Thron von K\u00f6nig David mehr gab, wird Jesus, der Messias und Nachfahre Davids, f\u00fcr immer auf dem himmlischen Thron sitzen.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Ein weiteres Detail: Gott sagte zu einem K\u00f6nig aus Davids Linie, dass dessen Nachkommen nie mehr auf Davids Thron sitzen w\u00fcrden. Doch Gott ist allm\u00e4chtig: Josef erhielt Davids Blutlinie nicht direkt, sondern durch Maria, die eine direkte Nachfahrin von David war.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Um dies zu beweisen, schrieben die Evangelisten Matth\u00e4us und Lukas den Stammbaum von Maria und Josef nieder. Das Matth\u00e4usevangelium, das f\u00fcr die Juden geschrieben wurde, f\u00fchrt den Stammbaum von Abraham bis zu Maria auf.<br>Das Lukasevangelium, das f\u00fcr die Heiden geschrieben wurde, f\u00fchrt den Stammbaum von Josef bis zu Adam auf.<br>Das Paar Josef und Maria entsprach genau den Voraussetzungen, die die Propheten vorausgesagt hatten, und so wurde Maria zur Mutter von Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":3} -->\n<ol start=\"3\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Was sagte der Engel Josef im Traum \u00fcber Maria und ihr Kind?<\/strong><br>Josef fragte sich, warum seine Verlobte schwanger war. Es war offensichtlich, dass er dachte, Maria sei untreu gewesen, und er plante, sich heimlich von ihr zu trennen. Deshalb sprach der Engel zu ihm im Traum und erkl\u00e4rte ihm, was geschehen war.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Welchen Namen sollten Maria und Josef ihrem Kind geben, und was bedeutet dieser Name?<\/strong><br>Sie sollten das Kind Jesus nennen, weil er sein Volk von ihren S\u00fcnden retten w\u00fcrde. Ein weiterer Name f\u00fcr Jesus ist Immanuel, was bedeutet: \u201eGott ist mit uns.\u201c<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Warum reisten Josef und Maria vor Jesu Geburt nach Bethlehem?<\/strong><br>Zu jener Zeit erlie\u00df Kaiser Augustus, der Herrscher des R\u00f6mischen Reiches, ein Dekret. Alle Menschen mussten sich in ihrer Heimatstadt registrieren lassen. Maria und Josef lebten in Nazareth in Galil\u00e4a, aber ihre Stadt war Bethlehem, die Stadt Davids, da sie Nachkommen Davids waren. Dort mussten sie sich eintragen lassen.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Wieder sehen wir hier ein scheinbar zuf\u00e4lliges Ereignis, das jedoch Teil von Gottes gr\u00f6\u00dferem Plan war. Der Messias wurde vorhergesagt, in Bethlehem geboren zu werden, aber er sollte auch ein Nazarener genannt werden. Alles, was Gott tut, ist bis ins Detail geplant.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":6} -->\n<ol start=\"6\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Wo wurde Jesus geboren, und warum wurde er in eine Krippe gelegt?<\/strong><br>Jesus wurde in Bethlehem geboren. Es gab keinen Platz in der Herberge, also mussten Maria und Josef die Nacht in einem Stall verbringen, und das Baby wurde in eine Krippe gelegt.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Aber das hat eine tiefere Bedeutung: Da Jesus das Lamm ist, das die S\u00fcnde der Welt wegnimmt, wurde er an einen Ort gelegt, wo sonst Tiere sind. Zudem zeigt dies, wie sehr Gott sich erniedrigte, indem er sich mit einer Krippe als Bett zufrieden gab.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":7} -->\n<ol start=\"7\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Wie erfuhren die Hirten von der Geburt Jesu, und wie reagierten sie?<\/strong><br>Engel erschienen den Hirten auf dem Feld, wo sie ihre Schafe h\u00fcteten. Sie sagten: \u201eLasst uns nach Bethlehem gehen und sehen, was geschehen ist.\u201c<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Welche Bedeutung hatte die Verk\u00fcndigung der Engel an die Hirten?<\/strong><br>Zum Zeitpunkt von Jesu Geburt hatte die Menschheit keinen Frieden mit Gott, da die S\u00fcnde zwischen ihnen stand. Die Engel verk\u00fcndeten, dass der Messias gekommen ist, der Frieden zu allen bringen wird, die ihn als ihren Retter annehmen.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Was tat Maria, als sie alles h\u00f6rte, was die Hirten erz\u00e4hlten?<\/strong><br>Maria bewahrte diese Worte in ihrem Herzen.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Was sagt Johannes \u00fcber Jesus als das Licht der Welt, und warum dachte er so?<\/strong><br>Jesus ist das Leben und das Licht. Wenn wir zu Jesus kommen, kann die Dunkelheit ihn nicht \u00fcberw\u00e4ltigen.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>An dem Tag, als Jesus gekreuzigt wurde, schien es, als h\u00e4tte die Dunkelheit gesiegt. Doch die Wahrheit ist, dass Jesus auferstanden ist und die Dunkelheit \u00fcberwunden hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wenn wir mit Jesus im Licht leben, hat die Dunkelheit keine Macht \u00fcber uns. Oft denken Menschen, es sei ein Kampf zwischen Gott und dem Teufel. Aber nein, Gott ist allm\u00e4chtig und der Sch\u00f6pfer von allem. Der Teufel ist ebenfalls ein Gesch\u00f6pf, und auch wenn er klug ist, hat er nicht dieselbe Macht wie Gott.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Die Entscheidung liegt bei uns: Gehen wir im Licht und sind in Christus sicher, oder bleiben wir in der Dunkelheit und landen am Ende der Zeit mit dem Teufel und seinen Engeln in der H\u00f6lle?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Das wird der einsamste Ort im Universum sein, denn Liebe, Gemeinschaft, Frieden \u2013 all die Dinge, die unsere Seele gl\u00fccklich machen \u2013 geh\u00f6ren zu Gott, dem Herrn Jesus und dem Heiligen Geist.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ich w\u00fcnsche allen Zuh\u00f6rern eine fr\u00f6hliche Weihnacht und hoffe, dass sie lernen, im Licht in der Gegenwart von Gott Vater, Jesus Christus und durch den Heiligen Geist zu leben, der uns an Jesu Worte erinnert.<\/p>\n<!-- \/wp:paragraph -->","_de_post_name":"","_de_post_excerpt":"","_de_post_title":"Weihnachtsprogramm 2024","_nb_post_content":"<!-- wp:paragraph -->\n<p>26 Da Elisabet var gravid i sin sjette m\u00e5ned, sendte Gud engelen Gabriel til en ung jente i byen Nasaret i Galilea. 27 Navnet hennes var Maria, og hun var trolovet med en mann som het Josef, som tilh\u00f8rte etterkommerne av kong David.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>28 Engelen Gabriel viste seg n\u00e5 for henne og sa: \u201dJeg hilser deg, Maria! Herren fryder seg over deg, og han er med deg!\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>29 Maria ble virkelig forskrekket og undret seg p\u00e5 hva engelen kunne mene. 30 Men engelen sa: \u201dV\u00e6r ikke redd, Maria! Gud har noe godt i vente for deg. 31 Du skal bli gravid og f\u00f8de en s\u00f8nn, og du skal kalle ham Jesus. 32 Han skal v\u00e6re stor og bli kalt Guds s\u00f8nn. Herren Gud skal gj\u00f8re ham til konge, for han skal arve sin stamfar Davids trone. 33 Han skal regjere over Israels folk[d] for evig, og hans kongsmakt skal aldri ta slutt.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>34 Da spurte Maria engelen: \u201dMen hvordan skal jeg kunne bli gravid? Jeg har jo ikke v\u00e6rt sammen med noen mann.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>35 Engelen svarte: \u201dGuds Hellige \u00c5nd skal komme over deg, og Guds kraft skal omslutte deg. Derfor skal det barnet som du f\u00f8der v\u00e6re hellig og bli kalt Guds s\u00f8nn. 36 Din slektning Elisabet venter ogs\u00e5 barn, og det til tross for sin h\u00f8ye alder. Hun, som de sa var steril, er n\u00e5 i sin sjette m\u00e5ned! 37 Ingen ting er umulig for Gud!\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>38 Maria sa: \u201dJeg vil v\u00e6re lydig mot Herren Gud og tjene ham. La det bli som du har sagt.\u201d Etter dette forsvant engelen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Mattew 1,18-25<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>18 Da Jesus Kristus ble f\u00f8dt, gikk det slik til: Hans mor Maria var trolovet og skulle gifte seg med Josef. Men allerede f\u00f8r de var gift, ble hun med barn ved Guds Hellige \u00c5nd.[b] 19 Josef, hennes kommende mann, s\u00e5 da ingen annen utvei enn \u00e5 skille seg fra henne i stillhet. Han ville leve etter Guds bud, men \u00f8nsket ikke \u00e5 skjemme ut Maria offentlig.[c]<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>20 Mens han fortsatt grublet p\u00e5 hvordan han skulle l\u00f8se problemet, viste en Herrens engel seg for ham i en dr\u00f8m.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Engelen sa: \u201dJosef, du som er etterkommer av kong David, du skal ikke n\u00f8le med \u00e5 gifte deg med Maria, for det barnet hun b\u00e6rer, er blitt til ved Guds Hellige \u00c5nd. 21 Hun skal f\u00e5 en s\u00f8nn, og du skal kalle ham Jesus, for han skal frelse folket sitt fra syndene deres.[d]\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>22 P\u00e5 denne m\u00e5ten ble det som Gud hadde forutsagt ved profeten Jesaja, til virkelighet: 23 \u201dLytt! Den unge jenta skal bli med barn og f\u00f8de en s\u00f8nn, og de skal kalle ham Immanuel, som betyr \u2019Gud er med oss\u2019.\u201d[e]<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>24 Da Josef v\u00e5knet, gjorde han som engelen hadde gitt beskjed om, og han giftet seg med Maria. 25 De hadde imidlertid ikke noe seksuelt samliv f\u00f8r s\u00f8nnen var f\u00f8dt. Josef ga ham navnet Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Lukas 2 <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>2 P\u00e5 denne tiden hadde den romerske keiseren ved navn Augustus gitt befaling om at alle innbyggerne i Romerriket skulle registreres i manntallet for \u00e5 betale skatt. 2 Det var den f\u00f8rste skatteregistreringen, og den ble gjort da Kvirinius var landsh\u00f8vding i Syria.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>3 Hver og en m\u00e5tte reise til hjembyen sin for \u00e5 registrere seg der. 4 Etter som Josef tilh\u00f8rte slekten til kong David, m\u00e5tte han reise fra byen Nasaret i Galilea til Betlehem i Judea, som var kong Davids by. 5 Han tok med seg Maria, som han var trolovet[a] med, og som n\u00e5 ventet barn.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>6 Mens de var i Betlehem, kom tiden da hun skulle f\u00f8de, 7 og hun f\u00f8dte sitt f\u00f8rste barn, en gutt. Hun sv\u00f8pte han i myke remser av t\u00f8y[b] og la ham i krybben som var beregnet p\u00e5 dyrene, for det var det ikke plass for dem inne i vertshuset.<br>Noen gjetere bes\u00f8ker Jesus<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>8 Samme natten var noen gjetere ute og voktet sauene sine p\u00e5 beitemarkene utenfor byen. 9 Da sto det plutselig en engel fra Herren Gud foran dem, og Herrens herlighet lyste omkring dem. De ble fryktelig redde, 10 men engelen beroliget alle og sa: \u201dV\u00e6r ikke redde! Jeg kommer til dere med en stor glede som gjelder hele folket, og som skal gj\u00f8re alle glade! 11 I natt er han som skal frelse dere, blitt f\u00f8dt i Betlehem. Han er Messias, den lovede kongen, Herren. 12 Dere skal kjenne ham igjen p\u00e5 det at han er sv\u00f8pt i remser av t\u00f8y og ligger i en krybbe.\u201d 13 Plutselig var engelen omgitt av et mektig kor av engler fra himmelen som hyllet Herren Gud og sang:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>14<br>\u201d\u00c6re til Gud i himmelen,<br>og fred p\u00e5 jorden til dem som gj\u00f8r Gud glad.\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>15 Da englene hadde dratt tilbake til himmelen, sa gjeterne til hverandre: \u201dKom! Vi m\u00e5 g\u00e5 til Betlehem og se det fantastiske som har skjedd, og som Herren har latt oss f\u00e5 vite om!\u201d<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>16 S\u00e5 sprang de inn til byen, og fant Maria og Josef og det nyf\u00f8dte barnet som l\u00e5 i krybben. 17 Da de hadde sett barnet, fortalte de til alle det engelen hadde sagt om den nyf\u00f8dte. 18 Alle som h\u00f8rte dette, undret seg over fortellingen til gjeterne. 19 Maria la hvert ord p\u00e5 sitt minne og tenkte ofte p\u00e5 det.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>20 Gjeterne dro tilbake til beitemarkene og hyllet og \u00e6ret Gud for alt det de hadde f\u00e5tt se og h\u00f8re. Fra begynnelse til slutt var det n\u00f8yaktig som engelen hadde fortalt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>21 \u00c5tte dager seinere, da gutten skulle bli omsk\u00e5ret, fikk han navnet Jesus. Det var dette navnet engelen hadde gitt ham f\u00f8r moren var blitt gravid.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>John 1,4-5<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>4 Alt liv kommer fra ham, og livet hans er lyset for menneskene. 5 Hans lys skinner i m\u00f8rket, og m\u00f8rket kan aldri slokke det.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true,\"start\":2} -->\n<ol start=\"2\" class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Sammendrag av Ingrid S\u00f8ster:<\/strong><\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>I dag har vi sett p\u00e5 tekstene til flere evangelister for \u00e5 f\u00e5 en helhetlig forst\u00e5else av historien om Jesu Kristi f\u00f8dsel i Betlehem, Judea.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>F\u00f8rst viste engelen Gabriel seg for Maria og kunngjorde at hun skulle bli gravid og at Messias skulle bli f\u00f8dt av henne.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Her finner vi en veldig viktig detalj som vi allerede har lest i Johannesevangeliet: Jesus Kristus begynte ikke \u00e5 eksistere f\u00f8rst da Den Hellige \u00c5nd kom over Maria, og Den H\u00f8yestes kraft overskygget henne.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Vi har l\u00e6rt at Jesus Kristus ikke har noen begynnelse, og b\u00e5de i Johannesevangeliet og i Paulus' brev f\u00e5r vi vite at Jesus allerede var til stede da jorden ble skapt. Da han kom ned til jorden, tok han menneskelig skikkelse. Johannes gj\u00f8r det klart i sitt brev at enhver som ikke bekjenner at Jesus Kristus er kommet i kj\u00f8tt og blod, er en bedrager og Antikrist \u2013 Guds fiende.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>N\u00e5r vi ser oss rundt p\u00e5 jorden:<br>Vi ser stallen, Maria og Josef, og det lille Jesusbarnet i krybben. Men hvis vi ikke bekjenner at dette lille barnet kom fra himmelen, er vi bedragere og ikke Guds barn. I dag reduserer mange mennesker julen til julenissen, som ikke har noe som helst \u00e5 gj\u00f8re med julens egentlige budskap.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Maria aksepterte engelens budskap om at hun skulle bli Messias\u2019 mor uten \u00e5 sp\u00f8rre hva som ville skje med henne dersom hennes forlovede oppdaget at hun var gravid. Hun overlot alle sine bekymringer og sp\u00f8rsm\u00e5l til Gud, som alltid har en perfekt plan.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La oss g\u00e5 videre med historien i Matteusevangeliet: Mens Josef vurderte \u00e5 forlate Maria i hemmelighet, sendte Gud en engel som talte til ham i en dr\u00f8m og sa at han skulle ta Maria til seg og leve med henne. S\u00e5 giftet de seg, men Josef r\u00f8rte henne ikke f\u00f8r Jesus var f\u00f8dt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Etter Jesu f\u00f8dsel levde de et normalt ekteskap med flere barn, ikke bare Jesus.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Det interessante med denne delen av historien er at Gud ga instruksjonene til Josef, ikke til Maria, om hva de skulle gj\u00f8re og hva som ville skje. I et hjem er det alltid mannen \u2013 ektemannen \u2013 som har hovedansvaret, og derfor talte Gud til Josef om hva han skulle gj\u00f8re med Maria, og senere om at de skulle flykte til Egypt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Vi vender tilbake til Lukasevangeliet, hvor vi f\u00e5r mer informasjon om natten da Jesus ble f\u00f8dt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>I de gamle profetiene sto det skrevet at Messias skulle bli f\u00f8dt i Betlehem. Josef og Maria kom fra Nasaret i Galilea, men akkurat da Messias skulle bli f\u00f8dt, ble det holdt en folketelling i Betlehem. Josef og Maria m\u00e5tte reise dit for \u00e5 registrere seg, fordi de var etterkommere av kong David.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Det var ingen plass p\u00e5 herberget, s\u00e5 Maria m\u00e5tte f\u00f8de i en stall, og Jesus ble lagt i en krybbe.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>For det f\u00f8rste viser dette hvor ydmyk Gud var; for det andre var Jesus Guds lam, og han befant seg i en stall, som de andre sauene som var blitt f\u00f8rt ut.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sauen var ute p\u00e5 marken med gjeterne sine, og da englene forkynte Messias\u2019 f\u00f8dsel med ordene: \u00ab\u00c6re v\u00e6re Gud i det h\u00f8yeste, og fred p\u00e5 jorden blant mennesker som har Guds velbehag!\u00bb, dro de til stallen for \u00e5 se hva som hadde skjedd. De s\u00e5 den lille familien og Messias i krybben, og vendte tilbake mens de lovpriste Gud for det som hadde skjedd.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>N\u00e5 er det opp til oss: Vil vi ta imot denne Messias som v\u00e5r personlige frelser, bli et Guds barn og leve i lyset, selv om vi aldri vil bli fullkomne her p\u00e5 jorden? Eller vil vi forbli i m\u00f8rket og vende ryggen til den nyf\u00f8dte Jesus, som 30 \u00e5r senere d\u00f8de for oss p\u00e5 korset som Guds lam som tar bort verdens synd?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","_nb_post_name":"","_nb_post_excerpt":"","_nb_post_title":"Julprogrammet 2024","edit_language":"de","episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","iawp_total_views":95,"footnotes":""},"categories":[25],"tags":[42,43],"series":[37],"class_list":["post-957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcaststrans","tag-deutsch","tag-neu","series-bibelstudy-podcast-luke"],"episode_featured_image":"https:\/\/loveforasia.org\/wp-content\/uploads\/2024\/12\/OIG3.TVs_uAa2wAGv7azRANUs.jpg","episode_player_image":"https:\/\/loveforasia.org\/wp-content\/uploads\/2025\/09\/unnamed48.png","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"}},"rssFeedUrl":"https:\/\/loveforasia.org\/de\/feed\/podcast\/bibelstudy-podcast-luke","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"eUVFalLAxR\"><a href=\"https:\/\/loveforasia.org\/de\/christmas-special\/\">Weihnachtsprogramm 2024<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/loveforasia.org\/de\/christmas-special\/embed\/#?secret=eUVFalLAxR\" width=\"500\" height=\"350\" title=\"&#8222;Weihnachtsprogramm 2024&#8220; &#8211; Love for Asia\" data-secret=\"eUVFalLAxR\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/loveforasia.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts\/957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/comments?post=957"}],"version-history":[{"count":6,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts\/957\/revisions"}],"predecessor-version":[{"id":966,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/posts\/957\/revisions\/966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/media\/959"}],"wp:attachment":[{"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/media?parent=957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/categories?post=957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/tags?post=957"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/loveforasia.org\/de\/wp-json\/wp\/v2\/series?post=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}