{"id":130,"date":"2023-07-29T23:44:37","date_gmt":"2023-07-29T23:44:37","guid":{"rendered":"https:\/\/loveforasia.org\/?p=130"},"modified":"2025-09-16T16:11:11","modified_gmt":"2025-09-16T16:11:11","slug":"","status":"publish","type":"post","link":"https:\/\/loveforasia.org\/zh\/jesus-has-changed-my-life\/","title":{"rendered":"Jesus has changed my life - CN ","raw":"Jesus has changed my life - CN "},"content":{"rendered":"<div id=\"1633078940\" class=\"castos-player dark-mode \" tabindex=\"0\" data-episode=\"507\" data-player_id=\"1633078940\">\n\t<div class=\"player\">\n\t\t<div class=\"player__main\">\n\t\t\t<div class=\"player__artwork player__artwork-507\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/loveforasia.org\/wp-content\/uploads\/2025\/12\/Copilot_20251213_203533-150x150.png\"\n\t\t\t\t\t alt=\"Kiki and Ingrid\"\n\t\t\t\t\t title=\"Kiki and Ingrid\">\n\t\t\t<\/div>\n\t\t\t<div class=\"player__body\">\n\t\t\t\t<div class=\"currently-playing\">\n\t\t\t\t\t<div class=\"show player__podcast-title\">\n\t\t\t\t\t\tKiki and Ingrid\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"episode-title player__episode-title\">Jesus has changed my life<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"play-progress\">\n\t\t\t\t\t<div class=\"play-pause-controls\">\n\t\t\t\t\t\t<button title=\"Play\" aria-label=\"Play Episode\" aria-pressed=\"false\" class=\"play-btn\">\n\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Play Episode<\/span>\n\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<button title=\"Pause\" aria-label=\"Pause Episode\" aria-pressed=\"false\" class=\"pause-btn hide\">\n\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Pause Episode<\/span>\n\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/loveforasia.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/css\/images\/player\/images\/icon-loader.svg\" alt=\"Loading\" class=\"ssp-loader hide\"\/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div>\n\t\t\t\t\t\t<audio preload=\"none\" class=\"clip clip-507\">\n\t\t\t\t\t\t\t<source src=\"https:\/\/loveforasia.org\/wp-content\/uploads\/2023\/12\/Podcast-Jesus-has-changed-my-life.mp3\">\n\t\t\t\t\t\t<\/audio>\n\t\t\t\t\t\t<div class=\"ssp-progress\" role=\"progressbar\" title=\"Seek\" aria-valuenow=\"0\" aria-valuemin=\"0\" aria-valuemax=\"1543\">\n\t\t\t\t\t\t\t<span class=\"progress__filled\"><\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ssp-playback playback\">\n\t\t\t\t\t\t\t<div class=\"playback__controls\">\n\t\t\t\t\t\t\t\t<button class=\"player-btn player-btn__volume\" title=\"Mute\/Unmute\">\n\t\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Mute\/Unmute Episode<\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button data-skip=\"-10\" class=\"player-btn player-btn__rwd\" title=\"Rewind 10 seconds\">\n\t\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Rewind 10 Seconds<\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t<button data-speed=\"1\" class=\"player-btn player-btn__speed\" title=\"Playback Speed\" aria-label=\"Playback Speed\">1x<\/button>\n\t\t\t\t\t\t\t\t<button data-skip=\"30\" class=\"player-btn player-btn__fwd\" title=\"Fast Forward 30 seconds\">\n\t\t\t\t\t\t\t\t\t<span class=\"screen-reader-text\">Fast Forward 30 seconds<\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"playback__timers\">\n\t\t\t\t\t\t\t\t<time class=\"ssp-timer\">00:00<\/time>\n\t\t\t\t\t\t\t\t<span>\/<\/span>\n\t\t\t\t\t\t\t\t<!-- We need actual duration here from the server -->\n\t\t\t\t\t\t\t\t<time class=\"ssp-duration\" datetime=\"PT0H25M43S\">25:43<\/time>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<nav class=\"player-panels-nav\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"subscribe-btn\" id=\"subscribe-btn-507\" title=\"Subscribe\">Subscribe<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class=\"share-btn\" id=\"share-btn-507\" title=\"Share\">Share<\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/nav>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<div class=\"player-panels player-panels-507\">\n\t\t\t\t\t\t\t<div class=\"subscribe player-panel subscribe-507\">\n\t\t\t\t\t<div class=\"close-btn close-btn-507\">\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"panel__inner\">\n\t\t\t\t\t\t<div class=\"subscribe-icons\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"player-panel-row\" aria-label=\"RSS Feed URL\">\n\t\t\t\t\t\t\t<div class=\"title\">RSS Feed<\/div>\n\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t<input value=\"https:\/\/loveforasia.org\/zh\/feed\/podcast\/kikiandingrid\" class=\"input-rss input-rss-507\" title=\"RSS Feed URL\" readonly \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<button class=\"copy-rss copy-rss-507\" title=\"Copy RSS Feed URL\" aria-label=\"Copy RSS Feed URL\"><\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"share share-507 player-panel\">\n\t\t\t\t\t<div class=\"close-btn close-btn-507\">\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"player-panel-row\">\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\tShare\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"icons-holder\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/loveforasia.org\/zh\/podcast\/jesus-has-changed-my-life\/&#038;t=Jesus has changed my life\"\n\t\t\t\t\t\t\t   target=\"_blank\" rel=\"noopener noreferrer\" class=\"share-icon facebook\" title=\"Share on Facebook\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/intent\/tweet?text=https:\/\/loveforasia.org\/zh\/podcast\/jesus-has-changed-my-life\/&#038;url=Jesus has changed my life\"\n\t\t\t\t\t\t\t   target=\"_blank\" rel=\"noopener noreferrer\" class=\"share-icon twitter\" title=\"Share on Twitter\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a href=\"https:\/\/loveforasia.org\/wp-content\/uploads\/2023\/12\/Podcast-Jesus-has-changed-my-life.mp3\"\n\t\t\t\t\t\t\t   target=\"_blank\" rel=\"noopener noreferrer\" class=\"share-icon download\" title=\"Download\" download>\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"player-panel-row\">\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\tLink\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<input value=\"https:\/\/loveforasia.org\/zh\/podcast\/jesus-has-changed-my-life\/\" class=\"input-link input-link-507\" title=\"Episode URL\" readonly \/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<button class=\"copy-link copy-link-507\" title=\"Copy Episode URL\" aria-label=\"Copy Episode URL\" readonly=\"\"><\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"player-panel-row\">\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\tEmbed\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"height: 10px;\">\n\t\t\t\t\t\t\t<input type=\"text\" value='&lt;blockquote class=&quot;wp-embedded-content&quot; data-secret=&quot;QIgUs5rRzw&quot;&gt;&lt;a href=&quot;https:\/\/loveforasia.org\/zh\/podcast\/jesus-has-changed-my-life\/&quot;&gt;Jesus has changed my life&lt;\/a&gt;&lt;\/blockquote&gt;&lt;iframe sandbox=&quot;allow-scripts&quot; security=&quot;restricted&quot; src=&quot;https:\/\/loveforasia.org\/zh\/podcast\/jesus-has-changed-my-life\/embed\/#?secret=QIgUs5rRzw&quot; width=&quot;500&quot; height=&quot;350&quot; title=&quot;\u300a Jesus has changed my life \u300b\u2014Love for Asia&quot; data-secret=&quot;QIgUs5rRzw&quot; frameborder=&quot;0&quot; marginwidth=&quot;0&quot; marginheight=&quot;0&quot; scrolling=&quot;no&quot; class=&quot;wp-embedded-content&quot;&gt;&lt;\/iframe&gt;&lt;script&gt;\n\/*! This file is auto-generated *\/\n!function(d,l){&quot;use strict&quot;;l.querySelector&amp;&amp;d.addEventListener&amp;&amp;&quot;undefined&quot;!=typeof URL&amp;&amp;(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&amp;&amp;!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll(&#039;iframe[data-secret=&quot;&#039;+t.secret+&#039;&quot;]&#039;),o=l.querySelectorAll(&#039;blockquote[data-secret=&quot;&#039;+t.secret+&#039;&quot;]&#039;),c=new RegExp(&quot;^https?:$&quot;,&quot;i&quot;),i=0;i&lt;o.length;i++)o[i].style.display=&quot;none&quot;;for(i=0;i&lt;a.length;i++)s=a[i],e.source===s.contentWindow&amp;&amp;(s.removeAttribute(&quot;style&quot;),&quot;height&quot;===t.message?(1e3&lt;(r=parseInt(t.value,10))?r=1e3:~~r&lt;200&amp;&amp;(r=200),s.height=r):&quot;link&quot;===t.message&amp;&amp;(r=new URL(s.getAttribute(&quot;src&quot;)),n=new URL(t.value),c.test(n.protocol))&amp;&amp;n.host===r.host&amp;&amp;l.activeElement===s&amp;&amp;(d.top.location.href=t.value))}},d.addEventListener(&quot;message&quot;,d.wp.receiveEmbedMessage,!1),l.addEventListener(&quot;DOMContentLoaded&quot;,function(){for(var e,t,s=l.querySelectorAll(&quot;iframe.wp-embedded-content&quot;),r=0;r&lt;s.length;r++)(t=(e=s[r]).getAttribute(&quot;data-secret&quot;))||(t=Math.random().toString(36).substring(2,12),e.src+=&quot;#?secret=&quot;+t,e.setAttribute(&quot;data-secret&quot;,t)),e.contentWindow.postMessage({message:&quot;ready&quot;,secret:t},&quot;*&quot;)},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/loveforasia.org\/wp-includes\/js\/wp-embed.min.js\n&lt;\/script&gt;\n'\n\t\t\t\t\t\t\t\t   title=\"Embed Code\"\n\t\t\t\t\t\t\t\t   class=\"input-embed input-embed-507\" readonly\/>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<button class=\"copy-embed copy-embed-507\" title=\"Copy Embed Code\" aria-label=\"Copy Embed Code\"><\/button>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\n\t\n\n\t<\/div>\n<div class=\"podcast_meta\"><aside><p><a href=\"https:\/\/loveforasia.org\/podcast-download\/507\/jesus-has-changed-my-life?ref=download\" title=\"Jesus has changed my life - CN  \" class=\"podcast-meta-download\">Download file<\/a> | <a href=\"https:\/\/loveforasia.org\/podcast-download\/507\/jesus-has-changed-my-life?ref=new_window\" target=\"_blank\" title=\"Jesus has changed my life - CN  \" class=\"podcast-meta-new-window\">Play in new window<\/a> | <span class=\"podcast-meta-duration\">Duration: 25:43<\/span> | <span class=\"podcast-meta-date\">Recorded on 26 12 \u6708, 2023<\/span><\/p><\/aside><\/div>\n\n\n<p class=\"wp-block-paragraph\">\u5927\u5bb6\u597d\u6211\u662f\u4e3b\u64adkiki,\u4eca\u5929\u7ed9\u5927\u5bb6\u5206\u4eab\u7684\u662fIngrid sister\u7684\u65b0\u6b4c&lt; Jesus has changed my life&gt;. \u4e2d\u6587\u8bd1\u540d&lt;\u4e0a\u5e1d\u91cd\u5851\u4e86\u6211\u7684\u4eba\u751f&gt;.\u4ee5\u4e0b\u662f\u6211\u5bf9\u5979\u7684\u76f8\u5173\u95ee\u9898\u91c7\u8bbf\uff0c\u6b22\u8fce\u5927\u5bb6\u5728\u8bc4\u8bba\u533a\u7559\u8a00\u8ba8\u8bba\uff01<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u8036\u7a23\u5728\u4f60\u751f\u547d\u4e2d\u7684\u4e34\u5728\u5982\u4f55\u4f7f\u4f60\u5bf9\u4f60\u6240\u9886\u53d7\u7684\u795d\u798f\u66f4\u52a0\u611f\u6069?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u6211\u4eec\u8981\u505a\u7684\u7b2c\u4e00\u4ef6\u4e8b\u5c31\u662f\u610f\u8bc6\u5230\uff0c\u6211\u4eec\u5f97\u5230\u4e86\u795d\u798f\u3002\u8bb8\u591a\u4eba\u8bf4:\u6211\u5f97\u5230\u7684\u4efb\u4f55\u4e00\u4ef6\u7269\u54c1\u90fd\u662f\u901a\u8fc7\u6211\u8f9b\u52e4\u5de5\u4f5c\u6362\u6765\u7684\u3002\u7136\u540e\u6211\u8bf4:\u597d\u5427\uff0c\u4f46\u662f\u662f\u8c01\u7ed9\u4e86\u4f60\u5de5\u4f5c\u7684\u529b\u91cf\u5462?\u4e3a\u4ec0\u4e48\u4f60\u8eab\u4f53\u5065\u5eb7\uff0c\u6bcf\u5929\u90fd\u80fd\u53bb\u4e0a\u73ed?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5341\u5e74\u524d\uff0c\u6211\u75c5\u5f97\u5f88\u91cd\uff0c\u6fd2\u4e34\u6b7b\u4ea1\uff0c\u4f46\u6211\u4ece\u660f\u8ff7\u4e2d\u9192\u6765\uff0c\u6ca1\u6709\u6c38\u4e45\u6027\u7684\u8111\u635f\u4f24\uff0c\u8fd9\u662f\u4e00\u4e2a\u5947\u8ff9\u3002\u6240\u4ee5\uff0c\u5f53\u7136\uff0c\u6211\u4e0d\u4ec5\u611f\u8c22\u4e0a\u5e1d\u7684\u795d\u798f\uff0c\u6211\u8fd8\u611f\u8c22\u4e0a\u5e1d\u8ba9\u6211\u6d3b\u7740\uff0c\u8ba9\u6211\u6bcf\u5929\u65e9\u4e0a\u4e0d\u9700\u8981\u522b\u4eba\u7684\u5e2e\u52a9\u5c31\u80fd\u7ad9\u8d77\u6765\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u4f60\u4e2a\u4eba\u5728\u54ea\u4e9b\u65b9\u9762\u7ecf\u5386\u4e86\u8036\u7a23\u7684\u7231\u548c\u5bbd\u6055\u7684\u6551\u8d4e?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u4e3a\u4e86\u4f53\u9a8c\u6551\u8d4e\uff0c\u6211\u4eec\u5fc5\u987b\u610f\u8bc6\u5230\uff0c\u6211\u4eec\u9700\u8981\u4e00\u4f4d\u6551\u8d4e\u8005\u3002\u5927\u591a\u6570\u4eba\u7684\u751f\u6d3b\u5c31\u50cf\u6211\u5728\u6b4c\u4e2d\u63cf\u8ff0\u7684\u90a3\u6837\uff0c\u4ed6\u4eec\u56db\u5904\u8d70\u52a8\uff0c\u505a\u4ed6\u4eec\u7684\u4e8b\u60c5\uff0c\u60f3\u8981\u73a9\u5f97\u5f00\u5fc3\uff0c\u4f46\u6ca1\u6709\u610f\u8bc6\u5230\uff0c\u4ed6\u4eec\u751f\u6765\u6709\u7f6a\uff0c\u5e94\u8be5\u53bb\u5fcf\u6094\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u67d0\u4e00\u65f6\u523b\uff0c\u6211\u4eec\u7684\u542c\u4f17\u53ef\u4ee5\u8bf4\u662f\u5f53\u4e0b\u3002\u6211\u662f\u4e2a\u597d\u4eba\uff0c\u4e0d\u662f\u7f6a\u4eba\u3002\u4f46\u8fd9\u5c31\u662f\u8ba9\u60c5\u51b5\u53d8\u5f97\u68d8\u624b\u7684\u5730\u65b9:\u6211\u4eec\u4e0d\u77e5\u9053\u6211\u4eec\u4ec0\u4e48\u65f6\u5019\u5df2\u7136\u72af\u4e0b\u4e86\u7f6a\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u7f6a\u4e0d\u662f\u4ec5\u4ec5\u6307\u4f5c\u5bf9\u6216\u505a\u9519\u3002\u7f6a\u662f\u6211\u4eec\u4ece\u6211\u4eec\u7684\u7956\u7236\u6bcd\u4e9a\u5f53\u548c\u590f\u5a03\u90a3\u91cc\u7ee7\u627f\u6765\u7684\uff0c\u6211\u4eec\u4e0d\u80fd\u9760\u81ea\u5df1\u7684\u610f\u5fd7\u548c\u529b\u91cf\u6446\u8131\u5b83\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5f53\u6211\u4eec\u5766\u7136\u9762\u5bf9\u81ea\u5df1\u7684\u65f6\u5019\uff0c\u6211\u4eec\u4e00\u751f\u4e2d\u81f3\u5c11\u90fd\u8bf4\u8fc7\u4e00\u6b21\u8c0e\u3002\u5df2\u7ecf\u8bf4\u4e86\u4e00\u4e2a\u8c0e\u8a00\uff0c\u6211\u4eec\u5c31\u6210\u4e86\u7f6a\u4eba\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u795e\u4e0d\u80fd\u4e0e\u7f6a\u4eba\u76f8\u4ea4\uff0c\u56e0\u4e3a\u4ed6\u662f\u7edd\u5bf9\u7eaf\u6d01\u5723\u6d01\u7684\u3002\u6240\u4ee5\u6211\u4eec\u9700\u8981\u8036\u7a23\u4e3a\u6211\u4eec\u4ed8\u4e0a\u7f6a\u7684\u4ee3\u4ef7\uff0c\u4f7f\u6211\u4eec\u6709\u53ef\u80fd\u4e0e\u6c38\u751f\u7684\u795e\u76f8\u4ea4\uff0c\u5728\u8fd9\u5c18\u4e16\u7684\u751f\u6d3b\u4e4b\u540e\uff0c\u4e0d\u5fc5\u4e0b\u5730\u72f1\uff0c\u800c\u662f\u4e0a\u5929\u5802\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u4f60\u5982\u4f55\u52aa\u529b\u5728\u4f60\u5468\u56f4\u7684\u4e16\u754c\u663e\u660e\u4f60\u7684\u4fe1\u5fc3\u548c\u8036\u7a23\u5e26\u7ed9\u4f60\u751f\u547d\u7684\u6539\u53d8?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u6211\u4e0d\u5bfb\u6c42\u5411\u6211\u5468\u56f4\u7684\u4e16\u754c\u900f\u9732\u6211\u7684\u4fe1\u4ef0\uff0c\u56e0\u4e3a\u5723\u7ecf\u6559\u5bfc\uff0c\u4e0d\u8981\u4e0e\u6240\u6709\u4eba\u5206\u4eab\u3002\u5982\u679c\u6709\u4eba\u4e0d\u60f3\u63a5\u53d7\u57fa\u7763\u7684\u798f\u97f3\uff0c\u6211\u4f1a\u8ba9\u4ed6\u6216\u5979\u79bb\u5f00\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4f46\u662f\u6211\u603b\u662f\u655e\u5f00\u5fc3\u6249\u548c\u6211\u5468\u56f4\u7684\u4eba\u8c08\u8bba\u8036\u7a23\uff0c\u6211\u7559\u5fc3\u627e\u673a\u4f1a\u544a\u8bc9\u4eba\u4eec\u8036\u7a23\u57fa\u7763\u548c\u4ed6\u4e3a\u4ed6\u4eec\u6240\u505a\u7684\u4e00\u5207\u52aa\u529b\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4f46\u8fd9\u5f80\u5f80\u51fa\u4e4e\u610f\u6599\u3002\u6211\u53ea\u662f\u613f\u610f\u544a\u8bc9\uff0c\u4e0a\u5e1d\u6253\u5f00\u4e86\u4e00\u6247\u901a\u5f80\u4eba\u7684\u5fc3\u7684\u95e8\uff0c\u4ed6\u4eec\u6b63\u5728\u503e\u542c\u548c\u8be2\u95ee\u66f4\u591a\u5173\u4e8e\u798f\u97f3\u7684\u4e8b\u60c5<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u4f60\u5982\u4f55\u60f3\u8c61\u5929\u5802\u7684\u6982\u5ff5\u548c\u4e0e\u8036\u7a23\u540c\u5728\u7684\u751f\u6d3b?\u8fd9\u79cd\u5e0c\u671b\u5982\u4f55\u5851\u9020\u4f60\u5bf9\u751f\u6d3b\u7684\u770b\u6cd5?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u5929\u5802\u7684\u6982\u5ff5\u7ed9\u4e86\u6211\u751f\u547d\u7684\u610f\u4e49\u548c\u76ee\u6807\u3002\u6211\u4e0d\u5bb3\u6015\u5f53\u6211\u6b7b\u7684\u65f6\u5019\uff0c\u6211\u5fc5\u987b\u5728\u6c38\u6052\u4e2d\u5448\u73b0\u81ea\u5df1\uff0c\u56e0\u4e3a\u8036\u7a23\u5df2\u7ecf\u4e3a\u6211\u5b89\u6392\u4e86\u4e00\u5207\u3002\u4ed6\u8bf4\uff0c\u4ed6\u4f1a\u4e3a\u6211\u4eec\u5efa\u9020\u4e00\u5ea7\u6c38\u751f\u7684\u623f\u5b50\uff0c\u6709\u4e00\u5929\u6211\u8981\u53bb\u90a3\u91cc\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6709\u8da3\u7684\u662f\uff0c\u5723\u7ecf\u5e76\u6ca1\u6709\u8fc7\u591a\u5730\u8c08\u8bba\u6b7b\u4ea1\uff0c\u5373\u4f7f\u8fd9\u4e00\u5929\u4f1a\u5230\u6765\uff0c\u5b83\u66f4\u591a\u5730\u8c08\u8bba\u6c38\u751f\uff0c\u5b83\u8bf4\uff0c\u90a3\u4e9b\u4e0e\u4e0a\u5e1d\u751f\u6d3b\u5728\u4e00\u8d77\u7684\u4eba\u5c06\u4f1a\u5e74\u8f7b\uff0c\u5373\u4f7f\u4ed6\u4eec\u5df2\u7ecf\u8001\u4e86\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6240\u4ee5\uff0c\u6211\u8bd5\u7740\u6210\u4e3a\u300a\u521b\u4e16\u7eaa\u300b\u91cc\u7684\u54c8\u8bfa\u514b\u3002\u4ed6\u53ea\u662f\u4e0e\u4e0a\u5e1d\u540c\u884c\uff0c\u6709\u4e00\u5929\u4e0a\u5e1d\u628a\u4ed6\u5e26\u8d70\u4e86\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6211\u8fc7\u7740\u6211\u7684\u65e5\u5e38\u751f\u6d3b\uff0c\u7559\u5fc3\u770b\u4e0a\u5e1d\u662f\u5426\u8981\u6211\u505a\u4ec0\u4e48\uff0c\u77e5\u9053\u4ed6\u603b\u662f\u4e0e\u6211\u540c\u5728\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4f46\u662f\u5723\u7ecf\u544a\u8bc9\u6211\u4eec\uff0c\u5f53\u6211\u4eec\u4e0d\u63a5\u53d7\u8036\u7a23\u4e3a\u6211\u4eec\u7684\u6551\u4e3b\u65f6\uff0c\u6211\u4eec\u4f1a\u53bb\u53e6\u4e00\u4e2a\u5730\u65b9:\u90a3\u5c31\u662f\u706b\u6e56\uff0c\u5730\u72f1\u3002\u5b83\u73b0\u5728\u662f\u7a7a\u7684\uff0c\u4f46\u662f\u5f53\u8036\u7a23\u4f5c\u4e3a\u5ba1\u5224\u5b98\u56de\u6765\u7684\u65f6\u5019\uff0c\u6240\u6709\u6ca1\u6709\u5f97\u6551\u7684\u4eba\u90fd\u4f1a\u5728\u767d\u8272\u7684\u5b9d\u5ea7\u4e0a\u53d7\u5230\u5ba1\u5224\uff0c\u7136\u540e\u4e0b\u5730\u72f1\u3002\u6240\u4ee5\u7ecf\u4e0a\u7528\u5e0c\u4f2f\u6765\u8bed\u8bb0\u7740\u8bf4\uff0c\u4eba\u6709\u4e00\u6b7b\uff0c\u4e14\u6709\u5ba1\u5224\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u5728\u4e16\u754c\u7684\u6311\u6218\u548c\u73b0\u5b9e\u4e2d\uff0c\u4f60\u5982\u4f55\u4fdd\u6301\u4e00\u9897\u548c\u5e73\u7684\u5fc3\uff0c\u5e76\u5728\u8036\u7a23\u7684\u6559\u5bfc\u4e2d\u627e\u5230\u5b89\u6170?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u76f8\u4fe1\u8036\u7a23\u662f\u4e00\u79cd\u5173\u7cfb\u3002\u5f53\u6211\u4e0e\u8036\u7a23\u5efa\u7acb\u5173\u7cfb\u65f6\uff0c\u6211\u4e0d\u4f9d\u8d56\u522b\u4eba\u76f8\u4fe1\u6211\u6216\u5bf9\u6211\u7684\u770b\u6cd5\u3002\u56e0\u6b64\uff0c\u5982\u679c\u6709\u51b2\u7a81\uff0c\u6211\u53ef\u4ee5\u4fdd\u6301\u51b7\u9759\uff0c\u5e76\u5728\u6211\u7684\u5185\u5fc3\u5411\u8036\u7a23\u7948\u7977\uff0c\u4ed6\u5e2e\u52a9\u6211\u8d70\u51fa\u8fd9\u4e2a\u4e0d\u8212\u670d\u7684\u5904\u5883\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6211\u60f3\u8d77\u4fdd\u7f57\u66fe\u5199\u8fc7\uff0c\u6211\u4eec\u4e0d\u662f\u4e0e\u8840\u7edf\u7684\u4e89\u6218\uff0c\u4e43\u662f\u4e0e\u9ed1\u6697\u7684\u6743\u52bf\u4e89\u6218\u3002\u6240\u4ee5\uff0c\u5982\u679c\u6709\u95ee\u9898\uff0c\u6211\u9a6c\u4e0a\u539f\u8c05\u4ed6\uff0c\u8ba9\u4e0a\u5e1d\u4e3a\u6211\u89e3\u51b3\u6311\u6218\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u4f60\u91c7\u53d6\u4e86\u4ec0\u4e48\u6b65\u9aa4\u6765\u79ef\u6781\u5730\u6d3b\u51fa\u4f60\u7684\u4fe1\u4ef0\uff0c\u5e76\u4e0e\u4ed6\u4eba\u5206\u4eab\u8036\u7a23\u7684\u7231\uff0c\u7279\u522b\u662f\u5728\u4e00\u4e2a\u53ef\u80fd\u5e76\u4e0d\u603b\u662f\u63a5\u53d7\u5b83\u7684\u4e16\u754c\u91cc? (\u59d0\u59d0\uff0c\u8bf7\u7ed9\u6211\u4eec\u7684\u542c\u4f17\u670b\u53cb\u4eec\u8be6\u7ec6\u7684\u8bf4\u660e\u4e00\u4e0b\u8fd9\u4e2a\u95ee\u9898\uff0c\u8ba9\u4ed6\u4eec\u77e5\u9053\u5982\u4f55\u5728\u73b0\u5b9e\u751f\u6d3b\u4e2d\u5177\u4f53\u53bb\u5b9e\u8df5)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u4e3a\u4e86\u79ef\u6781\u5730\u6d3b\u51fa\u6211\u7684\u4fe1\u4ef0\uff0c\u6211\u5531\u6b4c\uff0c\u4e3a\u8036\u7a23\u7948\u7977\uff0c\u6211\u8bfb\u5723\u7ecf\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5f53\u6211\u4eec\u60f3\u8981\u8ba4\u8bc6\u795e\uff0c\u4ed6\u662f\u8c01\uff0c\u4ed6\u7684\u54c1\u683c\uff0c\u4ed6\u7684\u65e8\u610f\u548c\u4ed6\u4f5c\u4e3a\u4e00\u4e2a\u4eba\uff0c\u6211\u4eec\u5fc5\u987b\u8bfb\u5723\u7ecf\uff0c\u56e0\u4e3a\u5b83\u662f\u795e\u7684\u60c5\u4e66\u548c\u795e\u7ed9\u6211\u4eec\u7684\u751f\u6d3b\u624b\u518c\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6211\u5df2\u7ecf\u628a\u5723\u7ecf\u4ece\u5934\u5230\u5c3e\u8bfb\u4e86\u4e09\u904d\u4e86\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4f46\u662f\u5f53\u6211\u4eec\u8bfb\u5723\u7ecf\u65f6\uff0c\u5982\u679c\u6ca1\u6709\u5e2e\u52a9\uff0c\u6211\u4eec\u5c06\u65e0\u6cd5\u7406\u89e3\u8bb8\u591a\u4e8b\u60c5\u3002\u6240\u4ee5\uff0c\u6211\u4eec\u5fc5\u987b\u5411\u4e0a\u5e1d\u7948\u7977\uff0c\u7948\u6c42\u4ed6\u5c06\u5723\u7075\u8d50\u7ed9\u6211\u4eec\uff0c\u5e2e\u52a9\u6211\u4eec\u7406\u89e3\u4e0a\u5e1d\u8981\u901a\u8fc7\u4ed6\u7684\u8bdd\u8bed\u5bf9\u6211\u4eec\u8bf4\u7684\u8bdd\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6ca1\u6709\u5723\u7075\uff0c\u5723\u7ecf\u53ea\u662f\u795e\u5b66\uff0c\u5c31\u50cf\u6240\u6709\u5176\u4ed6\u5173\u4e8e\u5b97\u6559\u7684\u4e66\u4e00\u6837\u3002\u4f46\u6709\u4e86\u5723\u7075\uff0c\u5b83\u5c31\u53d8\u6210\u4e86\u73cd\u5b9d\u3002\u6bcf\u6b21\u4f60\u8bfb\u5b83\uff0c\u4f60\u90fd\u4f1a\u4f53\u9a8c\u5230\u65b0\u7684\u4e1c\u897f\uff0c\u8fd9\u4e2a\u8bcd\u603b\u662f\u65b0\u9c9c\u7684\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4e3a\u4e86\u7948\u7977\uff0c\u6ca1\u6709\u5fc5\u8981\u53bb\u4e00\u4e2a\u7279\u522b\u7684\u5730\u65b9\u3002\u6211\u5728\u623f\u95f4\u6216\u4efb\u4f55\u5730\u65b9\u7948\u7977\uff0c\u56e0\u4e3a\u4e0a\u5e1d\u603b\u662f\u4e0e\u6211\u540c\u5728\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5f53\u7f6a\u7684\u95ee\u9898\u89e3\u51b3\u4e86\uff0c\u6211\u5c31\u53ef\u4ee5\u968f\u65f6\u6765\u5230\u795e\u7684\u5b9d\u5ea7\u524d\uff0c\u65e0\u8bba\u4f55\u65f6\u4f55\u5730\uff0c\u4ed6\u90fd\u4f1a\u542c\u5230\u6211\u7684\u56de\u7b54\u3002\u6709\u65f6\u7b54\u6848\u662f\u5426\u5b9a\u7684\uff0c\u4f46\u4ed6\u4f1a\u542c\u5230\u6211\u7684\u6bcf\u4e00\u6b21\u7948\u7977\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u4e0e\u4ed6\u4eba\u5206\u4eab\u6211\u7684\u4fe1\u4ef0\uff0c\u5e76\u4e3a\u4ed6\u4eba\u505a\u51fa\u8d21\u732e\uff0c\u4e5f\u662f\u5728\u4e0a\u5e1d\u7684\u624b\u4e2d\u3002\u4ed6\u8bf4\uff0c\u6211\u4eec\u8981\u884c\u4ed6\u4ee5\u524d\u591a\u6b21\u4e3a\u6211\u4eec\u9884\u5907\u7684\u5584\u4e8b\u3002\u6240\u4ee5\u6211\u4eec\u53ea\u9700\u8981\u6709\u610f\u613f\u53bb\u505a\uff0c\u4e0a\u5e1d\u4f1a\u544a\u8bc9\u6211\u4eec\uff0c\u6211\u4eec\u662f\u5426\u5e94\u8be5\u9080\u8bf7\u4e00\u4e2a\u4eba\u4e0e\u6211\u4eec\u5171\u8fdb\u5348\u9910\uff0c\u6216\u8005\u652f\u6301\u4e00\u4e2a\u4f20\u6559\u58eb\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u4f60\u5177\u4f53\u628a\u4ec0\u4e48\u8363\u8000\u5f52\u4e0e\u4e86\u795e?(\u4f8b\u5982,1.2.3\u2026\u2026)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u6211\u4eec\u53ef\u4ee5\u7528\u5f88\u591a\u65b9\u6cd5\u6765\u8363\u8000\u795e:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u5c0a\u91cd\u5e76\u9075\u5b88\u4ed6\u7684\u8beb\u547d\u3002<br>\u8036\u7a23\u8bf4\uff0c\u7231\u6211\u7684\u4eba\u5fc5\u9075\u5b88\u6211\u7684\u547d\u4ee4\u3002\u5f53\u7136\uff0c\u6211\u4eec\u5f97\u6551\u662f\u56e0\u4e3a\u4fe1\u5fc3\u548c\u6069\u5178\u3002\u4f46\u8036\u7a23\u6559\u5bfc\u6211\u4eec\u5982\u4f55\u6309\u7167\u4ed6\u7684\u65e8\u610f\u751f\u6d3b\uff0c\u5f53\u6211\u4eec\u60f3\u8981\u8363\u8000\u4e0a\u5e1d\u65f6\uff0c\u6211\u4eec\u5c0a\u91cd\u4ed6\u4eec<\/li>\n\n\n\n<li>\u548c\u522b\u4eba\u8c08\u8bba\u4e0a\u5e1d<br>\u5f53\u6211\u4eec\u8c08\u8bba\u795e\u7684\u65f6\u5019\uff0c\u4ed6\u662f\u591a\u4e48\u7684\u597d\uff0c\u4ed6\u5728\u6211\u4eec\u8eab\u4e0a\u6240\u505a\u7684\u4e00\u5207\u4e5f\u662f\u628a\u8363\u8000\u5f52\u7ed9\u795e<\/li>\n\n\n\n<li>\u63a2\u8bbf\u53d7\u82e6\u7684\u4eba<br>\u4e0a\u5e1d\u8bf4\uff0c\u8fd9\u624d\u662f\u771f\u6b63\u7684\u656c\u62dc:\u53bb\u770b\u671b\u90a3\u4e9b\u5728\u82e6\u96be\u4e2d\u7684\u5be1\u5987\u548c\u5979\u4eec\u6240\u5c45\u4f4f\u7684\u8857\u9053\u3002\u5f53\u6211\u4eec\u62dc\u8bbf\u90a3\u4e9b\u751f\u6d3b\u56f0\u96be\u7684\u4eba\u65f6\uff0c\u6211\u4eec\u7ed9\u4ed6\u4eec\u5e26\u6765\u597d\u6d88\u606f\uff0c\u5373\u4f7f\u5728\u56f0\u96be\u7684\u65f6\u5019\uff0c\u4e0a\u5e1d\u4e5f\u4f1a\u7167\u987e\u4ed6\u4eec\uff0c\u4e0e\u4ed6\u4eec\u5206\u4eab\u65f6\u95f4\uff0c\u4e3a\u4ed6\u4eec\u505a\u51fa\u8d21\u732e\uff0c\u8fd9\u4e5f\u662f\u8d5e\u7f8e\u4e0a\u5e1d\u3002<\/li>\n\n\n\n<li>\u5531\u6b4c\uff0c\u5411\u4e0a\u5e1d\u7948\u7977<br>\u6211\u5199\u8fd9\u4e9b\u6b4c\u7684\u4e3b\u8981\u539f\u56e0\u662f\u4e3a\u4e86\u8363\u8000\u795e\u3002\u901a\u8fc7\u97f3\u4e50\u76f4\u63a5\u4e0e\u4e0a\u5e1d\u5bf9\u8bdd\uff0c\u5f53\u6211\u5199\u4e00\u9996\u656c\u62dc\u6b4c\u66f2\u6216\u4e0e\u4ed6\u4eba\u79ef\u6781\u8c08\u8bba\u4e0a\u5e1d\u65f6\uff0c\u5f53\u6211\u901a\u8fc7\u97f3\u4e50\u89c1\u8bc1\u4e0a\u5e1d\u7684\u5b58\u5728\u65f6\u3002<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u4eca\u5929\u7684\u8282\u76ee\u5c31\u5230\u8fd9\u91cc\uff0c\u611f\u8c22\u5927\u5bb6\u7684\u6536\u542c\uff01\u6211\u4eec\u4e0b\u671f\u518d\u4f1a\uff01<\/p>\n","protected":false,"raw":"<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"507\"} \/-->\n\n<!-- wp:paragraph -->\n<p>\u5927\u5bb6\u597d\u6211\u662f\u4e3b\u64adkiki,\u4eca\u5929\u7ed9\u5927\u5bb6\u5206\u4eab\u7684\u662fIngrid sister\u7684\u65b0\u6b4c&lt; Jesus has changed my life&gt;. \u4e2d\u6587\u8bd1\u540d&lt;\u4e0a\u5e1d\u91cd\u5851\u4e86\u6211\u7684\u4eba\u751f&gt;.\u4ee5\u4e0b\u662f\u6211\u5bf9\u5979\u7684\u76f8\u5173\u95ee\u9898\u91c7\u8bbf\uff0c\u6b22\u8fce\u5927\u5bb6\u5728\u8bc4\u8bba\u533a\u7559\u8a00\u8ba8\u8bba\uff01<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u8036\u7a23\u5728\u4f60\u751f\u547d\u4e2d\u7684\u4e34\u5728\u5982\u4f55\u4f7f\u4f60\u5bf9\u4f60\u6240\u9886\u53d7\u7684\u795d\u798f\u66f4\u52a0\u611f\u6069?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u8981\u505a\u7684\u7b2c\u4e00\u4ef6\u4e8b\u5c31\u662f\u610f\u8bc6\u5230\uff0c\u6211\u4eec\u5f97\u5230\u4e86\u795d\u798f\u3002\u8bb8\u591a\u4eba\u8bf4:\u6211\u5f97\u5230\u7684\u4efb\u4f55\u4e00\u4ef6\u7269\u54c1\u90fd\u662f\u901a\u8fc7\u6211\u8f9b\u52e4\u5de5\u4f5c\u6362\u6765\u7684\u3002\u7136\u540e\u6211\u8bf4:\u597d\u5427\uff0c\u4f46\u662f\u662f\u8c01\u7ed9\u4e86\u4f60\u5de5\u4f5c\u7684\u529b\u91cf\u5462?\u4e3a\u4ec0\u4e48\u4f60\u8eab\u4f53\u5065\u5eb7\uff0c\u6bcf\u5929\u90fd\u80fd\u53bb\u4e0a\u73ed?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5341\u5e74\u524d\uff0c\u6211\u75c5\u5f97\u5f88\u91cd\uff0c\u6fd2\u4e34\u6b7b\u4ea1\uff0c\u4f46\u6211\u4ece\u660f\u8ff7\u4e2d\u9192\u6765\uff0c\u6ca1\u6709\u6c38\u4e45\u6027\u7684\u8111\u635f\u4f24\uff0c\u8fd9\u662f\u4e00\u4e2a\u5947\u8ff9\u3002\u6240\u4ee5\uff0c\u5f53\u7136\uff0c\u6211\u4e0d\u4ec5\u611f\u8c22\u4e0a\u5e1d\u7684\u795d\u798f\uff0c\u6211\u8fd8\u611f\u8c22\u4e0a\u5e1d\u8ba9\u6211\u6d3b\u7740\uff0c\u8ba9\u6211\u6bcf\u5929\u65e9\u4e0a\u4e0d\u9700\u8981\u522b\u4eba\u7684\u5e2e\u52a9\u5c31\u80fd\u7ad9\u8d77\u6765\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u4e2a\u4eba\u5728\u54ea\u4e9b\u65b9\u9762\u7ecf\u5386\u4e86\u8036\u7a23\u7684\u7231\u548c\u5bbd\u6055\u7684\u6551\u8d4e?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u4f53\u9a8c\u6551\u8d4e\uff0c\u6211\u4eec\u5fc5\u987b\u610f\u8bc6\u5230\uff0c\u6211\u4eec\u9700\u8981\u4e00\u4f4d\u6551\u8d4e\u8005\u3002\u5927\u591a\u6570\u4eba\u7684\u751f\u6d3b\u5c31\u50cf\u6211\u5728\u6b4c\u4e2d\u63cf\u8ff0\u7684\u90a3\u6837\uff0c\u4ed6\u4eec\u56db\u5904\u8d70\u52a8\uff0c\u505a\u4ed6\u4eec\u7684\u4e8b\u60c5\uff0c\u60f3\u8981\u73a9\u5f97\u5f00\u5fc3\uff0c\u4f46\u6ca1\u6709\u610f\u8bc6\u5230\uff0c\u4ed6\u4eec\u751f\u6765\u6709\u7f6a\uff0c\u5e94\u8be5\u53bb\u5fcf\u6094\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u67d0\u4e00\u65f6\u523b\uff0c\u6211\u4eec\u7684\u542c\u4f17\u53ef\u4ee5\u8bf4\u662f\u5f53\u4e0b\u3002\u6211\u662f\u4e2a\u597d\u4eba\uff0c\u4e0d\u662f\u7f6a\u4eba\u3002\u4f46\u8fd9\u5c31\u662f\u8ba9\u60c5\u51b5\u53d8\u5f97\u68d8\u624b\u7684\u5730\u65b9:\u6211\u4eec\u4e0d\u77e5\u9053\u6211\u4eec\u4ec0\u4e48\u65f6\u5019\u5df2\u7136\u72af\u4e0b\u4e86\u7f6a\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u7f6a\u4e0d\u662f\u4ec5\u4ec5\u6307\u4f5c\u5bf9\u6216\u505a\u9519\u3002\u7f6a\u662f\u6211\u4eec\u4ece\u6211\u4eec\u7684\u7956\u7236\u6bcd\u4e9a\u5f53\u548c\u590f\u5a03\u90a3\u91cc\u7ee7\u627f\u6765\u7684\uff0c\u6211\u4eec\u4e0d\u80fd\u9760\u81ea\u5df1\u7684\u610f\u5fd7\u548c\u529b\u91cf\u6446\u8131\u5b83\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u6211\u4eec\u5766\u7136\u9762\u5bf9\u81ea\u5df1\u7684\u65f6\u5019\uff0c\u6211\u4eec\u4e00\u751f\u4e2d\u81f3\u5c11\u90fd\u8bf4\u8fc7\u4e00\u6b21\u8c0e\u3002\u5df2\u7ecf\u8bf4\u4e86\u4e00\u4e2a\u8c0e\u8a00\uff0c\u6211\u4eec\u5c31\u6210\u4e86\u7f6a\u4eba\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u795e\u4e0d\u80fd\u4e0e\u7f6a\u4eba\u76f8\u4ea4\uff0c\u56e0\u4e3a\u4ed6\u662f\u7edd\u5bf9\u7eaf\u6d01\u5723\u6d01\u7684\u3002\u6240\u4ee5\u6211\u4eec\u9700\u8981\u8036\u7a23\u4e3a\u6211\u4eec\u4ed8\u4e0a\u7f6a\u7684\u4ee3\u4ef7\uff0c\u4f7f\u6211\u4eec\u6709\u53ef\u80fd\u4e0e\u6c38\u751f\u7684\u795e\u76f8\u4ea4\uff0c\u5728\u8fd9\u5c18\u4e16\u7684\u751f\u6d3b\u4e4b\u540e\uff0c\u4e0d\u5fc5\u4e0b\u5730\u72f1\uff0c\u800c\u662f\u4e0a\u5929\u5802\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u5982\u4f55\u52aa\u529b\u5728\u4f60\u5468\u56f4\u7684\u4e16\u754c\u663e\u660e\u4f60\u7684\u4fe1\u5fc3\u548c\u8036\u7a23\u5e26\u7ed9\u4f60\u751f\u547d\u7684\u6539\u53d8?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4e0d\u5bfb\u6c42\u5411\u6211\u5468\u56f4\u7684\u4e16\u754c\u900f\u9732\u6211\u7684\u4fe1\u4ef0\uff0c\u56e0\u4e3a\u5723\u7ecf\u6559\u5bfc\uff0c\u4e0d\u8981\u4e0e\u6240\u6709\u4eba\u5206\u4eab\u3002\u5982\u679c\u6709\u4eba\u4e0d\u60f3\u63a5\u53d7\u57fa\u7763\u7684\u798f\u97f3\uff0c\u6211\u4f1a\u8ba9\u4ed6\u6216\u5979\u79bb\u5f00\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u662f\u6211\u603b\u662f\u655e\u5f00\u5fc3\u6249\u548c\u6211\u5468\u56f4\u7684\u4eba\u8c08\u8bba\u8036\u7a23\uff0c\u6211\u7559\u5fc3\u627e\u673a\u4f1a\u544a\u8bc9\u4eba\u4eec\u8036\u7a23\u57fa\u7763\u548c\u4ed6\u4e3a\u4ed6\u4eec\u6240\u505a\u7684\u4e00\u5207\u52aa\u529b\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u8fd9\u5f80\u5f80\u51fa\u4e4e\u610f\u6599\u3002\u6211\u53ea\u662f\u613f\u610f\u544a\u8bc9\uff0c\u4e0a\u5e1d\u6253\u5f00\u4e86\u4e00\u6247\u901a\u5f80\u4eba\u7684\u5fc3\u7684\u95e8\uff0c\u4ed6\u4eec\u6b63\u5728\u503e\u542c\u548c\u8be2\u95ee\u66f4\u591a\u5173\u4e8e\u798f\u97f3\u7684\u4e8b\u60c5<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u5982\u4f55\u60f3\u8c61\u5929\u5802\u7684\u6982\u5ff5\u548c\u4e0e\u8036\u7a23\u540c\u5728\u7684\u751f\u6d3b?\u8fd9\u79cd\u5e0c\u671b\u5982\u4f55\u5851\u9020\u4f60\u5bf9\u751f\u6d3b\u7684\u770b\u6cd5?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u5929\u5802\u7684\u6982\u5ff5\u7ed9\u4e86\u6211\u751f\u547d\u7684\u610f\u4e49\u548c\u76ee\u6807\u3002\u6211\u4e0d\u5bb3\u6015\u5f53\u6211\u6b7b\u7684\u65f6\u5019\uff0c\u6211\u5fc5\u987b\u5728\u6c38\u6052\u4e2d\u5448\u73b0\u81ea\u5df1\uff0c\u56e0\u4e3a\u8036\u7a23\u5df2\u7ecf\u4e3a\u6211\u5b89\u6392\u4e86\u4e00\u5207\u3002\u4ed6\u8bf4\uff0c\u4ed6\u4f1a\u4e3a\u6211\u4eec\u5efa\u9020\u4e00\u5ea7\u6c38\u751f\u7684\u623f\u5b50\uff0c\u6709\u4e00\u5929\u6211\u8981\u53bb\u90a3\u91cc\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6709\u8da3\u7684\u662f\uff0c\u5723\u7ecf\u5e76\u6ca1\u6709\u8fc7\u591a\u5730\u8c08\u8bba\u6b7b\u4ea1\uff0c\u5373\u4f7f\u8fd9\u4e00\u5929\u4f1a\u5230\u6765\uff0c\u5b83\u66f4\u591a\u5730\u8c08\u8bba\u6c38\u751f\uff0c\u5b83\u8bf4\uff0c\u90a3\u4e9b\u4e0e\u4e0a\u5e1d\u751f\u6d3b\u5728\u4e00\u8d77\u7684\u4eba\u5c06\u4f1a\u5e74\u8f7b\uff0c\u5373\u4f7f\u4ed6\u4eec\u5df2\u7ecf\u8001\u4e86\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6240\u4ee5\uff0c\u6211\u8bd5\u7740\u6210\u4e3a\u300a\u521b\u4e16\u7eaa\u300b\u91cc\u7684\u54c8\u8bfa\u514b\u3002\u4ed6\u53ea\u662f\u4e0e\u4e0a\u5e1d\u540c\u884c\uff0c\u6709\u4e00\u5929\u4e0a\u5e1d\u628a\u4ed6\u5e26\u8d70\u4e86\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u8fc7\u7740\u6211\u7684\u65e5\u5e38\u751f\u6d3b\uff0c\u7559\u5fc3\u770b\u4e0a\u5e1d\u662f\u5426\u8981\u6211\u505a\u4ec0\u4e48\uff0c\u77e5\u9053\u4ed6\u603b\u662f\u4e0e\u6211\u540c\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u662f\u5723\u7ecf\u544a\u8bc9\u6211\u4eec\uff0c\u5f53\u6211\u4eec\u4e0d\u63a5\u53d7\u8036\u7a23\u4e3a\u6211\u4eec\u7684\u6551\u4e3b\u65f6\uff0c\u6211\u4eec\u4f1a\u53bb\u53e6\u4e00\u4e2a\u5730\u65b9:\u90a3\u5c31\u662f\u706b\u6e56\uff0c\u5730\u72f1\u3002\u5b83\u73b0\u5728\u662f\u7a7a\u7684\uff0c\u4f46\u662f\u5f53\u8036\u7a23\u4f5c\u4e3a\u5ba1\u5224\u5b98\u56de\u6765\u7684\u65f6\u5019\uff0c\u6240\u6709\u6ca1\u6709\u5f97\u6551\u7684\u4eba\u90fd\u4f1a\u5728\u767d\u8272\u7684\u5b9d\u5ea7\u4e0a\u53d7\u5230\u5ba1\u5224\uff0c\u7136\u540e\u4e0b\u5730\u72f1\u3002\u6240\u4ee5\u7ecf\u4e0a\u7528\u5e0c\u4f2f\u6765\u8bed\u8bb0\u7740\u8bf4\uff0c\u4eba\u6709\u4e00\u6b7b\uff0c\u4e14\u6709\u5ba1\u5224\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u5728\u4e16\u754c\u7684\u6311\u6218\u548c\u73b0\u5b9e\u4e2d\uff0c\u4f60\u5982\u4f55\u4fdd\u6301\u4e00\u9897\u548c\u5e73\u7684\u5fc3\uff0c\u5e76\u5728\u8036\u7a23\u7684\u6559\u5bfc\u4e2d\u627e\u5230\u5b89\u6170?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u76f8\u4fe1\u8036\u7a23\u662f\u4e00\u79cd\u5173\u7cfb\u3002\u5f53\u6211\u4e0e\u8036\u7a23\u5efa\u7acb\u5173\u7cfb\u65f6\uff0c\u6211\u4e0d\u4f9d\u8d56\u522b\u4eba\u76f8\u4fe1\u6211\u6216\u5bf9\u6211\u7684\u770b\u6cd5\u3002\u56e0\u6b64\uff0c\u5982\u679c\u6709\u51b2\u7a81\uff0c\u6211\u53ef\u4ee5\u4fdd\u6301\u51b7\u9759\uff0c\u5e76\u5728\u6211\u7684\u5185\u5fc3\u5411\u8036\u7a23\u7948\u7977\uff0c\u4ed6\u5e2e\u52a9\u6211\u8d70\u51fa\u8fd9\u4e2a\u4e0d\u8212\u670d\u7684\u5904\u5883\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u60f3\u8d77\u4fdd\u7f57\u66fe\u5199\u8fc7\uff0c\u6211\u4eec\u4e0d\u662f\u4e0e\u8840\u7edf\u7684\u4e89\u6218\uff0c\u4e43\u662f\u4e0e\u9ed1\u6697\u7684\u6743\u52bf\u4e89\u6218\u3002\u6240\u4ee5\uff0c\u5982\u679c\u6709\u95ee\u9898\uff0c\u6211\u9a6c\u4e0a\u539f\u8c05\u4ed6\uff0c\u8ba9\u4e0a\u5e1d\u4e3a\u6211\u89e3\u51b3\u6311\u6218\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u91c7\u53d6\u4e86\u4ec0\u4e48\u6b65\u9aa4\u6765\u79ef\u6781\u5730\u6d3b\u51fa\u4f60\u7684\u4fe1\u4ef0\uff0c\u5e76\u4e0e\u4ed6\u4eba\u5206\u4eab\u8036\u7a23\u7684\u7231\uff0c\u7279\u522b\u662f\u5728\u4e00\u4e2a\u53ef\u80fd\u5e76\u4e0d\u603b\u662f\u63a5\u53d7\u5b83\u7684\u4e16\u754c\u91cc? (\u59d0\u59d0\uff0c\u8bf7\u7ed9\u6211\u4eec\u7684\u542c\u4f17\u670b\u53cb\u4eec\u8be6\u7ec6\u7684\u8bf4\u660e\u4e00\u4e0b\u8fd9\u4e2a\u95ee\u9898\uff0c\u8ba9\u4ed6\u4eec\u77e5\u9053\u5982\u4f55\u5728\u73b0\u5b9e\u751f\u6d3b\u4e2d\u5177\u4f53\u53bb\u5b9e\u8df5)<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u79ef\u6781\u5730\u6d3b\u51fa\u6211\u7684\u4fe1\u4ef0\uff0c\u6211\u5531\u6b4c\uff0c\u4e3a\u8036\u7a23\u7948\u7977\uff0c\u6211\u8bfb\u5723\u7ecf\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u6211\u4eec\u60f3\u8981\u8ba4\u8bc6\u795e\uff0c\u4ed6\u662f\u8c01\uff0c\u4ed6\u7684\u54c1\u683c\uff0c\u4ed6\u7684\u65e8\u610f\u548c\u4ed6\u4f5c\u4e3a\u4e00\u4e2a\u4eba\uff0c\u6211\u4eec\u5fc5\u987b\u8bfb\u5723\u7ecf\uff0c\u56e0\u4e3a\u5b83\u662f\u795e\u7684\u60c5\u4e66\u548c\u795e\u7ed9\u6211\u4eec\u7684\u751f\u6d3b\u624b\u518c\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u5df2\u7ecf\u628a\u5723\u7ecf\u4ece\u5934\u5230\u5c3e\u8bfb\u4e86\u4e09\u904d\u4e86\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u662f\u5f53\u6211\u4eec\u8bfb\u5723\u7ecf\u65f6\uff0c\u5982\u679c\u6ca1\u6709\u5e2e\u52a9\uff0c\u6211\u4eec\u5c06\u65e0\u6cd5\u7406\u89e3\u8bb8\u591a\u4e8b\u60c5\u3002\u6240\u4ee5\uff0c\u6211\u4eec\u5fc5\u987b\u5411\u4e0a\u5e1d\u7948\u7977\uff0c\u7948\u6c42\u4ed6\u5c06\u5723\u7075\u8d50\u7ed9\u6211\u4eec\uff0c\u5e2e\u52a9\u6211\u4eec\u7406\u89e3\u4e0a\u5e1d\u8981\u901a\u8fc7\u4ed6\u7684\u8bdd\u8bed\u5bf9\u6211\u4eec\u8bf4\u7684\u8bdd\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6ca1\u6709\u5723\u7075\uff0c\u5723\u7ecf\u53ea\u662f\u795e\u5b66\uff0c\u5c31\u50cf\u6240\u6709\u5176\u4ed6\u5173\u4e8e\u5b97\u6559\u7684\u4e66\u4e00\u6837\u3002\u4f46\u6709\u4e86\u5723\u7075\uff0c\u5b83\u5c31\u53d8\u6210\u4e86\u73cd\u5b9d\u3002\u6bcf\u6b21\u4f60\u8bfb\u5b83\uff0c\u4f60\u90fd\u4f1a\u4f53\u9a8c\u5230\u65b0\u7684\u4e1c\u897f\uff0c\u8fd9\u4e2a\u8bcd\u603b\u662f\u65b0\u9c9c\u7684\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u7948\u7977\uff0c\u6ca1\u6709\u5fc5\u8981\u53bb\u4e00\u4e2a\u7279\u522b\u7684\u5730\u65b9\u3002\u6211\u5728\u623f\u95f4\u6216\u4efb\u4f55\u5730\u65b9\u7948\u7977\uff0c\u56e0\u4e3a\u4e0a\u5e1d\u603b\u662f\u4e0e\u6211\u540c\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u7f6a\u7684\u95ee\u9898\u89e3\u51b3\u4e86\uff0c\u6211\u5c31\u53ef\u4ee5\u968f\u65f6\u6765\u5230\u795e\u7684\u5b9d\u5ea7\u524d\uff0c\u65e0\u8bba\u4f55\u65f6\u4f55\u5730\uff0c\u4ed6\u90fd\u4f1a\u542c\u5230\u6211\u7684\u56de\u7b54\u3002\u6709\u65f6\u7b54\u6848\u662f\u5426\u5b9a\u7684\uff0c\u4f46\u4ed6\u4f1a\u542c\u5230\u6211\u7684\u6bcf\u4e00\u6b21\u7948\u7977\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4e0e\u4ed6\u4eba\u5206\u4eab\u6211\u7684\u4fe1\u4ef0\uff0c\u5e76\u4e3a\u4ed6\u4eba\u505a\u51fa\u8d21\u732e\uff0c\u4e5f\u662f\u5728\u4e0a\u5e1d\u7684\u624b\u4e2d\u3002\u4ed6\u8bf4\uff0c\u6211\u4eec\u8981\u884c\u4ed6\u4ee5\u524d\u591a\u6b21\u4e3a\u6211\u4eec\u9884\u5907\u7684\u5584\u4e8b\u3002\u6240\u4ee5\u6211\u4eec\u53ea\u9700\u8981\u6709\u610f\u613f\u53bb\u505a\uff0c\u4e0a\u5e1d\u4f1a\u544a\u8bc9\u6211\u4eec\uff0c\u6211\u4eec\u662f\u5426\u5e94\u8be5\u9080\u8bf7\u4e00\u4e2a\u4eba\u4e0e\u6211\u4eec\u5171\u8fdb\u5348\u9910\uff0c\u6216\u8005\u652f\u6301\u4e00\u4e2a\u4f20\u6559\u58eb\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u5177\u4f53\u628a\u4ec0\u4e48\u8363\u8000\u5f52\u4e0e\u4e86\u795e?(\u4f8b\u5982,1.2.3\u2026\u2026)<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u53ef\u4ee5\u7528\u5f88\u591a\u65b9\u6cd5\u6765\u8363\u8000\u795e:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>\u5c0a\u91cd\u5e76\u9075\u5b88\u4ed6\u7684\u8beb\u547d\u3002<br>\u8036\u7a23\u8bf4\uff0c\u7231\u6211\u7684\u4eba\u5fc5\u9075\u5b88\u6211\u7684\u547d\u4ee4\u3002\u5f53\u7136\uff0c\u6211\u4eec\u5f97\u6551\u662f\u56e0\u4e3a\u4fe1\u5fc3\u548c\u6069\u5178\u3002\u4f46\u8036\u7a23\u6559\u5bfc\u6211\u4eec\u5982\u4f55\u6309\u7167\u4ed6\u7684\u65e8\u610f\u751f\u6d3b\uff0c\u5f53\u6211\u4eec\u60f3\u8981\u8363\u8000\u4e0a\u5e1d\u65f6\uff0c\u6211\u4eec\u5c0a\u91cd\u4ed6\u4eec<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u548c\u522b\u4eba\u8c08\u8bba\u4e0a\u5e1d<br>\u5f53\u6211\u4eec\u8c08\u8bba\u795e\u7684\u65f6\u5019\uff0c\u4ed6\u662f\u591a\u4e48\u7684\u597d\uff0c\u4ed6\u5728\u6211\u4eec\u8eab\u4e0a\u6240\u505a\u7684\u4e00\u5207\u4e5f\u662f\u628a\u8363\u8000\u5f52\u7ed9\u795e<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u63a2\u8bbf\u53d7\u82e6\u7684\u4eba<br>\u4e0a\u5e1d\u8bf4\uff0c\u8fd9\u624d\u662f\u771f\u6b63\u7684\u656c\u62dc:\u53bb\u770b\u671b\u90a3\u4e9b\u5728\u82e6\u96be\u4e2d\u7684\u5be1\u5987\u548c\u5979\u4eec\u6240\u5c45\u4f4f\u7684\u8857\u9053\u3002\u5f53\u6211\u4eec\u62dc\u8bbf\u90a3\u4e9b\u751f\u6d3b\u56f0\u96be\u7684\u4eba\u65f6\uff0c\u6211\u4eec\u7ed9\u4ed6\u4eec\u5e26\u6765\u597d\u6d88\u606f\uff0c\u5373\u4f7f\u5728\u56f0\u96be\u7684\u65f6\u5019\uff0c\u4e0a\u5e1d\u4e5f\u4f1a\u7167\u987e\u4ed6\u4eec\uff0c\u4e0e\u4ed6\u4eec\u5206\u4eab\u65f6\u95f4\uff0c\u4e3a\u4ed6\u4eec\u505a\u51fa\u8d21\u732e\uff0c\u8fd9\u4e5f\u662f\u8d5e\u7f8e\u4e0a\u5e1d\u3002<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u5531\u6b4c\uff0c\u5411\u4e0a\u5e1d\u7948\u7977<br>\u6211\u5199\u8fd9\u4e9b\u6b4c\u7684\u4e3b\u8981\u539f\u56e0\u662f\u4e3a\u4e86\u8363\u8000\u795e\u3002\u901a\u8fc7\u97f3\u4e50\u76f4\u63a5\u4e0e\u4e0a\u5e1d\u5bf9\u8bdd\uff0c\u5f53\u6211\u5199\u4e00\u9996\u656c\u62dc\u6b4c\u66f2\u6216\u4e0e\u4ed6\u4eba\u79ef\u6781\u8c08\u8bba\u4e0a\u5e1d\u65f6\uff0c\u5f53\u6211\u901a\u8fc7\u97f3\u4e50\u89c1\u8bc1\u4e0a\u5e1d\u7684\u5b58\u5728\u65f6\u3002<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>\u4eca\u5929\u7684\u8282\u76ee\u5c31\u5230\u8fd9\u91cc\uff0c\u611f\u8c22\u5927\u5bb6\u7684\u6536\u542c\uff01\u6211\u4eec\u4e0b\u671f\u518d\u4f1a\uff01<\/p>\n<!-- \/wp:paragraph -->"},"excerpt":{"rendered":"","protected":false,"raw":""},"author":1,"featured_media":137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_en_post_content":"<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"0\"} \/-->\n\n<!-- wp:paragraph -->\n<p><strong>Jesus Has Changed My Life<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus has changed my life,<br>Jesus has changed my life,<br>Jesus has changed my life\u2014<br>I give him glory.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus has changed my life,<br>Jesus has changed my life,<br>Jesus has changed my life\u2014<br>I give him praise.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Once I was a sinner,<br>but I was unaware.<br>I was just out for fun,<br>to comfort me at night.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>But the fun of the night<br>was followed by emptiness,<br>and I felt hunger for more life.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Once I was a sinner,<br>but I was unaware.<br>When I hurt the people<br>that surrounded me,<br>being hurt myself<br>made me unrighteous\u2014<br>until that day<br>when Jesus saved me.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Once I was a sinner,<br>and now I am aware<br>that Jesus is the one<br>who gives me joy and life.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>And his blessing each day<br>brings healing to all suffering.<br>His Spirit and love<br>comfort me.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Interview (Auswahl Korrekturen)<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>Q:<\/strong> How has Jesus\u2019 presence in your life made you more thankful for the blessings you have received?<br><strong>A:<\/strong> The first thing we have to do is be aware that we have received a blessing. Many people say: <em>\u201cI got my goods and what I have through my hard work.\u201d<\/em> Then I say: <em>\u201cOk, but who gave you the strength to work? Why are you healthy and able to go to work each day?\u201d<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2026I was very sick 10 years ago and at the point of dying, but I awoke from the coma without permanent brain damage, which was a miracle. So of course, I am thankful not only for the blessings; I am thankful that God allows me to live and to get up each morning without help from others.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Q:<\/strong> In what ways have you personally experienced redemption through Jesus\u2019 love and forgiveness?<br><strong>A:<\/strong> To experience redemption, it is necessary to be aware that we need a redeemer. Most people live as I described in my song: they walk around, do their things, want to have fun, but are not aware that they have sin in their lives and need to repent.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2026When we are honest, we all have told a lie once in our life. And already telling one single lie makes us sinners.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>God cannot have fellowship with a sinner, because he is absolutely pure and holy. So we need Jesus to pay the price of sin for us and make it possible to have fellowship with the living God and not go to hell, but to heaven after this life on earth.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Q:<\/strong> How do you strive to reveal your faith and the transformation Jesus has brought to your life in the world around you?<br><strong>A:<\/strong> I don\u2019t seek to reveal my faith to the world around me, because the Bible teaches us not to share with everybody. When somebody does not want to receive the gospel of Christ, I let him or her go.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>But I am always open to talk about Jesus with the people around me, and I watch for an opportunity to tell them about Jesus Christ and the work that he has done for them on Calvary.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Q:<\/strong> How do you envision the concept of paradise and living in the presence of Jesus? How does this hope shape your perspective on life?<br><strong>A:<\/strong> The concept of paradise gives meaning and direction to my life. I don\u2019t fear what will happen when I die and enter eternity, since Jesus has arranged everything for me. He said he will build a house for us in eternal life, and one day I will go there.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2026So, I try to be like Enoch in the book of Genesis. He just walked with God, and one day God took him away.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Q:<\/strong> What steps do you take to actively live out your faith and share the love of Jesus with others?<br><strong>A:<\/strong> To live out my faith actively, I sing and pray to Jesus and I read the Bible.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>When we want to know God\u2014who he is, his character, his will, and him as a person\u2014we have to read the Bible, because it is God\u2019s love letter and manual about life for us.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2026I have already read the Bible at least 3 times from beginning to end.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u2026Without the Holy Spirit, the Bible is only theology, like any other religious book. But with the Holy Spirit, it becomes a treasure. Every time you read it, you experience new things, and the Word is always fresh.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:separator -->\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<!-- \/wp:separator -->\n\n<!-- wp:paragraph -->\n<p><strong>Q:<\/strong> What exact glory did you give to God?<br><strong>A:<\/strong> There are many ways we can give glory to God:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Respecting and keeping his commandments.<\/strong> Jesus said: <em>Those who love me will keep my commandments.<\/em> Of course, we are saved by faith and grace, but Jesus taught us how to live according to his will, and when we want to give glory to God, we respect them.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Talking about God to other people.<\/strong> When we talk about God, how good he is and what he has done for us, that is giving glory to God too.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Visiting people who suffer.<\/strong> God says this is true worship: to visit widows and orphans in their affliction.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Singing and praying to God.<\/strong> The main reason why I have written these songs is to give glory to God. Through music, I can talk directly to God in worship songs or testify to others that God exists.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->","_en_post_name":"jesus-has-changed-my-life","_en_post_excerpt":"","_en_post_title":"Jesus has changed my life","_zh_post_content":"<!-- wp:seriously-simple-podcasting\/castos-html-player {\"episodeId\":\"507\"} \/-->\n\n<!-- wp:paragraph -->\n<p>\u5927\u5bb6\u597d\u6211\u662f\u4e3b\u64adkiki,\u4eca\u5929\u7ed9\u5927\u5bb6\u5206\u4eab\u7684\u662fIngrid sister\u7684\u65b0\u6b4c&lt; Jesus has changed my life&gt;. \u4e2d\u6587\u8bd1\u540d&lt;\u4e0a\u5e1d\u91cd\u5851\u4e86\u6211\u7684\u4eba\u751f&gt;.\u4ee5\u4e0b\u662f\u6211\u5bf9\u5979\u7684\u76f8\u5173\u95ee\u9898\u91c7\u8bbf\uff0c\u6b22\u8fce\u5927\u5bb6\u5728\u8bc4\u8bba\u533a\u7559\u8a00\u8ba8\u8bba\uff01<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u8036\u7a23\u5728\u4f60\u751f\u547d\u4e2d\u7684\u4e34\u5728\u5982\u4f55\u4f7f\u4f60\u5bf9\u4f60\u6240\u9886\u53d7\u7684\u795d\u798f\u66f4\u52a0\u611f\u6069?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u8981\u505a\u7684\u7b2c\u4e00\u4ef6\u4e8b\u5c31\u662f\u610f\u8bc6\u5230\uff0c\u6211\u4eec\u5f97\u5230\u4e86\u795d\u798f\u3002\u8bb8\u591a\u4eba\u8bf4:\u6211\u5f97\u5230\u7684\u4efb\u4f55\u4e00\u4ef6\u7269\u54c1\u90fd\u662f\u901a\u8fc7\u6211\u8f9b\u52e4\u5de5\u4f5c\u6362\u6765\u7684\u3002\u7136\u540e\u6211\u8bf4:\u597d\u5427\uff0c\u4f46\u662f\u662f\u8c01\u7ed9\u4e86\u4f60\u5de5\u4f5c\u7684\u529b\u91cf\u5462?\u4e3a\u4ec0\u4e48\u4f60\u8eab\u4f53\u5065\u5eb7\uff0c\u6bcf\u5929\u90fd\u80fd\u53bb\u4e0a\u73ed?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5341\u5e74\u524d\uff0c\u6211\u75c5\u5f97\u5f88\u91cd\uff0c\u6fd2\u4e34\u6b7b\u4ea1\uff0c\u4f46\u6211\u4ece\u660f\u8ff7\u4e2d\u9192\u6765\uff0c\u6ca1\u6709\u6c38\u4e45\u6027\u7684\u8111\u635f\u4f24\uff0c\u8fd9\u662f\u4e00\u4e2a\u5947\u8ff9\u3002\u6240\u4ee5\uff0c\u5f53\u7136\uff0c\u6211\u4e0d\u4ec5\u611f\u8c22\u4e0a\u5e1d\u7684\u795d\u798f\uff0c\u6211\u8fd8\u611f\u8c22\u4e0a\u5e1d\u8ba9\u6211\u6d3b\u7740\uff0c\u8ba9\u6211\u6bcf\u5929\u65e9\u4e0a\u4e0d\u9700\u8981\u522b\u4eba\u7684\u5e2e\u52a9\u5c31\u80fd\u7ad9\u8d77\u6765\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u4e2a\u4eba\u5728\u54ea\u4e9b\u65b9\u9762\u7ecf\u5386\u4e86\u8036\u7a23\u7684\u7231\u548c\u5bbd\u6055\u7684\u6551\u8d4e?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u4f53\u9a8c\u6551\u8d4e\uff0c\u6211\u4eec\u5fc5\u987b\u610f\u8bc6\u5230\uff0c\u6211\u4eec\u9700\u8981\u4e00\u4f4d\u6551\u8d4e\u8005\u3002\u5927\u591a\u6570\u4eba\u7684\u751f\u6d3b\u5c31\u50cf\u6211\u5728\u6b4c\u4e2d\u63cf\u8ff0\u7684\u90a3\u6837\uff0c\u4ed6\u4eec\u56db\u5904\u8d70\u52a8\uff0c\u505a\u4ed6\u4eec\u7684\u4e8b\u60c5\uff0c\u60f3\u8981\u73a9\u5f97\u5f00\u5fc3\uff0c\u4f46\u6ca1\u6709\u610f\u8bc6\u5230\uff0c\u4ed6\u4eec\u751f\u6765\u6709\u7f6a\uff0c\u5e94\u8be5\u53bb\u5fcf\u6094\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u67d0\u4e00\u65f6\u523b\uff0c\u6211\u4eec\u7684\u542c\u4f17\u53ef\u4ee5\u8bf4\u662f\u5f53\u4e0b\u3002\u6211\u662f\u4e2a\u597d\u4eba\uff0c\u4e0d\u662f\u7f6a\u4eba\u3002\u4f46\u8fd9\u5c31\u662f\u8ba9\u60c5\u51b5\u53d8\u5f97\u68d8\u624b\u7684\u5730\u65b9:\u6211\u4eec\u4e0d\u77e5\u9053\u6211\u4eec\u4ec0\u4e48\u65f6\u5019\u5df2\u7136\u72af\u4e0b\u4e86\u7f6a\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u7f6a\u4e0d\u662f\u4ec5\u4ec5\u6307\u4f5c\u5bf9\u6216\u505a\u9519\u3002\u7f6a\u662f\u6211\u4eec\u4ece\u6211\u4eec\u7684\u7956\u7236\u6bcd\u4e9a\u5f53\u548c\u590f\u5a03\u90a3\u91cc\u7ee7\u627f\u6765\u7684\uff0c\u6211\u4eec\u4e0d\u80fd\u9760\u81ea\u5df1\u7684\u610f\u5fd7\u548c\u529b\u91cf\u6446\u8131\u5b83\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u6211\u4eec\u5766\u7136\u9762\u5bf9\u81ea\u5df1\u7684\u65f6\u5019\uff0c\u6211\u4eec\u4e00\u751f\u4e2d\u81f3\u5c11\u90fd\u8bf4\u8fc7\u4e00\u6b21\u8c0e\u3002\u5df2\u7ecf\u8bf4\u4e86\u4e00\u4e2a\u8c0e\u8a00\uff0c\u6211\u4eec\u5c31\u6210\u4e86\u7f6a\u4eba\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u795e\u4e0d\u80fd\u4e0e\u7f6a\u4eba\u76f8\u4ea4\uff0c\u56e0\u4e3a\u4ed6\u662f\u7edd\u5bf9\u7eaf\u6d01\u5723\u6d01\u7684\u3002\u6240\u4ee5\u6211\u4eec\u9700\u8981\u8036\u7a23\u4e3a\u6211\u4eec\u4ed8\u4e0a\u7f6a\u7684\u4ee3\u4ef7\uff0c\u4f7f\u6211\u4eec\u6709\u53ef\u80fd\u4e0e\u6c38\u751f\u7684\u795e\u76f8\u4ea4\uff0c\u5728\u8fd9\u5c18\u4e16\u7684\u751f\u6d3b\u4e4b\u540e\uff0c\u4e0d\u5fc5\u4e0b\u5730\u72f1\uff0c\u800c\u662f\u4e0a\u5929\u5802\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u5982\u4f55\u52aa\u529b\u5728\u4f60\u5468\u56f4\u7684\u4e16\u754c\u663e\u660e\u4f60\u7684\u4fe1\u5fc3\u548c\u8036\u7a23\u5e26\u7ed9\u4f60\u751f\u547d\u7684\u6539\u53d8?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4e0d\u5bfb\u6c42\u5411\u6211\u5468\u56f4\u7684\u4e16\u754c\u900f\u9732\u6211\u7684\u4fe1\u4ef0\uff0c\u56e0\u4e3a\u5723\u7ecf\u6559\u5bfc\uff0c\u4e0d\u8981\u4e0e\u6240\u6709\u4eba\u5206\u4eab\u3002\u5982\u679c\u6709\u4eba\u4e0d\u60f3\u63a5\u53d7\u57fa\u7763\u7684\u798f\u97f3\uff0c\u6211\u4f1a\u8ba9\u4ed6\u6216\u5979\u79bb\u5f00\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u662f\u6211\u603b\u662f\u655e\u5f00\u5fc3\u6249\u548c\u6211\u5468\u56f4\u7684\u4eba\u8c08\u8bba\u8036\u7a23\uff0c\u6211\u7559\u5fc3\u627e\u673a\u4f1a\u544a\u8bc9\u4eba\u4eec\u8036\u7a23\u57fa\u7763\u548c\u4ed6\u4e3a\u4ed6\u4eec\u6240\u505a\u7684\u4e00\u5207\u52aa\u529b\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u8fd9\u5f80\u5f80\u51fa\u4e4e\u610f\u6599\u3002\u6211\u53ea\u662f\u613f\u610f\u544a\u8bc9\uff0c\u4e0a\u5e1d\u6253\u5f00\u4e86\u4e00\u6247\u901a\u5f80\u4eba\u7684\u5fc3\u7684\u95e8\uff0c\u4ed6\u4eec\u6b63\u5728\u503e\u542c\u548c\u8be2\u95ee\u66f4\u591a\u5173\u4e8e\u798f\u97f3\u7684\u4e8b\u60c5<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u5982\u4f55\u60f3\u8c61\u5929\u5802\u7684\u6982\u5ff5\u548c\u4e0e\u8036\u7a23\u540c\u5728\u7684\u751f\u6d3b?\u8fd9\u79cd\u5e0c\u671b\u5982\u4f55\u5851\u9020\u4f60\u5bf9\u751f\u6d3b\u7684\u770b\u6cd5?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u5929\u5802\u7684\u6982\u5ff5\u7ed9\u4e86\u6211\u751f\u547d\u7684\u610f\u4e49\u548c\u76ee\u6807\u3002\u6211\u4e0d\u5bb3\u6015\u5f53\u6211\u6b7b\u7684\u65f6\u5019\uff0c\u6211\u5fc5\u987b\u5728\u6c38\u6052\u4e2d\u5448\u73b0\u81ea\u5df1\uff0c\u56e0\u4e3a\u8036\u7a23\u5df2\u7ecf\u4e3a\u6211\u5b89\u6392\u4e86\u4e00\u5207\u3002\u4ed6\u8bf4\uff0c\u4ed6\u4f1a\u4e3a\u6211\u4eec\u5efa\u9020\u4e00\u5ea7\u6c38\u751f\u7684\u623f\u5b50\uff0c\u6709\u4e00\u5929\u6211\u8981\u53bb\u90a3\u91cc\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6709\u8da3\u7684\u662f\uff0c\u5723\u7ecf\u5e76\u6ca1\u6709\u8fc7\u591a\u5730\u8c08\u8bba\u6b7b\u4ea1\uff0c\u5373\u4f7f\u8fd9\u4e00\u5929\u4f1a\u5230\u6765\uff0c\u5b83\u66f4\u591a\u5730\u8c08\u8bba\u6c38\u751f\uff0c\u5b83\u8bf4\uff0c\u90a3\u4e9b\u4e0e\u4e0a\u5e1d\u751f\u6d3b\u5728\u4e00\u8d77\u7684\u4eba\u5c06\u4f1a\u5e74\u8f7b\uff0c\u5373\u4f7f\u4ed6\u4eec\u5df2\u7ecf\u8001\u4e86\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6240\u4ee5\uff0c\u6211\u8bd5\u7740\u6210\u4e3a\u300a\u521b\u4e16\u7eaa\u300b\u91cc\u7684\u54c8\u8bfa\u514b\u3002\u4ed6\u53ea\u662f\u4e0e\u4e0a\u5e1d\u540c\u884c\uff0c\u6709\u4e00\u5929\u4e0a\u5e1d\u628a\u4ed6\u5e26\u8d70\u4e86\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u8fc7\u7740\u6211\u7684\u65e5\u5e38\u751f\u6d3b\uff0c\u7559\u5fc3\u770b\u4e0a\u5e1d\u662f\u5426\u8981\u6211\u505a\u4ec0\u4e48\uff0c\u77e5\u9053\u4ed6\u603b\u662f\u4e0e\u6211\u540c\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u662f\u5723\u7ecf\u544a\u8bc9\u6211\u4eec\uff0c\u5f53\u6211\u4eec\u4e0d\u63a5\u53d7\u8036\u7a23\u4e3a\u6211\u4eec\u7684\u6551\u4e3b\u65f6\uff0c\u6211\u4eec\u4f1a\u53bb\u53e6\u4e00\u4e2a\u5730\u65b9:\u90a3\u5c31\u662f\u706b\u6e56\uff0c\u5730\u72f1\u3002\u5b83\u73b0\u5728\u662f\u7a7a\u7684\uff0c\u4f46\u662f\u5f53\u8036\u7a23\u4f5c\u4e3a\u5ba1\u5224\u5b98\u56de\u6765\u7684\u65f6\u5019\uff0c\u6240\u6709\u6ca1\u6709\u5f97\u6551\u7684\u4eba\u90fd\u4f1a\u5728\u767d\u8272\u7684\u5b9d\u5ea7\u4e0a\u53d7\u5230\u5ba1\u5224\uff0c\u7136\u540e\u4e0b\u5730\u72f1\u3002\u6240\u4ee5\u7ecf\u4e0a\u7528\u5e0c\u4f2f\u6765\u8bed\u8bb0\u7740\u8bf4\uff0c\u4eba\u6709\u4e00\u6b7b\uff0c\u4e14\u6709\u5ba1\u5224\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u5728\u4e16\u754c\u7684\u6311\u6218\u548c\u73b0\u5b9e\u4e2d\uff0c\u4f60\u5982\u4f55\u4fdd\u6301\u4e00\u9897\u548c\u5e73\u7684\u5fc3\uff0c\u5e76\u5728\u8036\u7a23\u7684\u6559\u5bfc\u4e2d\u627e\u5230\u5b89\u6170?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u76f8\u4fe1\u8036\u7a23\u662f\u4e00\u79cd\u5173\u7cfb\u3002\u5f53\u6211\u4e0e\u8036\u7a23\u5efa\u7acb\u5173\u7cfb\u65f6\uff0c\u6211\u4e0d\u4f9d\u8d56\u522b\u4eba\u76f8\u4fe1\u6211\u6216\u5bf9\u6211\u7684\u770b\u6cd5\u3002\u56e0\u6b64\uff0c\u5982\u679c\u6709\u51b2\u7a81\uff0c\u6211\u53ef\u4ee5\u4fdd\u6301\u51b7\u9759\uff0c\u5e76\u5728\u6211\u7684\u5185\u5fc3\u5411\u8036\u7a23\u7948\u7977\uff0c\u4ed6\u5e2e\u52a9\u6211\u8d70\u51fa\u8fd9\u4e2a\u4e0d\u8212\u670d\u7684\u5904\u5883\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u60f3\u8d77\u4fdd\u7f57\u66fe\u5199\u8fc7\uff0c\u6211\u4eec\u4e0d\u662f\u4e0e\u8840\u7edf\u7684\u4e89\u6218\uff0c\u4e43\u662f\u4e0e\u9ed1\u6697\u7684\u6743\u52bf\u4e89\u6218\u3002\u6240\u4ee5\uff0c\u5982\u679c\u6709\u95ee\u9898\uff0c\u6211\u9a6c\u4e0a\u539f\u8c05\u4ed6\uff0c\u8ba9\u4e0a\u5e1d\u4e3a\u6211\u89e3\u51b3\u6311\u6218\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u91c7\u53d6\u4e86\u4ec0\u4e48\u6b65\u9aa4\u6765\u79ef\u6781\u5730\u6d3b\u51fa\u4f60\u7684\u4fe1\u4ef0\uff0c\u5e76\u4e0e\u4ed6\u4eba\u5206\u4eab\u8036\u7a23\u7684\u7231\uff0c\u7279\u522b\u662f\u5728\u4e00\u4e2a\u53ef\u80fd\u5e76\u4e0d\u603b\u662f\u63a5\u53d7\u5b83\u7684\u4e16\u754c\u91cc? (\u59d0\u59d0\uff0c\u8bf7\u7ed9\u6211\u4eec\u7684\u542c\u4f17\u670b\u53cb\u4eec\u8be6\u7ec6\u7684\u8bf4\u660e\u4e00\u4e0b\u8fd9\u4e2a\u95ee\u9898\uff0c\u8ba9\u4ed6\u4eec\u77e5\u9053\u5982\u4f55\u5728\u73b0\u5b9e\u751f\u6d3b\u4e2d\u5177\u4f53\u53bb\u5b9e\u8df5)<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u79ef\u6781\u5730\u6d3b\u51fa\u6211\u7684\u4fe1\u4ef0\uff0c\u6211\u5531\u6b4c\uff0c\u4e3a\u8036\u7a23\u7948\u7977\uff0c\u6211\u8bfb\u5723\u7ecf\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u6211\u4eec\u60f3\u8981\u8ba4\u8bc6\u795e\uff0c\u4ed6\u662f\u8c01\uff0c\u4ed6\u7684\u54c1\u683c\uff0c\u4ed6\u7684\u65e8\u610f\u548c\u4ed6\u4f5c\u4e3a\u4e00\u4e2a\u4eba\uff0c\u6211\u4eec\u5fc5\u987b\u8bfb\u5723\u7ecf\uff0c\u56e0\u4e3a\u5b83\u662f\u795e\u7684\u60c5\u4e66\u548c\u795e\u7ed9\u6211\u4eec\u7684\u751f\u6d3b\u624b\u518c\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u5df2\u7ecf\u628a\u5723\u7ecf\u4ece\u5934\u5230\u5c3e\u8bfb\u4e86\u4e09\u904d\u4e86\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4f46\u662f\u5f53\u6211\u4eec\u8bfb\u5723\u7ecf\u65f6\uff0c\u5982\u679c\u6ca1\u6709\u5e2e\u52a9\uff0c\u6211\u4eec\u5c06\u65e0\u6cd5\u7406\u89e3\u8bb8\u591a\u4e8b\u60c5\u3002\u6240\u4ee5\uff0c\u6211\u4eec\u5fc5\u987b\u5411\u4e0a\u5e1d\u7948\u7977\uff0c\u7948\u6c42\u4ed6\u5c06\u5723\u7075\u8d50\u7ed9\u6211\u4eec\uff0c\u5e2e\u52a9\u6211\u4eec\u7406\u89e3\u4e0a\u5e1d\u8981\u901a\u8fc7\u4ed6\u7684\u8bdd\u8bed\u5bf9\u6211\u4eec\u8bf4\u7684\u8bdd\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u6ca1\u6709\u5723\u7075\uff0c\u5723\u7ecf\u53ea\u662f\u795e\u5b66\uff0c\u5c31\u50cf\u6240\u6709\u5176\u4ed6\u5173\u4e8e\u5b97\u6559\u7684\u4e66\u4e00\u6837\u3002\u4f46\u6709\u4e86\u5723\u7075\uff0c\u5b83\u5c31\u53d8\u6210\u4e86\u73cd\u5b9d\u3002\u6bcf\u6b21\u4f60\u8bfb\u5b83\uff0c\u4f60\u90fd\u4f1a\u4f53\u9a8c\u5230\u65b0\u7684\u4e1c\u897f\uff0c\u8fd9\u4e2a\u8bcd\u603b\u662f\u65b0\u9c9c\u7684\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4e3a\u4e86\u7948\u7977\uff0c\u6ca1\u6709\u5fc5\u8981\u53bb\u4e00\u4e2a\u7279\u522b\u7684\u5730\u65b9\u3002\u6211\u5728\u623f\u95f4\u6216\u4efb\u4f55\u5730\u65b9\u7948\u7977\uff0c\u56e0\u4e3a\u4e0a\u5e1d\u603b\u662f\u4e0e\u6211\u540c\u5728\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u5f53\u7f6a\u7684\u95ee\u9898\u89e3\u51b3\u4e86\uff0c\u6211\u5c31\u53ef\u4ee5\u968f\u65f6\u6765\u5230\u795e\u7684\u5b9d\u5ea7\u524d\uff0c\u65e0\u8bba\u4f55\u65f6\u4f55\u5730\uff0c\u4ed6\u90fd\u4f1a\u542c\u5230\u6211\u7684\u56de\u7b54\u3002\u6709\u65f6\u7b54\u6848\u662f\u5426\u5b9a\u7684\uff0c\u4f46\u4ed6\u4f1a\u542c\u5230\u6211\u7684\u6bcf\u4e00\u6b21\u7948\u7977\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u4e0e\u4ed6\u4eba\u5206\u4eab\u6211\u7684\u4fe1\u4ef0\uff0c\u5e76\u4e3a\u4ed6\u4eba\u505a\u51fa\u8d21\u732e\uff0c\u4e5f\u662f\u5728\u4e0a\u5e1d\u7684\u624b\u4e2d\u3002\u4ed6\u8bf4\uff0c\u6211\u4eec\u8981\u884c\u4ed6\u4ee5\u524d\u591a\u6b21\u4e3a\u6211\u4eec\u9884\u5907\u7684\u5584\u4e8b\u3002\u6240\u4ee5\u6211\u4eec\u53ea\u9700\u8981\u6709\u610f\u613f\u53bb\u505a\uff0c\u4e0a\u5e1d\u4f1a\u544a\u8bc9\u6211\u4eec\uff0c\u6211\u4eec\u662f\u5426\u5e94\u8be5\u9080\u8bf7\u4e00\u4e2a\u4eba\u4e0e\u6211\u4eec\u5171\u8fdb\u5348\u9910\uff0c\u6216\u8005\u652f\u6301\u4e00\u4e2a\u4f20\u6559\u58eb\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">\u4f60\u5177\u4f53\u628a\u4ec0\u4e48\u8363\u8000\u5f52\u4e0e\u4e86\u795e?(\u4f8b\u5982,1.2.3\u2026\u2026)<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u6211\u4eec\u53ef\u4ee5\u7528\u5f88\u591a\u65b9\u6cd5\u6765\u8363\u8000\u795e:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>\u5c0a\u91cd\u5e76\u9075\u5b88\u4ed6\u7684\u8beb\u547d\u3002<br>\u8036\u7a23\u8bf4\uff0c\u7231\u6211\u7684\u4eba\u5fc5\u9075\u5b88\u6211\u7684\u547d\u4ee4\u3002\u5f53\u7136\uff0c\u6211\u4eec\u5f97\u6551\u662f\u56e0\u4e3a\u4fe1\u5fc3\u548c\u6069\u5178\u3002\u4f46\u8036\u7a23\u6559\u5bfc\u6211\u4eec\u5982\u4f55\u6309\u7167\u4ed6\u7684\u65e8\u610f\u751f\u6d3b\uff0c\u5f53\u6211\u4eec\u60f3\u8981\u8363\u8000\u4e0a\u5e1d\u65f6\uff0c\u6211\u4eec\u5c0a\u91cd\u4ed6\u4eec<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u548c\u522b\u4eba\u8c08\u8bba\u4e0a\u5e1d<br>\u5f53\u6211\u4eec\u8c08\u8bba\u795e\u7684\u65f6\u5019\uff0c\u4ed6\u662f\u591a\u4e48\u7684\u597d\uff0c\u4ed6\u5728\u6211\u4eec\u8eab\u4e0a\u6240\u505a\u7684\u4e00\u5207\u4e5f\u662f\u628a\u8363\u8000\u5f52\u7ed9\u795e<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u63a2\u8bbf\u53d7\u82e6\u7684\u4eba<br>\u4e0a\u5e1d\u8bf4\uff0c\u8fd9\u624d\u662f\u771f\u6b63\u7684\u656c\u62dc:\u53bb\u770b\u671b\u90a3\u4e9b\u5728\u82e6\u96be\u4e2d\u7684\u5be1\u5987\u548c\u5979\u4eec\u6240\u5c45\u4f4f\u7684\u8857\u9053\u3002\u5f53\u6211\u4eec\u62dc\u8bbf\u90a3\u4e9b\u751f\u6d3b\u56f0\u96be\u7684\u4eba\u65f6\uff0c\u6211\u4eec\u7ed9\u4ed6\u4eec\u5e26\u6765\u597d\u6d88\u606f\uff0c\u5373\u4f7f\u5728\u56f0\u96be\u7684\u65f6\u5019\uff0c\u4e0a\u5e1d\u4e5f\u4f1a\u7167\u987e\u4ed6\u4eec\uff0c\u4e0e\u4ed6\u4eec\u5206\u4eab\u65f6\u95f4\uff0c\u4e3a\u4ed6\u4eec\u505a\u51fa\u8d21\u732e\uff0c\u8fd9\u4e5f\u662f\u8d5e\u7f8e\u4e0a\u5e1d\u3002<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>\u5531\u6b4c\uff0c\u5411\u4e0a\u5e1d\u7948\u7977<br>\u6211\u5199\u8fd9\u4e9b\u6b4c\u7684\u4e3b\u8981\u539f\u56e0\u662f\u4e3a\u4e86\u8363\u8000\u795e\u3002\u901a\u8fc7\u97f3\u4e50\u76f4\u63a5\u4e0e\u4e0a\u5e1d\u5bf9\u8bdd\uff0c\u5f53\u6211\u5199\u4e00\u9996\u656c\u62dc\u6b4c\u66f2\u6216\u4e0e\u4ed6\u4eba\u79ef\u6781\u8c08\u8bba\u4e0a\u5e1d\u65f6\uff0c\u5f53\u6211\u901a\u8fc7\u97f3\u4e50\u89c1\u8bc1\u4e0a\u5e1d\u7684\u5b58\u5728\u65f6\u3002<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>\u4eca\u5929\u7684\u8282\u76ee\u5c31\u5230\u8fd9\u91cc\uff0c\u611f\u8c22\u5927\u5bb6\u7684\u6536\u542c\uff01\u6211\u4eec\u4e0b\u671f\u518d\u4f1a\uff01<\/p>\n<!-- \/wp:paragraph -->","_zh_post_name":"","_zh_post_excerpt":"","_zh_post_title":"Jesus has changed my life - CN ","_es_post_content":"<!-- wp:paragraph -->\n<p>Este texto es la traduccion del podcast \"Kiki y Ingrid - una senorita de China encuentra a Ingrid, la cantante\" <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:pullquote -->\n<figure class=\"wp-block-pullquote\"><blockquote><p>Jes\u00fas ha cambiado mi vida<br>Jes\u00fas ha cambiado mi vida<br>Jes\u00fas ha cambiado mi vida<br>yo le doy la gloria<br>Jes\u00fas ha cambiado mi vida<br>Jes\u00fas ha cambiado mi vida<br>Jes\u00fas ha cambiado mi vida<br>le doy alabanza<br><br>Una vez fui un pecador<br>pero yo no estaba conciente<br>sali  por diversi\u00f3n<br>y risa  en la noche<br>Pero la diversi\u00f3n de la noche<br>fue seguido por el vac\u00edo<br>Y sent\u00ed hambre de m\u00e1s vida<br>Una vez fui un pecador<br>pero yo no estaba conciente<br>Cuando lastimo a la gente<br>que me rodeaba<br>siendo lastimada yo mismo<br>me hizo injusta<br>hasta ese d\u00eda<br>que Jes\u00fas me salv\u00f3<br><br>Una vez fui un pecador<br>y ahora soy consciente<br>que Jesus es el<br>quien me da alegria y vida<br>Y su bendici\u00f3n cada d\u00eda<br>dar sanidad a cada sufrimiento<br>Su esp\u00edritu y amor me dan consolacion<\/p><\/blockquote><\/figure>\n<!-- \/wp:pullquote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"> <strong>\u00bfDe qu\u00e9 manera la presencia de Jes\u00fas en tu vida te ha hecho sentir m\u00e1s agradecido por las bendiciones que has recibido?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Lo primero que tenemos que hacer es ser conscientes de que tenemos una bendici\u00f3n. Mucha gente dice: obtuve mis bienes y lo que tengo a trav\u00e9s de mi arduo trabajo. Entonces digo: ok, pero \u00bfqui\u00e9n te ha dado la fuerza para que puedas trabajar? \u00bfPor qu\u00e9 est\u00e1s sano y puedes ir todos los d\u00edas a trabajar?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>23&nbsp;Quien me ofrece su gratitud, me honra; al que enmiende su conducta le mostrar\u00e9 mi salvaci\u00f3n.\u00bb<\/p>\n<!-- \/wp:paragraph --><cite>Salmo 50<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Estuve hace 10 a\u00f1os muy enfermo ya al punto de morir, pero despert\u00e9 del coma sin da\u00f1o cerebral permanente, lo cual fue un milagro. Entonces, por supuesto, estoy agradecido no solo por las bendiciones, estoy agradecido de que Dios me permita vivir y levantarme cada ma\u00f1ana sin la ayuda de otros.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>1&nbsp;El Se\u00f1or es mi pastor, nada me falta;<br>2&nbsp;en verdes pastos me hace descansar. Junto a tranquilas aguas me conduce;<br>3&nbsp;me infunde nuevas fuerzas. Me gu\u00eda por sendas de justicia por amor a su nombre.<br>4&nbsp;Aun si voy por valles tenebrosos, no temo peligro alguno porque t\u00fa est\u00e1s a mi lado; tu vara de pastor me reconforta.<br>5&nbsp;Dispones ante m\u00ed un banquete en presencia de mis enemigos. Has ungido con perfume mi cabeza; has llenado mi copa a rebosar.<br>6&nbsp;La bondad y el amor me seguir\u00e1n todos los d\u00edas de mi vida; y en la casa del Se\u00f1or habitar\u00e9 para siempre.<\/p>\n<!-- \/wp:paragraph --><cite>Salmo 23<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"> <strong>\u00bfDe qu\u00e9 manera has experimentado personalmente la redenci\u00f3n a trav\u00e9s del amor y el perd\u00f3n de Jes\u00fas?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Para experimentar la redenci\u00f3n, es necesario ser conscientes de que necesitamos un redentor. La mayor\u00eda de las personas viven como describo en mi canci\u00f3n, caminan, hacen sus cosas, quieren divertirse, pero no son conscientes de que tienen pecado en su vida y deben arrepentirse.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>2&nbsp;Desde el cielo el Se\u00f1or contempla a los mortales, para ver si hay alguien que sea sensato y busque a Dios.<br>3&nbsp;Pero todos se han descarriado, a una se han corrompido. No hay nadie que haga lo bueno; \u00a1no hay uno solo!<\/p>\n<!-- \/wp:paragraph --><cite>Salmo 14<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Un momento, nuestros oyentes pueden decir ahora. Soy una buena persona y no un pecador. Pero esto es lo que complica la situaci\u00f3n: no somos conscientes de cu\u00e1ndo pecamos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>9&nbsp;Nada hay tan enga\u00f1oso como el coraz\u00f3n. No tiene remedio. \u00bfQui\u00e9n puede comprenderlo?<\/p>\n<!-- \/wp:paragraph --><cite>Jeremia 17,9<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>El pecado no es hacer el bien o el mal. El pecado es algo que hemos heredado de nuestros bisabuelos Ad\u00e1n y Eva y no podemos deshacernos de \u00e9l por nuestra propia voluntad y poder.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>12&nbsp;Por medio de un solo hombre el pecado entr\u00f3 en el mundo, y por medio del pecado entr\u00f3 la muerte; fue as\u00ed como la muerte pas\u00f3 a toda la humanidad, porque todos pecaron.<\/p>\n<!-- \/wp:paragraph --><cite>Romanos 5<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Cuando somos honestos, todos hemos dicho una mentira alguna vez en nuestra vida. Y ya decir una sola mentira nos convierte en pecadores.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dios no puede tener comuni\u00f3n con un pecador, porque \u00e9l es absolutamente puro y santo. As\u00ed que necesitamos que Jes\u00fas pague el precio del pecado por nosotros y haga posible que tengamos comuni\u00f3n con el Dios vivo y no tengamos que ir al infierno sino al cielo. despu\u00e9s de esta vida en la tierra\u3002<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong> \u00bfC\u00f3mo te esfuerzas por revelar tu fe y la transformaci\u00f3n que Jes\u00fas ha tra\u00eddo a tu vida en el mundo que te rodea?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>No busco revelar mi fe al mundo que me rodea, porque la biblia ense\u00f1a, no compartir con todos. Cuando alguien no quiere recibir el evangelio de Cristo, lo dejo ir.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero siempre estoy abierto a hablar de Jes\u00fas con las personas que me rodean y busco la oportunidad de contarles a las personas acerca de Jesucristo y el trabajo que ha hecho por ellos en el Calvario.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero esto viene a menudo inesperado. Solo estoy dispuesto a decir y Dios abre una puerta al coraz\u00f3n de la persona, que est\u00e1 escuchando y preguntando m\u00e1s sobre el Evangelio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>16&nbsp;A la verdad, no me averg\u00fcenzo del evangelio, pues es poder de Dios para la salvaci\u00f3n de todos los que creen: de los jud\u00edos primeramente, pero tambi\u00e9n de los gentiles.<br>17&nbsp;De hecho, en el evangelio se revela la justicia que proviene de Dios, la cual es por fe de principio a fin,[4] tal como est\u00e1 escrito: \u00abEl justo vivir\u00e1 por la fe.\u00bb<\/p>\n<!-- \/wp:paragraph --><cite>Rom 1<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"> <strong>\u00bfC\u00f3mo imaginas el concepto del para\u00edso y vivir en la presencia de Jes\u00fas? \u00bfC\u00f3mo moldea esta esperanza tu perspectiva de la vida?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>El concepto de para\u00edso es algo que le da sentido y destino a mi vida. No tengo miedo de lo que pase cuando muera y tenga que presentarme en la eternidad, ya que Jes\u00fas lo ha dispuesto todo para m\u00ed. \u00c9l dijo, nos construir\u00e1 una casa en la vida eterna y all\u00ed ir\u00e9 alg\u00fan d\u00eda.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>2&nbsp;En el hogar de mi Padre hay muchas viviendas; si no fuera as\u00ed, ya se lo habr\u00eda dicho a ustedes. Voy a prepararles un lugar.<br>3&nbsp;Y si me voy y se lo preparo, vendr\u00e9 para llev\u00e1rmelos conmigo. As\u00ed ustedes estar\u00e1n donde yo est\u00e9.<\/p>\n<!-- \/wp:paragraph --><cite>Juan 14<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Algo que es interesante es, que la biblia no habla mucho de la muerte, aun este d\u00eda llegar\u00e1, habla m\u00e1s de la vida eterna y dice, que los que viven con Dios ser\u00e1n j\u00f3venes aunque ya sean viejos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Entonces, trato de ser como Enoc en el libro de G\u00e9nesis. Simplemente camin\u00f3 con Dios y un d\u00eda Dios se lo llev\u00f3.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>24&nbsp;Und Henoch wandelte mit Gott und ward nicht mehr gesehen, denn Gott hatte ihn entr\u00fcckt.<\/p>\n<!-- \/wp:paragraph --><cite>1. Mose 5<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Vivo mi d\u00eda a d\u00eda, atento, si hay algo que Dios quiere que haga y sabiendo que siempre est\u00e1 conmigo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero la biblia nos ense\u00f1a de otro lugar, a donde vamos, cuando no recibimos a Jes\u00fas como nuestro Salvador: Es el lago de fuego, el infierno. Est\u00e1 vac\u00edo en este momento, pero cuando Jes\u00fas regrese como juez, todos los que no fueron salvos ser\u00e1n juzgados en el trono blanco y luego ir\u00e1n al infierno. Por eso est\u00e1 escrito en hebreo: El hombre morir\u00e1 una vez, despu\u00e9s de esto viene el juicio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>27&nbsp;Y as\u00ed como est\u00e1 establecido que los seres humanos mueran una sola vez, y despu\u00e9s venga el juicio,<\/p>\n<!-- \/wp:paragraph --><cite>Hebreos 9 <\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>5&nbsp;Pero por tu obstinaci\u00f3n y por tu coraz\u00f3n empedernido sigues acumulando castigo contra ti mismo para el d\u00eda de la ira, cuando Dios revelar\u00e1 su justo juicio.<br>6&nbsp;Porque Dios \u00abpagar\u00e1 a cada uno seg\u00fan lo que merezcan sus obras\u00bb.[1]<br>7&nbsp;\u00c9l dar\u00e1 vida eterna a los que, perseverando en las buenas obras, buscan gloria, honor e inmortalidad.<br>8&nbsp;Pero los que por ego\u00edsmo rechazan la verdad para aferrarse a la maldad, recibir\u00e1n el gran castigo de Dios.<br>9&nbsp;Habr\u00e1 sufrimiento y angustia para todos los que hacen el mal, los jud\u00edos primeramente, y tambi\u00e9n los gentiles;<br>10&nbsp;pero gloria, honor y paz para todos los que hacen el bien, los jud\u00edos primeramente, y tambi\u00e9n los gentiles.<br>11&nbsp;Porque con Dios no hay favoritismos.<\/p>\n<!-- \/wp:paragraph --><cite>Rom 2,5-11<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>11&nbsp;Luego vi un gran trono blanco y a alguien que estaba sentado en \u00e9l. De su presencia huyeron la tierra y el cielo, sin dejar rastro alguno.<br>12&nbsp;Vi tambi\u00e9n a los muertos, grandes y peque\u00f1os, de pie delante del trono. Se abrieron unos libros, y luego otro, que es el libro de la vida. Los muertos fueron juzgados seg\u00fan lo que hab\u00edan hecho, conforme a lo que estaba escrito en los libros.<br>13&nbsp;El mar devolvi\u00f3 sus muertos; la muerte y el infierno[1]devolvieron los suyos; y cada uno fue juzgado seg\u00fan lo que hab\u00eda hecho.<br>14&nbsp;La muerte y el infierno fueron arrojados al lago de fuego. Este lago de fuego es la muerte segunda.<br>15&nbsp;Aquel cuyo nombre no estaba escrito en el libro de la vida era arrojado al lago de fuego.<\/p>\n<!-- \/wp:paragraph --><cite>Apocalipsis 20<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong> En medio de los desaf\u00edos y realidades del mundo, \u00bfc\u00f3mo mantienes un coraz\u00f3n en paz y encuentras consuelo en las ense\u00f1anzas de Jes\u00fas?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Creer en Jes\u00fas es relaci\u00f3n. Cuando tengo una relaci\u00f3n con Jes\u00fas, no dependo de lo que otras personas crean o piensen de m\u00ed. Entonces, si hay un conflicto, puedo mantener la calma y orar en mi coraz\u00f3n a Jes\u00fas para que me ayude a salir de esta situaci\u00f3n inc\u00f3moda.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Y recuerdo que Pablo ha escrito, que no luchamos contra sangre y carne, sino contra los poderes de las tinieblas. Entonces, si hay un problema, perdono de inmediato y dejo que Dios resuelva el desaf\u00edo por m\u00ed.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>11&nbsp;P\u00f3nganse toda la armadura de Dios para que puedan hacer frente a las artima\u00f1as del diablo.<br>12&nbsp;Porque nuestra lucha no es contra seres humanos, sino contra poderes, contra autoridades, contra potestades que dominan este mundo de tinieblas, contra fuerzas espirituales malignas en las regiones celestiales.<\/p>\n<!-- \/wp:paragraph --><cite>Epheser 6<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 pasos toma para vivir activamente su fe y compartir el amor de Jes\u00fas con los dem\u00e1s, particularmente en un mundo que no siempre es receptivo?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><em><strong>(Hermana, por favor explique esta pregunta en una descripci\u00f3n detallada para nuestra audiencia, para que sepan c\u00f3mo concretar la pr\u00e1ctica en sus vidas reales)<\/strong><\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Porque para vivir mi fe activamente, canto y oro por Jes\u00fas y leo la Biblia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cuando quisi\u00e9ramos conocer a Dios, qui\u00e9n es, su car\u00e1cter, su voluntad y \u00e9l como persona, tenemos que leer la Biblia, porque es la carta de amor de Dios y el manual de Dios sobre la vida para nosotros.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ya he le\u00eddo la biblia al menos 3 veces desde el principio hasta el final.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero cuando leemos la Biblia, hay muchas cosas que no entenderemos sin ayuda. Entonces, tenemos que orar a Dios, que nos env\u00ede su Esp\u00edritu Santo y nos ayude a entender lo que Dios quiere decirnos a trav\u00e9s de su palabra.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sin el Esp\u00edritu Santo, la Biblia es solo teolog\u00eda, como todos los dem\u00e1s libros sobre religi\u00f3n. Pero con el Esp\u00edritu Santo, se convierte en tesoro. Cada vez que lo lees, experimentas cosas nuevas y la palabra siempre est\u00e1 fresca.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>19&nbsp;\u00bfAcaso no saben que su cuerpo es templo del Esp\u00edritu Santo, quien est\u00e1 en ustedes y al que han recibido de parte de Dios? Ustedes no son sus propios due\u00f1os;<\/p>\n<!-- \/wp:paragraph --><cite>1 Cor 6<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Porque para orar no es necesario ir a un lugar especial. Rezo en mi habitaci\u00f3n o donde est\u00e9, porque Dios siempre est\u00e1 conmigo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cuando el problema del pecado se resuelve, siempre tengo acceso al trono de Dios, y puedo venir cuando sea o donde sea, \u00e9l me escuchar\u00e1 y responder\u00e1. A veces la respuesta es no, pero \u00e9l escuchar\u00e1 todas mis oraciones.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Compartir mi fe con otros y contribuir a otros tambi\u00e9n est\u00e1 en manos de Dios. \u00c9l dice, haremos las buenas obras que \u00e9l ha preparado para nosotros mucho tiempo antes. Entonces solo tenemos que tener la voluntad de hacerlas y Dios nos mostrar\u00e1, si debemos invitar a una persona a almorzar con nosotros oa apoyar a un misionero por ejemplo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 gloria exacta le diste a Dios? (Por ejemplo, 1.2.3\u2026)<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Hay muchas maneras en que podemos dar gloria a Dios:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Respetar y guardar sus mandamientos.<\/em><br>Jes\u00fas dijo, el que me ama guardar\u00e1 mis mandamientos. Por supuesto, somos salvos por la fe y la gracia. Pero Jes\u00fas nos ense\u00f1\u00f3 a vivir seg\u00fan su voluntad y cuando quisi\u00e9ramos dar gloria a Dios, los respetamos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Hablar de Dios con otras personas<\/em><br>Cuando hablamos de Dios, lo bueno que es y lo que nos ha hecho es dar gloria a Dios tambi\u00e9n<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Visitar a las personas que sufren<\/em><br>Dios dice, \u00e9ste es el verdadero culto: visitar a las viudas y a los hu\u00e9rfanos en su aflicci\u00f3n. Cuando visitamos a personas que tienen una vida realmente dura y les llevamos la buena noticia, que incluso en tiempos dif\u00edciles Dios los cuidar\u00e1 y compartir\u00e1 con ellos tiempo y contribuir\u00e1 con ellos, esto tambi\u00e9n es alabar a Dios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Cantar y orar a Dios<\/em><br>La raz\u00f3n principal por la que he escrito estas canciones es para dar gloria a Dios. Para hablar directamente con Dios a trav\u00e9s de la m\u00fasica, cuando escribo una canci\u00f3n de adoraci\u00f3n o para hablarles a otros de manera positiva acerca de Dios, cuando testifico a trav\u00e9s de mi m\u00fasica que Dios existe.<\/p>\n<!-- \/wp:paragraph -->","_es_post_name":"","_es_post_excerpt":"","_es_post_title":"Jesus has changed my life - ES","_de_post_content":"<!-- wp:pullquote -->\n<figure class=\"wp-block-pullquote\"><blockquote><p>Jesus hat mein Leben ver\u00e4ndert<br>Jesus hat mein Leben ver\u00e4ndert<br>Jesus hat mein Leben ver\u00e4ndert<br>Ich gebe ihm Ehre<br>Jesus hat mein Leben ver\u00e4ndert<br>Jesus hat mein Leben ver\u00e4ndert<br>Jesus hat mein Leben ver\u00e4ndert<br>Ich lobe ihn<br>Einst war ich ein S\u00fcnder<br>aber ich war mir nicht bewusst<br>Ich wollte einfach nur Spa\u00df haben<br>um mich nachts um die H\u00e4user ziehen<br><br>Aber auf den Spa\u00df des Abends <br>folgte die  Leere<br>Und ich versp\u00fcrte Hunger nach mehr Leben<br><br>Einst war ich ein S\u00fcnder<br>aber ich war mir nicht bewusst<br>Dass ich die Menschen verletzte<br>die um mich herum waren<br>Selbst verletzt zu sein<br>macht einen ungerecht<br>bis zu jenem Tag<br>als Jesus mich gerettet hat<br><br>Einst war ich ein S\u00fcnder<br>und jetzt bin ich mir dessen bewusst<br>dass Jesus derjenige ist<br>der mir Freude und Leben gibt<br>Und seinen Segen jeden Tag<br>Gib jedem Leidenden Heilung<br>Sein Geist und seine Liebe<br>tr\u00f6sten mich<\/p><\/blockquote><\/figure>\n<!-- \/wp:pullquote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong> Wie hat die Anwesenheit Jesu in deinem Leben Sie dankbarer f\u00fcr die Segnungen gemacht, die du erhalten hast?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Das erste, was wir tun m\u00fcssen, ist uns bewusst zu machen, dass wir einen Segen haben. Viele Leute sagen: Ich habe meine G\u00fcter und das, was ich habe, durch meine harte Arbeit bekommen. Dann sage ich: Ok, aber wer hat Ihnen die Kraft gegeben, dass Sie arbeiten k\u00f6nnen? Warum sind Sie gesund und k\u00f6nnen jeden Tag zur Arbeit gehen?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>23&nbsp;Wer Dank opfert, der preiset mich, und da ist der Weg, dass ich ihm zeige das Heil Gottes.\u00ab<\/p>\n<!-- \/wp:paragraph --><cite>Psalm 50<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Vor 10 Jahren war ich sehr krank und im fast gestorben, aber ich erwachte aus dem Koma ohne bleibende Hirnsch\u00e4den, was ein Wunder war. Nat\u00fcrlich bin ich nicht nur f\u00fcr die Segnungen dankbar, sondern auch daf\u00fcr, dass Gott es mir erm\u00f6glicht, jeden Morgen ohne die Hilfe anderer zu leben und aufzustehen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>&nbsp;Ein Psalm Davids. Der HERR ist mein Hirte, mir wird nichts mangeln.<br>2&nbsp;Er weidet mich auf einer gr\u00fcnen Aue und f\u00fchret mich zum frischen Wasser.<br>3&nbsp;Er erquicket meine Seele. Er f\u00fchret mich auf rechter Stra\u00dfe um seines Namens willen.<br>4&nbsp;Und ob ich schon wanderte im finstern Tal, f\u00fcrchte ich kein Ungl\u00fcck; denn du bist bei mir, dein Stecken und Stab tr\u00f6sten mich.<br>5&nbsp;Du bereitest vor mir einen Tisch im Angesicht meiner Feinde. Du salbest mein Haupt mit \u00d6l und schenkest mir voll ein.<br>6&nbsp;Gutes und Barmherzigkeit werden mir folgen mein Leben lang, und ich werde bleiben im Hause des HERRN immerdar.<\/p>\n<!-- \/wp:paragraph --><cite>Psalm 23<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>Auf welche Weise hast Du pers\u00f6nlich die Erl\u00f6sung durch die Liebe und Vergebung Jesu erfahren?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Um Erl\u00f6sung zu erfahren, muss man sich bewusst sein, dass wir einen Erl\u00f6ser brauchen. <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Die meisten Menschen leben so, wie ich es in meinem Lied beschreibe, sie laufen herum, machen ihre Sachen, wollen Spa\u00df haben, sind sich aber nicht bewusst, dass sie S\u00fcnde in ihrem Leben haben und Bu\u00dfe tun sollten.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>2&nbsp;Der HERR schaut vom Himmel auf die Menschenkinder, dass er sehe, ob jemand klug sei und nach Gott frage.<br>3&nbsp;Aber sie sind alle abgewichen und allesamt verdorben; da ist keiner, der Gutes tut, auch nicht einer.<\/p>\n<!-- \/wp:paragraph --><cite>Psalm 14<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Einen Moment k\u00f6nnen unsere Zuh\u00f6rer jetzt sagen. Ich bin ein guter Mensch und kein S\u00fcnder. Aber das macht die Situation so schwierig: Wir sind uns nicht bewusst, wann wir s\u00fcndigen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>9&nbsp;Es ist das Herz ein trotzig und verzagt Ding; wer kann es ergr\u00fcnden?<\/p>\n<!-- \/wp:paragraph --><cite>Jeremiah<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>S\u00fcnde bedeutet nicht, richtig oder falsch zu handeln. S\u00fcnde ist etwas, das wir von unseren Gro\u00dfeltern Adam und Eva geerbt haben, und wir k\u00f6nnen sie nicht durch unseren eigenen Willen und unsere eigene Kraft loswerden.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>12&nbsp;Deshalb, wie durch einen Menschen die S\u00fcnde in die Welt gekommen ist und der Tod durch die S\u00fcnde, so ist der Tod zu allen Menschen durchgedrungen, weil sie alle ges\u00fcndigt haben.<\/p>\n<!-- \/wp:paragraph --><cite>Rom 5<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Wenn wir ehrlich sind, haben wir alle einmal in unserem Leben schon einmal gelogen. Und schon das Erz\u00e4hlen einer einzigen L\u00fcge macht uns zu S\u00fcndern.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Gott kann keine Gemeinschaft mit einem S\u00fcnder haben, weil er absolut rein und heilig ist. Wir brauchen also Jesus, der den Preis der S\u00fcnde f\u00fcr uns zahlt und es uns erm\u00f6glicht, Gemeinschaft mit dem lebendigen Gott zu haben und nicht in die H\u00f6lle, sondern in den Himmel zu m\u00fcssen nach diesem Leben auf der Erde.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>Wie strebst du danach, deinen Glauben und die Ver\u00e4nderung, die Jesus in dein Leben gebracht hat, in der Welt um Sie herum zu offenbaren?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Ich versuche nicht, meinen Glauben der Welt um mich herum zu offenbaren, denn die Bibel lehrt, dass man meinen Glauben nicht mit jedem teilen soll. Wenn jemand das Evangelium Christi nicht annehmen m\u00f6chte, lasse ich ihn oder sie gehen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aber ich bin immer offen daf\u00fcr, mit den Menschen um mich herum \u00fcber Jesus zu sprechen, und ich halte Ausschau nach einer Gelegenheit, den Menschen von Jesus Christus und der Arbeit zu erz\u00e4hlen, die er auf Golgatha f\u00fcr sie getan hat.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aber das kommt oft unerwartet. Ich bin einfach bereit zu sagen und Gott \u00f6ffnet eine T\u00fcr zum Herzen der Person, dass sie zuh\u00f6rt und mehr \u00fcber das Evangelium fragt<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>16&nbsp;Denn ich sch\u00e4me mich des Evangeliums nicht; denn es ist eine Kraft Gottes, die selig macht[1] alle, die glauben, die Juden zuerst und ebenso die Griechen.<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>Wie stellst du dir  das Konzept des Paradieses und des Lebens in der Gegenwart Jesu vor? Wie pr\u00e4gt diese Hoffnung Ihre Sicht auf das Leben?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Das Konzept des Paradieses gibt meinem Leben Sinn und Ziel. Ich habe keine Angst davor, was passiert, wenn ich sterbe und mich in der Ewigkeit pr\u00e4sentieren muss, da Jesus alles f\u00fcr mich arrangiert hat. Er sagte, er werde im ewigen Leben ein Haus f\u00fcr uns bauen und dorthin werde ich eines Tages gehen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>2&nbsp;In meines Vaters Hause sind viele Wohnungen. Wenn\u2019s nicht so w\u00e4re, h\u00e4tte ich dann zu euch gesagt: Ich gehe hin, euch die St\u00e4tte zu bereiten?<br>3&nbsp;Und wenn ich hingehe, euch die St\u00e4tte zu bereiten, will ich wiederkommen und euch zu mir nehmen, auf dass auch ihr seid, wo ich bin.<br>4&nbsp;Und wo ich hingehe \u2013 den Weg dahin wisst ihr.<\/p>\n<!-- \/wp:paragraph --><cite>Johannes 14<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Interessant ist, dass die Bibel nicht viel \u00fcber den Tod spricht, auch wenn dieser Tag kommen wird. Sie spricht mehr vom ewigen Leben und sagt, dass diejenigen, die mit Gott leben, jung sein werden, auch wenn sie bereits alt sind.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Deshalb versuche ich, wie Henoch im Buch Genesis zu sein. Er ging einfach mit Gott und eines Tages hat Gott ihn weggenommen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>24&nbsp;Und Henoch wandelte mit Gott und ward nicht mehr gesehen, denn Gott hatte ihn entr\u00fcckt.<\/p>\n<!-- \/wp:paragraph --><cite>Genesis 1<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Ich lebe meinen Alltag, achte darauf, ob Gott etwas von mir m\u00f6chte, und wei\u00df, dass er immer bei mir ist.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aber die Bibel lehrt uns einen anderen Ort, wohin wir gehen, wenn wir Jesus nicht als unseren Retter annehmen: Es ist der Feuersee, die H\u00f6lle. Im Moment ist es leer, aber wenn Jesus als Richter zur\u00fcckkommt, werden alle, die nicht gerettet wurden, auf dem wei\u00dfen Thron gerichtet und dann in die H\u00f6lle kommen. Deshalb steht auf Hebr\u00e4isch geschrieben: Der Mensch wird einmal sterben, danach kommt das Gericht.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>27&nbsp;Und wie den Menschen bestimmt ist, einmal zu sterben, danach aber das Gericht:<\/p>\n<!-- \/wp:paragraph --><cite>Hebr 9 <\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>5&nbsp;Du aber, mit deinem verstockten und unbu\u00dffertigen Herzen, h\u00e4ufst dir selbst Zorn an f\u00fcr den Tag des Zorns und der Offenbarung des gerechten Gerichtes Gottes,<br>6&nbsp;der einem jeden geben wird nach seinen Werken:<br>7&nbsp;ewiges Leben denen, die in aller Geduld mit guten Werken trachten nach Herrlichkeit, Ehre und unverg\u00e4nglichem Leben;<br>8&nbsp;Zorn und Grimm aber denen, die streits\u00fcchtig sind und der Wahrheit nicht gehorchen, gehorchen aber der Ungerechtigkeit;<br>9&nbsp;Tr\u00fcbsal und Angst \u00fcber alle Seelen der Menschen, die das B\u00f6se tun, zuerst der Juden und auch der Griechen;<br>10&nbsp;Herrlichkeit aber und Ehre und Frieden allen denen, die das Gute tun, zuerst den Juden und ebenso den Griechen.<br>11&nbsp;Denn es ist kein Ansehen der Person vor Gott.<\/p>\n<!-- \/wp:paragraph --><cite>Roemer 2<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>11&nbsp;Und ich sah einen gro\u00dfen, wei\u00dfen Thron und den, der darauf sa\u00df; vor seinem Angesicht flohen die Erde und der Himmel, und es wurde keine St\u00e4tte f\u00fcr sie gefunden.<br>12&nbsp;Und ich sah die Toten, Gro\u00df und Klein, stehen vor dem Thron, und B\u00fccher wurden aufgetan. Und ein andres Buch wurde aufgetan, welches ist das Buch des Lebens. Und die Toten wurden gerichtet nach dem, was in den B\u00fcchern geschrieben steht, nach ihren Werken.<br>13&nbsp;Und das Meer gab die Toten heraus, die darin waren, und der Tod und die H\u00f6lle gaben die Toten heraus, die darin waren; und sie wurden gerichtet, ein jeder nach seinen Werken.<br>14&nbsp;Und der Tod und die H\u00f6lle wurden geworfen in den feurigen Pfuhl. Das ist der zweite Tod: der feurige Pfuhl.<br>15&nbsp;Und wenn jemand nicht gefunden wurde geschrieben in dem Buch des Lebens, der wurde geworfen in den feurigen Pfuhl.<\/p>\n<!-- \/wp:paragraph --><cite>Offenbarung 20 <\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>Wie bewahrst du inmitten der Herausforderungen und Realit\u00e4ten der Welt ein friedvolles Herz und findest Trost in den Lehren Jesu?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Der Glaube an Jesus ist eine Beziehung. Wenn ich eine Beziehung zu Jesus habe, bin ich nicht darauf angewiesen, was andere Menschen \u00fcber mich glauben oder denken. Wenn es also zu einem Konflikt kommt, kann ich ruhig bleiben und in meinem Herzen zu Jesus beten, dass er mir hilft, aus dieser unangenehmen Situation herauszukommen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Und ich erinnere mich, dass Paulus geschrieben hat, dass wir nicht gegen Blut und Fleisch k\u00e4mpfen, sondern gegen die M\u00e4chte der Finsternis. Wenn es also ein Problem gibt, vergebe ich sofort und lasse Gott die Herausforderung f\u00fcr mich l\u00f6sen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>11&nbsp;Zieht an die Waffenr\u00fcstung Gottes, damit ihr bestehen k\u00f6nnt gegen die listigen Anschl\u00e4ge des Teufels.<br>12&nbsp;Denn wir haben nicht mit Fleisch und Blut zu k\u00e4mpfen, sondern mit M\u00e4chtigen und Gewaltigen, mit den Herren der Welt, die \u00fcber diese Finsternis herrschen, mit den b\u00f6sen Geistern unter dem Himmel.<\/p>\n<!-- \/wp:paragraph --><cite>Eph 6<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>Welche Schritte unternimmst du, um deinen Glauben aktiv auszuleben und die Liebe Jesu mit anderen zu teilen, insbesondere in einer Welt, die daf\u00fcr m\u00f6glicherweise nicht immer empf\u00e4nglich ist?<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><em><strong>(Schwester, bitte erkl\u00e4re  diese Frage in einer detaillierten Beschreibung f\u00fcr unsere Zuh\u00f6rer, damit sie wissen, wie sie konkret in ihrem wirklichen Leben praktizieren k\u00f6nnen.)<\/strong><\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Um meinen Glauben aktiv zu leben, singe und bete ich f\u00fcr Jesus und lese die Bibel.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wenn wir Gott kennenlernen m\u00f6chten, wer er ist, seinen Charakter, seinen Willen und ihn als Person, m\u00fcssen wir die Bibel lesen, denn sie ist Gottes Liebesbrief und Gottes Handbuch \u00fcber das Leben f\u00fcr uns.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ich habe die Bibel bereits dreimal von Anfang bis Ende gelesen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aber wenn wir die Bibel lesen, gibt es viele Dinge, die wir ohne Hilfe nicht verstehen werden. Wir m\u00fcssen also zu Gott beten, dass er uns seinen Heiligen Geist sendet und uns hilft, zu verstehen, was Gott uns durch sein Wort sagen m\u00f6chte.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ohne den Heiligen Geist ist die Bibel nur Theologie, wie alle anderen B\u00fccher \u00fcber Religion. Aber mit dem Heiligen Geist verwandelt es sich in einen Schatz. Jedes Mal, wenn man es liest, erlebt man neue Dinge und das Wort ist immer frisch.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>19&nbsp;Oder wisst ihr nicht, dass euer Leib ein Tempel des Heiligen Geistes ist, der in euch ist und den ihr von Gott habt, und dass ihr nicht euch selbst geh\u00f6rt?<\/p>\n<!-- \/wp:paragraph --><cite>1 Korinther 6<\/cite><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Denn um zu beten, ist es nicht notwendig, an einen besonderen Ort zu gehen. Ich bete in meinem Zimmer oder wo auch immer ich bin, denn Gott ist immer bei mir.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wenn das Problem der S\u00fcnde gel\u00f6st ist, habe ich immer Zugang zum Thron Gottes und kann jederzeit und \u00fcberall hinkommen, er wird mir zuh\u00f6ren und antworten. Manchmal ist die Antwort nein, aber er wird jedes Gebet von mir h\u00f6ren.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es liegt auch in Gottes Hand, meinen Glauben mit anderen zu teilen und einen Beitrag f\u00fcr andere zu leisten. Er sagt, wir werden die guten Werke tun, die er schon oft f\u00fcr uns vorbereitet hat. Wir m\u00fcssen also nur den Willen dazu haben und Gott wird es uns zeigen, ob wir jemanden zum Mittagessen einladen oder beispielsweise einen Missionar unterst\u00fctzen sollen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><strong>Welche genaue Ehre hast du Gott gegeben? (Zum Beispiel 1.2.3\u2026)<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Es gibt viele M\u00f6glichkeiten, wie wir Gott die Ehre geben k\u00f6nnen:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Seine Gebote respektieren und halten.<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>Jesus sagte: Wer mich liebt, wird meine Gebote halten. Nat\u00fcrlich werden wir durch Glauben und Gnade gerettet. Aber Jesus hat uns gelehrt, nach seinem Willen zu leben, und wenn wir Gott die Ehre geben m\u00f6chten, respektieren wir ihn<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Mit anderen Menschen \u00fcber Gott sprechen<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>Wenn wir \u00fcber Gott reden, wie gut er ist und was er uns getan hat, ist das auch eine Ehrerbietung f\u00fcr Gott<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Menschen besuchen, die leiden<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>Gott sagt, das ist der wahre Gottesdienst: Witwen und Waisen in ihrer Not zu besuchen. Wenn wir Menschen besuchen, die ein wirklich hartes Leben haben, und ihnen die gute Nachricht \u00fcberbringen, dass Gott sich auch in schwierigen Zeiten um sie k\u00fcmmert, Zeit mit ihnen teilt und zu ihnen beitr\u00e4gt, dann loben wir auch Gott.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>F\u00fcr Gott singen und beten<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><br>Der Hauptgrund, warum ich diese Lieder geschrieben habe, ist, Gott die Ehre zu geben. Durch Musik direkt mit Gott sprechen, wenn ich ein Anbetungslied schreibe, oder mit anderen positiv \u00fcber Gott sprechen, wenn ich durch meine Musik bezeuge, dass Gott existiert.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","_de_post_name":"","_de_post_excerpt":"","_de_post_title":"Jesus has changed my life - DE","_nb_post_content":"<!-- wp:pullquote -->\n<figure class=\"wp-block-pullquote\"><blockquote><p>Jesus forandret livet mitt<br>Jesus forandret livet mitt<br>Jesus forandret livet mitt<br>Jeg gir ham \u00e6re<br>Jesus forandret livet mitt<br>Jesus forandret livet mitt<br>Jesus forandret livet mitt<br>Jeg priser ham<br>Jeg var en gang en synder<br>men jeg var ikke klar over det<br>Jeg ville bare ha det g\u00f8y<br>\u00e5 vandre rundt i husene om natten<br>Men over til kveldens moro<br>fulgte tomheten<br>Og jeg f\u00f8lte meg sulten p\u00e5 mer liv<br>Jeg var en gang en synder<br>men jeg var ikke klar over det<br>At jeg s\u00e5ret folk<br>som var rundt meg<br>\u00c5 bli skadet selv<br>gj\u00f8r meg urettferdig<br>til den dagen<br>da Jesus reddet meg<br>Jeg var en gang en synder<br>og n\u00e5 er jeg klar over det<br>at Jesus er den ene<br>som gir meg glede og liv<br>Og hans velsignelser hver dag<br>Gi helbredelse til alle som lider<br>Hans \u00e5nd og hans kj\u00e6rlighet<br>tr\u00f8st meg<\/p><\/blockquote><\/figure>\n<!-- \/wp:pullquote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hvordan har Jesu n\u00e6rv\u00e6r i livet ditt gjort deg mer takknemlig for velsignelsene du har mottatt?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Det f\u00f8rste vi m\u00e5 gj\u00f8re er \u00e5 innse at vi har en velsignelse. Mange sier: Jeg fikk eindomene mine og det jeg har gjennom hardt arbeid. Da sier jeg: OK, men hvem ga deg styrke til \u00e5 jobbe? Hvorfor er du frisk og kan g\u00e5 p\u00e5 jobb hver dag?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>23&nbsp;Den som ofrer takksigelse, priser meg, og der er en vei hvor jeg kan vise ham Guds frelse.\u00bb<br>Salme 50<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>For 10 \u00e5r siden var jeg veldig syk og d\u00f8de nesten, men jeg v\u00e5knet fra koma uten noen permanent hjerneskade, noe som var et mirakel. Jeg er selvf\u00f8lgelig takknemlig ikke bare for velsignelsene, men ogs\u00e5 for at Gud gj\u00f8r meg i stand til \u00e5 leve og st\u00e5 opp hver morgen uten hjelp fra andre.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>En salme av David. Herren er min hyrde, jeg mangler ikke.<br>2&nbsp;Han mater meg p\u00e5 en gr\u00f8nn eng og f\u00f8rer meg til ferskvann.<br>3&nbsp;Han forfrisker sjelen min. Han leder meg p\u00e5 rett vei for hans navns skyld.<br>4 Og om jeg vandrer i m\u00f8rkets dal, frykter jeg ikke noe ondt; for du er med meg, din stav og stav tr\u00f8ster meg.<br>5 Du lager et bord foran meg i mine fiender. Du salver hodet mitt med olje og heller det ut for meg.<br>6 Godhet og barmhjertighet skal f\u00f8lge meg alle mitt livs dager, og jeg vil bo i Herrens hus til evig tid.<br>Salme 23<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">P\u00e5 hvilke m\u00e5ter har du personlig opplevd frelse gjennom Jesu kj\u00e6rlighet og tilgivelse?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>For \u00e5 oppleve frelse m\u00e5 man innse at vi trenger en Frelser.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>De fleste lever slik jeg beskriver i sangen min, l\u00f8per rundt, gj\u00f8r tingene sine, vil ha det g\u00f8y, men skj\u00f8nner ikke at de har synd i livet og burde omvende seg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>2 Herren ser ned fra himmelen p\u00e5 menneskenes barn for \u00e5 se om noen er vis og s\u00f8ker Gud.<br>3&nbsp;Men de har alle vendt seg bort, og alle er blitt fordervet; det er ingen som gj\u00f8r godt, ikke en gang.<br>Salme 14<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>V\u00e5re lyttere kan n\u00e5 si et \u00f8yeblikk. Jeg er et godt menneske og ikke en synder. Men det er dette som gj\u00f8r situasjonen s\u00e5 vanskelig: vi er ikke klar over n\u00e5r vi synder.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>9&nbsp;Hjertet er en sta og motl\u00f8s ting; hvem kan fatte det?<br>Jeremia<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Synd betyr ikke \u00e5 gj\u00f8re rett eller galt. Synd er noe vi har arvet fra v\u00e5re besteforeldre Adam og Eva, og vi kan ikke bli kvitt den med v\u00e5r egen vilje og styrke.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>12 Derfor, likesom synden kom inn i verden ved ett menneske, og d\u00f8den ved synden, slik kom d\u00f8den inn i alle mennesker, fordi de alle syndet.<br>Romer 5<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Hvis vi er \u00e6rlige, har vi alle l\u00f8yet p\u00e5 et tidspunkt i livet v\u00e5rt. Og selv \u00e5 fortelle en enkelt l\u00f8gn gj\u00f8r oss til syndere.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Gud kan ikke ha fellesskap med en synder fordi han er absolutt ren og hellig. S\u00e5 vi trenger at Jesus betaler syndens pris for oss og gj\u00f8r det mulig for oss \u00e5 ha fellesskap med den levende Gud og ikke komme til helvete, men til himmelen etter dette livet p\u00e5 jorden.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hvordan s\u00f8ker du \u00e5 avsl\u00f8re din tro og endringen Jesus har f\u00f8rt inn i livet ditt til verden rundt deg?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Jeg pr\u00f8ver ikke \u00e5 \u00e5penbare min tro til verden rundt meg fordi Bibelen l\u00e6rer at min tro ikke skal deles med alle. Hvis noen ikke vil ta imot Kristi evangelium, lar jeg ham eller henne g\u00e5.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Men jeg er alltid \u00e5pen for \u00e5 snakke om Jesus med menneskene rundt meg, og jeg ser etter en mulighet til \u00e5 fortelle folk om Jesus Kristus og arbeidet han gjorde for dem p\u00e5 Golgata.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Men dette er ofte uventet. Jeg er bare villig til \u00e5 si, og Gud \u00e5pner en d\u00f8r til personens hjerte for \u00e5 lytte og sp\u00f8rre mer om evangeliet<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>16 For jeg skammer meg ikke over evangeliet; for det er Guds kraft som frelser alle som tror, \u200b\u200bj\u00f8dene f\u00f8rst og ogs\u00e5 grekerne.<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hvordan forestiller du deg begrepet paradis og livet i Jesu n\u00e6rv\u00e6r? Hvordan former dette h\u00e5pet ditt syn p\u00e5 livet?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Begrepet paradis gir livet mitt mening . Jeg er ikke redd for hva som skjer n\u00e5r jeg d\u00f8r og m\u00e5 presentere meg selv i evigheten fordi Jesus har ordnet alt for meg. Han sa at han ville bygge et hus for oss i evig liv, og at jeg ville reise dit en dag.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>2 I min Fars hus er det mange herskapshus. Hvis det ikke var slik, ville jeg da ha sagt til deg: Jeg skal gj\u00f8re i stand stedet for deg?<br>3 Og n\u00e5r jeg g\u00e5r for \u00e5 gj\u00f8re i stand stedet for dere, vil jeg komme igjen og ta dere til meg, for at ogs\u00e5 dere kan v\u00e6re der jeg er.<br>4&nbsp;Og hvor jeg g\u00e5r, vet du veien dit.<br>Johannes 14<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Det som er interessant er at Bibelen ikke snakker s\u00e5 mye om d\u00f8den, selv om den dagen kommer. Hun snakker mer om evig liv og sier at de som lever med Gud vil v\u00e6re unge selv n\u00e5r de allerede er gamle.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Det er derfor jeg pr\u00f8ver \u00e5 v\u00e6re som Enok i 1. Mosebok. Han gikk bare med Gud og en dag tok Gud ham bort.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>24 Og Enok vandret med Gud og ble ikke sett lenger, for Gud hadde tatt ham opp.<br>F\u00f8rste Mosebok <\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Jeg lever hverdagen min med oppmerksomhet p\u00e5 om Gud vil meg noe og vite at han alltid er med meg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Men Bibelen l\u00e6rer oss et annet sted vi vil g\u00e5 hvis vi ikke tar imot Jesus som v\u00e5r frelser: det er ildsj\u00f8en, helvete. Det er tomt for \u00f8yeblikket, men n\u00e5r Jesus kommer tilbake som dommer, vil alle som ikke er frelst bli d\u00f8mt p\u00e5 den hvite tronen og deretter g\u00e5 til helvete. Derfor st\u00e5r det skrevet p\u00e5 hebraisk: Mennesket skal d\u00f8 \u00e9n gang, og deretter kommer dommen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>27 Og som det er gitt menneskene \u00e9n gang \u00e5 d\u00f8, og deretter dommen:<br>Hebreerne 9<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>5&nbsp;Men du, med ditt forherdede og uangrende hjerte, samler vrede for deg selv for vredens dag og \u00e5penbaringen av Guds rettferdige dom;<br>6&nbsp;Hvem skal gi enhver etter hans gjerninger:<br>7&nbsp;Evig liv for dem som med all t\u00e5lmodighet og gode gjerninger s\u00f8ker \u00e6re og \u00e6re og uforgjengelig liv;<br>8&nbsp;Men vrede og vrede hos dem som er stridbare og ikke adlyder sannheten, men adlyder urettferdighet;<br>9 Trengsel og n\u00f8d over alle sjeler til mennesker som gj\u00f8r det onde, j\u00f8dene f\u00f8rst og ogs\u00e5 grekerne;<br>10 Men \u00e6re og \u00e6re og fred til alle dem som gj\u00f8r godt, f\u00f8rst til j\u00f8dene og ogs\u00e5 til grekerne.<br>11 For det er ingen respekt for mennesker for Gud.<br>Romerne 2<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>11 Og jeg s\u00e5 en stor hvit trone, og ham som satt p\u00e5 den; Jorden og himmelen flyktet fra hans n\u00e6rhet, og det ble ikke funnet noe sted for dem.<br>12 Og jeg s\u00e5 de d\u00f8de, b\u00e5de store og sm\u00e5, st\u00e5 foran tronen, og b\u00f8ker ble \u00e5pnet. Og en annen bok ble \u00e5pnet, som er livets bok. Og de d\u00f8de ble d\u00f8mt etter det som var skrevet i b\u00f8kene, etter deres gjerninger.<br>13&nbsp;Og havet gav opp de d\u00f8de som var i det, og d\u00f8den og helvete ga opp de d\u00f8de som var i det; og de ble d\u00f8mt hver etter hans gjerninger.<br>14 Og d\u00f8den og helvete ble kastet i ildsj\u00f8en. Dette er den andre d\u00f8den: Ildsj\u00f8en.<br>15 Og hvis noen ikke ble funnet skrevet i livets bok, ble han kastet i ildsj\u00f8en.<br>\u00c5penbaring 20<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hvordan opprettholder du et fredelig hjerte midt i verdens utfordringer og realiteter og finner tr\u00f8st i Jesu l\u00e6resetninger?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Troen p\u00e5 Jesus er et forhold. N\u00e5r jeg har et forhold til Jesus, er jeg ikke avhengig av hva andre mennesker tror eller tenker om meg. S\u00e5 n\u00e5r en konflikt oppst\u00e5r, kan jeg forbli rolig og be i mitt hjerte til Jesus om \u00e5 hjelpe meg \u00e5 komme meg ut av denne ubehagelige situasjonen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Og jeg husker Paulus skrev at vi ikke kjemper mot blod og kj\u00f8tt, men mot m\u00f8rkets makter. S\u00e5 n\u00e5r det er et problem, tilgir jeg umiddelbart og lar Gud l\u00f8se utfordringen for meg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>11&nbsp;Ta p\u00e5 deg Guds rustning, s\u00e5 du kan st\u00e5 imot djevelens gjerninger.<br>12 For v\u00e5r kamp er ikke mot kj\u00f8tt og blod, men mot makter og makter, mot verdens herrer, som hersker over dette m\u00f8rket, mot onde \u00e5nder under himmelen.<br>Ef 6<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hvilke skritt tar du for aktivt \u00e5 leve ut din tro og dele Jesu kj\u00e6rlighet med andre, spesielt i en verden som kanskje ikke alltid er mottakelig?<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:heading {\"level\":5} -->\n<h5 class=\"wp-block-heading\">(S\u00f8ster, vennligst forklar dette sp\u00f8rsm\u00e5let i en detaljert beskrivelse for lytterne v\u00e5re slik at de vet hvordan de skal \u00f8ve spesifikt i deres virkelige liv.)<\/h5>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>For \u00e5 aktivt leve min tro, synger og ber jeg for Jesus og leser Bibelen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hvis vi vil kjenne Gud, hvem han er, hans karakter, hans vilje og ham som person, m\u00e5 vi lese Bibelen fordi det er Guds kj\u00e6rlighetsbrev og Guds h\u00e5ndbok om livet for oss.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jeg har allerede lest Bibelen fra begynnelse til slutt tre ganger.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Men n\u00e5r vi leser Bibelen, er det mange ting vi ikke vil forst\u00e5 uten hjelp. S\u00e5 vi m\u00e5 be til Gud om \u00e5 sende oss sin Hellige \u00c5nd og hjelpe oss \u00e5 forst\u00e5 hva Gud \u00f8nsker \u00e5 fortelle oss gjennom sitt Ord.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Uten Den Hellige \u00c5nd er Bibelen bare teologi, som alle andre b\u00f8ker om religion. Men med Den Hellige \u00c5nd blir det til en skatt. Hver gang du leser det opplever du nye ting og ordet er alltid friskt.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>19 Eller vet du ikke at ditt legeme er et tempel for Den Hellige \u00c5nd som er i deg, som du har fra Gud, og at du ikke er din egen?<br>1 Korinterbrev 6<\/p>\n<!-- \/wp:paragraph --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>For for \u00e5 be er det ikke n\u00f8dvendig \u00e5 g\u00e5 til et spesielt sted. Jeg ber p\u00e5 rommet mitt eller hvor jeg enn er fordi Gud er alltid med meg.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>N\u00e5r problemet med synd er l\u00f8st, vil jeg alltid ha tilgang til Guds trone og kan komme hvor som helst, n\u00e5r som helst, han vil lytte og svare meg. Noen ganger er svaret nei, men han vil h\u00f8re alle mine b\u00f8nner.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Det er ogs\u00e5 i Guds hender \u00e5 dele min tro med andre og \u00e5 bidra til andre. Han sier at vi skal gj\u00f8re de gode gjerningene som han har forberedt for oss mange ganger. S\u00e5 vi m\u00e5 bare ha viljen og Gud vil vise oss om vi skal invitere noen p\u00e5 lunsj eller for eksempel st\u00f8tte en misjon\u00e6r.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Hvordan kan du \u00e6re  Gud? (For eksempel 1.2.3\u2026)<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Det er mange m\u00e5ter vi kan gi \u00e6re til Gud:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Respekter og hold hans bud.<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Jesus sa: Den som elsker meg, skal holde mine bud. Selvf\u00f8lgelig er vi frelst ved tro og n\u00e5de. Men Jesus l\u00e6rte oss \u00e5 leve etter hans vilje, og hvis vi vil gi Gud \u00e6re, respekterer vi ham<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Snakk med andre mennesker om Gud<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>N\u00e5r vi snakker om Gud, hvor god han er og hva han har gjort for oss, er det ogs\u00e5 en \u00e6re for Gud<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Bes\u00f8k folk som lider<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Gud sier at dette er sann tilbedelse: \u00e5 bes\u00f8ke enker og foreldrel\u00f8se barn n\u00e5r de trenger det. N\u00e5r vi bes\u00f8ker mennesker som har virkelig vanskelige liv og forteller dem den gode nyheten om at Gud bryr seg om dem, deler tid med dem og bidrar til dem selv i vanskelige tider, priser vi ogs\u00e5 Gud.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><em>Syng og be for Gud<\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hovedgrunnen til at jeg skrev disse sangene er for \u00e5 gi \u00e6re til Gud. \u00c5 snakke direkte til Gud gjennom musikk n\u00e5r jeg skriver en lovsang, eller snakke positivt om Gud til andre n\u00e5r jeg vitner om at Gud eksisterer gjennom musikken min<\/p>\n<!-- \/wp:paragraph -->","_nb_post_name":"","_nb_post_excerpt":"","_nb_post_title":"Jesus has changed my life - norsk","edit_language":"zh","episode_type":"audio","audio_file":"https:\/\/loveforasia.org\/wp-content\/uploads\/2023\/12\/Podcast-Jesus-has-changed-my-life.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"25:43","filesize":"17.72M","filesize_raw":"18583322","date_recorded":"2023-07-29 23:44:37","explicit":"","block":"","iawp_total_views":13,"footnotes":""},"categories":[25],"tags":[],"series":[34],"class_list":["post-130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcaststrans","series-default-podcast"],"episode_featured_image":"https:\/\/loveforasia.org\/wp-content\/uploads\/2023\/07\/IMG-20230326-WA00011.jpg","episode_player_image":"https:\/\/loveforasia.org\/wp-content\/plugins\/seriously-simple-podcasting\/assets\/images\/no-album-art.png","download_link":"https:\/\/loveforasia.org\/podcast-download\/130\/jesus-has-changed-my-life","player_link":"https:\/\/loveforasia.org\/podcast-player\/130\/jesus-has-changed-my-life","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/loveforasia.org\/podcast-player\/130\/jesus-has-changed-my-life\">https:\/\/loveforasia.org\/podcast-player\/130\/jesus-has-changed-my-life<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"amazon":{"key":"amazon","url":"","label":"Amazon","class":"amazon","icon":"amazon.png"},"apple_podcasts":{"key":"apple_podcasts","url":"","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"}},"rssFeedUrl":"https:\/\/loveforasia.org\/zh\/feed\/podcast\/default-podcast","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"3MOSPQ8rQv\"><a href=\"https:\/\/loveforasia.org\/zh\/jesus-has-changed-my-life\/\">Jesus has changed my life - CN <\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/loveforasia.org\/zh\/jesus-has-changed-my-life\/embed\/#?secret=3MOSPQ8rQv\" width=\"500\" height=\"350\" title=\"\u300a Jesus has changed my life - CN  \u300b\u2014Love for Asia\" data-secret=\"3MOSPQ8rQv\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/loveforasia.org\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":20,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"predecessor-version":[{"id":1201,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/posts\/130\/revisions\/1201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/media\/137"}],"wp:attachment":[{"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/tags?post=130"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/loveforasia.org\/zh\/wp-json\/wp\/v2\/series?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}